{"id":1448,"date":"2024-05-21T16:49:21","date_gmt":"2024-05-21T19:49:21","guid":{"rendered":"https:\/\/radioplanetasaudade.com.br\/?p=1448"},"modified":"2024-05-21T16:49:22","modified_gmt":"2024-05-21T19:49:22","slug":"confira-as-ultimas-10-que-rolaram-na-programacao-8","status":"publish","type":"post","link":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/05\/21\/confira-as-ultimas-10-que-rolaram-na-programacao-8\/","title":{"rendered":"Confira as \u00faltimas 10 que rolaram na programa\u00e7\u00e3o"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Visite o site: conhe\u00e7a mais sobre a R\u00e1dio Planeta Saudade<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"650\" height=\"646\" src=\"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2024\/05\/ATULAIZADA-TOP-10-9.jpg\" alt=\"\" class=\"wp-image-1449\" srcset=\"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2024\/05\/ATULAIZADA-TOP-10-9.jpg 650w, https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2024\/05\/ATULAIZADA-TOP-10-9-300x298.jpg 300w, https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2024\/05\/ATULAIZADA-TOP-10-9-150x150.jpg 150w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><img decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t7a\/1\/16\/31_20e3.png\" alt=\"1\ufe0f\u20e3\"><img decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t33\/1\/16\/2705.png\" alt=\"\u2705\"><strong>Patrick Hernandez \/Born to Be Alive<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t99\/1\/16\/32_20e3.png\" alt=\"2\ufe0f\u20e3\"><img decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t33\/1\/16\/2705.png\" alt=\"\u2705\"><strong>The Farm \/All Together Now<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/tb8\/1\/16\/33_20e3.png\" alt=\"3\ufe0f\u20e3\"><img decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t33\/1\/16\/2705.png\" alt=\"\u2705\"><strong>Paul Young \/Everytime You Go Away<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/td7\/1\/16\/34_20e3.png\" alt=\"4\ufe0f\u20e3\"><img decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t33\/1\/16\/2705.png\" alt=\"\u2705\"><strong>Kid Abelha \/Eu Tive Um Sonho<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/tf6\/1\/16\/35_20e3.png\" alt=\"5\ufe0f\u20e3\"><img decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t33\/1\/16\/2705.png\" alt=\"\u2705\"><strong>Ne-Yo \/Mad<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t15\/1\/16\/36_20e3.png\" alt=\"6\ufe0f\u20e3\"><img decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t33\/1\/16\/2705.png\" alt=\"\u2705\"><strong>Rihanna \/Unfaithful<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t34\/1\/16\/37_20e3.png\" alt=\"7\ufe0f\u20e3\"><img decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t33\/1\/16\/2705.png\" alt=\"\u2705\"><strong>Jota Quest \/Amor Maior<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t53\/1\/16\/38_20e3.png\" alt=\"8\ufe0f\u20e3\"><img decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t33\/1\/16\/2705.png\" alt=\"\u2705\"><strong>Joe Cocker &amp; Jennifer Warnes \/Up Where We Belong<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t72\/1\/16\/39_20e3.png\" alt=\"9\ufe0f\u20e3\"><img decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t33\/1\/16\/2705.png\" alt=\"\u2705\"><strong>Sandra de S\u00e1 \/Sozinha<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t62\/1\/16\/1f51f.png\" alt=\"\ud83d\udd1f\"><img decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t33\/1\/16\/2705.png\" alt=\"\u2705\"><strong>A-ha \/There\u00b4s Never A forever Thing<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>PLANETA SAUDADE &#8220;AQUI \u00c9 EMO\u00c7\u00c3O&#8221;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Baixe nosso APP pela Google Play<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sites dispon\u00edveis tamb\u00e9m (Pelo Google)<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Visite o site: conhe\u00e7a mais sobre a R\u00e1dio Planeta Saudade Patrick Hernandez \/Born to Be&#8230;<\/p>\n","protected":false},"author":1,"featured_media":1449,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[93],"tags":[119,118,120,121,117,238,116,99],"class_list":["post-1448","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cantores","tag-anos-70","tag-anos-80","tag-anos-90","tag-baixe-nosso-app","tag-flashaback","tag-joe-cocker","tag-radio","tag-radio-planeta-saudade"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Confira as \u00faltimas 10 que rolaram na programa\u00e7\u00e3o - R\u00c1DIO PLANETA SAUDADE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/05\/21\/confira-as-ultimas-10-que-rolaram-na-programacao-8\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Confira as \u00faltimas 10 que rolaram na programa\u00e7\u00e3o - R\u00c1DIO PLANETA SAUDADE\" \/>\n<meta property=\"og:description\" content=\"Visite o site: conhe\u00e7a mais sobre a R\u00e1dio Planeta Saudade Patrick Hernandez \/Born to Be...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/05\/21\/confira-as-ultimas-10-que-rolaram-na-programacao-8\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00c1DIO PLANETA SAUDADE\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-21T19:49:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-21T19:49:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2024\/05\/ATULAIZADA-TOP-10-9.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"650\" \/>\n\t<meta property=\"og:image:height\" content=\"646\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Planeta Saudade\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Planeta Saudade\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2024\\\/05\\\/21\\\/confira-as-ultimas-10-que-rolaram-na-programacao-8\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2024\\\/05\\\/21\\\/confira-as-ultimas-10-que-rolaram-na-programacao-8\\\/\"},\"author\":{\"name\":\"Planeta Saudade\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#\\\/schema\\\/person\\\/1a6f6fc0d987819324e7ed417a1a6581\"},\"headline\":\"Confira as \u00faltimas 10 que rolaram na programa\u00e7\u00e3o\",\"datePublished\":\"2024-05-21T19:49:21+00:00\",\"dateModified\":\"2024-05-21T19:49:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2024\\\/05\\\/21\\\/confira-as-ultimas-10-que-rolaram-na-programacao-8\\\/\"},\"wordCount\":89,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2024\\\/05\\\/21\\\/confira-as-ultimas-10-que-rolaram-na-programacao-8\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/ATULAIZADA-TOP-10-9.jpg\",\"keywords\":[\"Anos 70\",\"Anos 80\",\"Anos 90\",\"Baixe nosso App\",\"Flashaback\",\"Joe Cocker\",\"R\u00e1dio\",\"R\u00e1dio Planeta Saudade\"],\"articleSection\":[\"CANTORES\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2024\\\/05\\\/21\\\/confira-as-ultimas-10-que-rolaram-na-programacao-8\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2024\\\/05\\\/21\\\/confira-as-ultimas-10-que-rolaram-na-programacao-8\\\/\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2024\\\/05\\\/21\\\/confira-as-ultimas-10-que-rolaram-na-programacao-8\\\/\",\"name\":\"Confira as \u00faltimas 10 que rolaram na programa\u00e7\u00e3o - R\u00c1DIO PLANETA SAUDADE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2024\\\/05\\\/21\\\/confira-as-ultimas-10-que-rolaram-na-programacao-8\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2024\\\/05\\\/21\\\/confira-as-ultimas-10-que-rolaram-na-programacao-8\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/ATULAIZADA-TOP-10-9.jpg\",\"datePublished\":\"2024-05-21T19:49:21+00:00\",\"dateModified\":\"2024-05-21T19:49:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2024\\\/05\\\/21\\\/confira-as-ultimas-10-que-rolaram-na-programacao-8\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2024\\\/05\\\/21\\\/confira-as-ultimas-10-que-rolaram-na-programacao-8\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2024\\\/05\\\/21\\\/confira-as-ultimas-10-que-rolaram-na-programacao-8\\\/#primaryimage\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/ATULAIZADA-TOP-10-9.jpg\",\"contentUrl\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/ATULAIZADA-TOP-10-9.jpg\",\"width\":650,\"height\":646},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2024\\\/05\\\/21\\\/confira-as-ultimas-10-que-rolaram-na-programacao-8\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Confira as \u00faltimas 10 que rolaram na programa\u00e7\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#website\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/\",\"name\":\"R\u00e1dio Planeta Saudade\",\"description\":\"Relembrando grandes sucessos musicais e informando sobre os maiores artistas do mundo ou\u00e7a no seu celular.\",\"publisher\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#organization\",\"name\":\"R\u00e1dio Planeta Saudade\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/capture-20230607-202153.png\",\"contentUrl\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/capture-20230607-202153.png\",\"width\":1350,\"height\":358,\"caption\":\"R\u00e1dio Planeta Saudade\"},\"image\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#\\\/schema\\\/person\\\/1a6f6fc0d987819324e7ed417a1a6581\",\"name\":\"Planeta Saudade\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g\",\"caption\":\"Planeta Saudade\"},\"sameAs\":[\"https:\\\/\\\/radioplanetasaudade.com.br\"],\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/author\\\/wendelsantos4567\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Confira as \u00faltimas 10 que rolaram na programa\u00e7\u00e3o - R\u00c1DIO PLANETA SAUDADE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/05\/21\/confira-as-ultimas-10-que-rolaram-na-programacao-8\/","og_locale":"pt_BR","og_type":"article","og_title":"Confira as \u00faltimas 10 que rolaram na programa\u00e7\u00e3o - R\u00c1DIO PLANETA SAUDADE","og_description":"Visite o site: conhe\u00e7a mais sobre a R\u00e1dio Planeta Saudade Patrick Hernandez \/Born to Be...","og_url":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/05\/21\/confira-as-ultimas-10-que-rolaram-na-programacao-8\/","og_site_name":"R\u00c1DIO PLANETA SAUDADE","article_published_time":"2024-05-21T19:49:21+00:00","article_modified_time":"2024-05-21T19:49:22+00:00","og_image":[{"width":650,"height":646,"url":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2024\/05\/ATULAIZADA-TOP-10-9.jpg","type":"image\/jpeg"}],"author":"Planeta Saudade","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Planeta Saudade","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/05\/21\/confira-as-ultimas-10-que-rolaram-na-programacao-8\/#article","isPartOf":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/05\/21\/confira-as-ultimas-10-que-rolaram-na-programacao-8\/"},"author":{"name":"Planeta Saudade","@id":"https:\/\/radioplanetasaudade.com.br\/#\/schema\/person\/1a6f6fc0d987819324e7ed417a1a6581"},"headline":"Confira as \u00faltimas 10 que rolaram na programa\u00e7\u00e3o","datePublished":"2024-05-21T19:49:21+00:00","dateModified":"2024-05-21T19:49:22+00:00","mainEntityOfPage":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/05\/21\/confira-as-ultimas-10-que-rolaram-na-programacao-8\/"},"wordCount":89,"commentCount":0,"publisher":{"@id":"https:\/\/radioplanetasaudade.com.br\/#organization"},"image":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/05\/21\/confira-as-ultimas-10-que-rolaram-na-programacao-8\/#primaryimage"},"thumbnailUrl":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2024\/05\/ATULAIZADA-TOP-10-9.jpg","keywords":["Anos 70","Anos 80","Anos 90","Baixe nosso App","Flashaback","Joe Cocker","R\u00e1dio","R\u00e1dio Planeta Saudade"],"articleSection":["CANTORES"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/05\/21\/confira-as-ultimas-10-que-rolaram-na-programacao-8\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/05\/21\/confira-as-ultimas-10-que-rolaram-na-programacao-8\/","url":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/05\/21\/confira-as-ultimas-10-que-rolaram-na-programacao-8\/","name":"Confira as \u00faltimas 10 que rolaram na programa\u00e7\u00e3o - R\u00c1DIO PLANETA SAUDADE","isPartOf":{"@id":"https:\/\/radioplanetasaudade.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/05\/21\/confira-as-ultimas-10-que-rolaram-na-programacao-8\/#primaryimage"},"image":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/05\/21\/confira-as-ultimas-10-que-rolaram-na-programacao-8\/#primaryimage"},"thumbnailUrl":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2024\/05\/ATULAIZADA-TOP-10-9.jpg","datePublished":"2024-05-21T19:49:21+00:00","dateModified":"2024-05-21T19:49:22+00:00","breadcrumb":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/05\/21\/confira-as-ultimas-10-que-rolaram-na-programacao-8\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/05\/21\/confira-as-ultimas-10-que-rolaram-na-programacao-8\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/05\/21\/confira-as-ultimas-10-que-rolaram-na-programacao-8\/#primaryimage","url":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2024\/05\/ATULAIZADA-TOP-10-9.jpg","contentUrl":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2024\/05\/ATULAIZADA-TOP-10-9.jpg","width":650,"height":646},{"@type":"BreadcrumbList","@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/05\/21\/confira-as-ultimas-10-que-rolaram-na-programacao-8\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/radioplanetasaudade.com.br\/"},{"@type":"ListItem","position":2,"name":"Confira as \u00faltimas 10 que rolaram na programa\u00e7\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/radioplanetasaudade.com.br\/#website","url":"https:\/\/radioplanetasaudade.com.br\/","name":"R\u00e1dio Planeta Saudade","description":"Relembrando grandes sucessos musicais e informando sobre os maiores artistas do mundo ou\u00e7a no seu celular.","publisher":{"@id":"https:\/\/radioplanetasaudade.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radioplanetasaudade.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/radioplanetasaudade.com.br\/#organization","name":"R\u00e1dio Planeta Saudade","url":"https:\/\/radioplanetasaudade.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radioplanetasaudade.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2023\/10\/capture-20230607-202153.png","contentUrl":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2023\/10\/capture-20230607-202153.png","width":1350,"height":358,"caption":"R\u00e1dio Planeta Saudade"},"image":{"@id":"https:\/\/radioplanetasaudade.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/radioplanetasaudade.com.br\/#\/schema\/person\/1a6f6fc0d987819324e7ed417a1a6581","name":"Planeta Saudade","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g","caption":"Planeta Saudade"},"sameAs":["https:\/\/radioplanetasaudade.com.br"],"url":"https:\/\/radioplanetasaudade.com.br\/index.php\/author\/wendelsantos4567\/"}]}},"_links":{"self":[{"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1448","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=1448"}],"version-history":[{"count":1,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1448\/revisions"}],"predecessor-version":[{"id":1450,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1448\/revisions\/1450"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/media\/1449"}],"wp:attachment":[{"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=1448"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=1448"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=1448"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}