{"id":1920,"date":"2024-07-10T09:27:55","date_gmt":"2024-07-10T12:27:55","guid":{"rendered":"https:\/\/radioplanetasaudade.com.br\/?p=1920"},"modified":"2024-07-10T09:27:57","modified_gmt":"2024-07-10T12:27:57","slug":"robby-rosa-hello","status":"publish","type":"post","link":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/07\/10\/robby-rosa-hello\/","title":{"rendered":"Robby Rosa \/Hello"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Cante com a R\u00e1dio Planeta Saudade <\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"650\" height=\"650\" src=\"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2024\/07\/ROBBY-ROSA.jpg\" alt=\"\" class=\"wp-image-1921\" srcset=\"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2024\/07\/ROBBY-ROSA.jpg 650w, https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2024\/07\/ROBBY-ROSA-300x300.jpg 300w, https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2024\/07\/ROBBY-ROSA-150x150.jpg 150w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Estou morrendo de saudade, tanto tempo sem te ver<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como <a><\/a>\u00e9 grande esta cidade eu n\u00e3o sei onde est\u00e1 voc\u00ea<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por que n\u00e3o me telefona, o que foi que eu te fiz?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pra sumir por tanto tempo, me deixando triste assim, quero ser feliz<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Liga ao menos pra saber como eu estou<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Liga pra mim acho que mere\u00e7o<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Meu amor d\u00b4aquele amor que j\u00e1 foi teu<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Liga pra mim ao menos uma vez<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hello hello, liga outra vez pra mim dizer que vai voltar pra mim<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hello, hello liga outra vez pra mim dizer que n\u00e3o chegou ao fim<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por que n\u00e3o me telefona, o que foi que eu te fiz?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pra sumir por tanto tempo, me deixando triste assim, quero ser feliz<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Liga ao menos pra saber como eu estou, Liga pra mim acho que mere\u00e7o<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Meu amor d&#8217;aquele amor que j\u00e1 foi teu, Liga pra mim ao menos uma vez<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hello hello, liga outra vez pra mim dizer que vai voltar pra mim<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.facebook.com\/photo\/?fbid=122160475958188428&amp;set=a.122094274238188428&amp;__cft__[0]=AZXebEBD6Xt4KHg7LIMI9X_gyAIH9_NaaWiS5qcgHyjbgzvN3-1JWgNVXQVd3n8P1XAF05Fx-JeVDux53BKiK1YvE5FHdkwegjJD2OwNem7cNgRhJKRSIIay0lTmvvkKmunzPsiD2Y2maetSCB6uXzAnMoEeLRyz2So8yMTy1aizxF_gQHz6bYziWJL81NudaHrA4gRRXusBdBfbM7Yspkzj&amp;__tn__=EH-R\"><\/a><\/p>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/www.facebook.com\/photo\/?fbid=122160475958188428&amp;set=a.122094274238188428&amp;__cft__[0]=AZXebEBD6Xt4KHg7LIMI9X_gyAIH9_NaaWiS5qcgHyjbgzvN3-1JWgNVXQVd3n8P1XAF05Fx-JeVDux53BKiK1YvE5FHdkwegjJD2OwNem7cNgRhJKRSIIay0lTmvvkKmunzPsiD2Y2maetSCB6uXzAnMoEeLRyz2So8yMTy1aizxF_gQHz6bYziWJL81NudaHrA4gRRXusBdBfbM7Yspkzj&amp;__tn__=EH-R\"><img decoding=\"async\" src=\"https:\/\/scontent.fvix7-1.fna.fbcdn.net\/v\/t39.30808-6\/450575577_122160475964188428_4988216720145619783_n.jpg?stp=dst-jpg_p526x296&amp;_nc_cat=107&amp;ccb=1-7&amp;_nc_sid=127cfc&amp;_nc_ohc=OvTS_qzFKSwQ7kNvgFNfR8E&amp;_nc_ht=scontent.fvix7-1.fna&amp;oh=00_AYApaMVH1q1vYp-SoFzV3ZZJINAPETYT3UdKT0K0VgebvA&amp;oe=66946275\" alt=\"Pode ser uma imagem de 1 pessoa, telefone e texto\"\/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Ver insights e an\u00fancios<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.facebook.com\/ad_center\/create\/boostpost\/?entry_point=www_profile_plus_timeline&amp;page_id=204619156067889&amp;target_id=122160476654188428&amp;__cft__[0]=AZXebEBD6Xt4KHg7LIMI9X_gyAIH9_NaaWiS5qcgHyjbgzvN3-1JWgNVXQVd3n8P1XAF05Fx-JeVDux53BKiK1YvE5FHdkwegjJD2OwNem7cNgRhJKRSIIay0lTmvvkKmunzPsiD2Y2maetSCB6uXzAnMoEeLRyz2So8yMTy1aizxF_gQHz6bYziWJL81NudaHrA4gRRXusBdBfbM7Yspkzj&amp;__tn__=*W-R\"><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.facebook.com\/ad_center\/create\/boostpost\/?entry_point=www_profile_plus_timeline&amp;page_id=204619156067889&amp;target_id=122160476654188428&amp;__cft__[0]=AZXebEBD6Xt4KHg7LIMI9X_gyAIH9_NaaWiS5qcgHyjbgzvN3-1JWgNVXQVd3n8P1XAF05Fx-JeVDux53BKiK1YvE5FHdkwegjJD2OwNem7cNgRhJKRSIIay0lTmvvkKmunzPsiD2Y2maetSCB6uXzAnMoEeLRyz2So8yMTy1aizxF_gQHz6bYziWJL81NudaHrA4gRRXusBdBfbM7Yspkzj&amp;__tn__=*W-R\">Turbinar publica\u00e7\u00e3o<\/a><\/p>\n\n\n\n\n\n<p class=\"wp-block-paragraph\">Todas as rea\u00e7\u00f5es:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1Wendel Santos<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cante com a R\u00e1dio Planeta Saudade Estou morrendo de saudade, tanto tempo sem te ver&#8230;<\/p>\n","protected":false},"author":1,"featured_media":1921,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[92],"tags":[119,118,120,121,528,117,97,194,116,99,275],"class_list":["post-1920","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-baixe-nosso-aplicativo","tag-anos-70","tag-anos-80","tag-anos-90","tag-baixe-nosso-app","tag-ex-menudo","tag-flashaback","tag-hello","tag-menudo","tag-radio","tag-radio-planeta-saudade","tag-robby-rosa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Robby Rosa \/Hello - R\u00c1DIO PLANETA SAUDADE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/07\/10\/robby-rosa-hello\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Robby Rosa \/Hello - R\u00c1DIO PLANETA SAUDADE\" \/>\n<meta property=\"og:description\" content=\"Cante com a R\u00e1dio Planeta Saudade Estou morrendo de saudade, tanto tempo sem te ver...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/07\/10\/robby-rosa-hello\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00c1DIO PLANETA SAUDADE\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-10T12:27:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-10T12:27:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2024\/07\/ROBBY-ROSA.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"650\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Planeta Saudade\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Planeta Saudade\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2024\\\/07\\\/10\\\/robby-rosa-hello\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2024\\\/07\\\/10\\\/robby-rosa-hello\\\/\"},\"author\":{\"name\":\"Planeta Saudade\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#\\\/schema\\\/person\\\/1a6f6fc0d987819324e7ed417a1a6581\"},\"headline\":\"Robby Rosa \\\/Hello\",\"datePublished\":\"2024-07-10T12:27:55+00:00\",\"dateModified\":\"2024-07-10T12:27:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2024\\\/07\\\/10\\\/robby-rosa-hello\\\/\"},\"wordCount\":196,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2024\\\/07\\\/10\\\/robby-rosa-hello\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/ROBBY-ROSA.jpg\",\"keywords\":[\"Anos 70\",\"Anos 80\",\"Anos 90\",\"Baixe nosso App\",\"Ex Menudo\",\"Flashaback\",\"Hello\",\"Menudo\",\"R\u00e1dio\",\"R\u00e1dio Planeta Saudade\",\"Robby Rosa\"],\"articleSection\":[\"BAIXE NOSSO APLICATIVO\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2024\\\/07\\\/10\\\/robby-rosa-hello\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2024\\\/07\\\/10\\\/robby-rosa-hello\\\/\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2024\\\/07\\\/10\\\/robby-rosa-hello\\\/\",\"name\":\"Robby Rosa \\\/Hello - R\u00c1DIO PLANETA SAUDADE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2024\\\/07\\\/10\\\/robby-rosa-hello\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2024\\\/07\\\/10\\\/robby-rosa-hello\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/ROBBY-ROSA.jpg\",\"datePublished\":\"2024-07-10T12:27:55+00:00\",\"dateModified\":\"2024-07-10T12:27:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2024\\\/07\\\/10\\\/robby-rosa-hello\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2024\\\/07\\\/10\\\/robby-rosa-hello\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2024\\\/07\\\/10\\\/robby-rosa-hello\\\/#primaryimage\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/ROBBY-ROSA.jpg\",\"contentUrl\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/ROBBY-ROSA.jpg\",\"width\":650,\"height\":650},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2024\\\/07\\\/10\\\/robby-rosa-hello\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Robby Rosa \\\/Hello\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#website\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/\",\"name\":\"R\u00e1dio Planeta Saudade\",\"description\":\"Relembrando grandes sucessos musicais e informando sobre os maiores artistas do mundo ou\u00e7a no seu celular.\",\"publisher\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#organization\",\"name\":\"R\u00e1dio Planeta Saudade\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/capture-20230607-202153.png\",\"contentUrl\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/capture-20230607-202153.png\",\"width\":1350,\"height\":358,\"caption\":\"R\u00e1dio Planeta Saudade\"},\"image\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#\\\/schema\\\/person\\\/1a6f6fc0d987819324e7ed417a1a6581\",\"name\":\"Planeta Saudade\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g\",\"caption\":\"Planeta Saudade\"},\"sameAs\":[\"https:\\\/\\\/radioplanetasaudade.com.br\"],\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/author\\\/wendelsantos4567\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Robby Rosa \/Hello - R\u00c1DIO PLANETA SAUDADE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/07\/10\/robby-rosa-hello\/","og_locale":"pt_BR","og_type":"article","og_title":"Robby Rosa \/Hello - R\u00c1DIO PLANETA SAUDADE","og_description":"Cante com a R\u00e1dio Planeta Saudade Estou morrendo de saudade, tanto tempo sem te ver...","og_url":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/07\/10\/robby-rosa-hello\/","og_site_name":"R\u00c1DIO PLANETA SAUDADE","article_published_time":"2024-07-10T12:27:55+00:00","article_modified_time":"2024-07-10T12:27:57+00:00","og_image":[{"width":650,"height":650,"url":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2024\/07\/ROBBY-ROSA.jpg","type":"image\/jpeg"}],"author":"Planeta Saudade","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Planeta Saudade","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/07\/10\/robby-rosa-hello\/#article","isPartOf":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/07\/10\/robby-rosa-hello\/"},"author":{"name":"Planeta Saudade","@id":"https:\/\/radioplanetasaudade.com.br\/#\/schema\/person\/1a6f6fc0d987819324e7ed417a1a6581"},"headline":"Robby Rosa \/Hello","datePublished":"2024-07-10T12:27:55+00:00","dateModified":"2024-07-10T12:27:57+00:00","mainEntityOfPage":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/07\/10\/robby-rosa-hello\/"},"wordCount":196,"commentCount":0,"publisher":{"@id":"https:\/\/radioplanetasaudade.com.br\/#organization"},"image":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/07\/10\/robby-rosa-hello\/#primaryimage"},"thumbnailUrl":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2024\/07\/ROBBY-ROSA.jpg","keywords":["Anos 70","Anos 80","Anos 90","Baixe nosso App","Ex Menudo","Flashaback","Hello","Menudo","R\u00e1dio","R\u00e1dio Planeta Saudade","Robby Rosa"],"articleSection":["BAIXE NOSSO APLICATIVO"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/07\/10\/robby-rosa-hello\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/07\/10\/robby-rosa-hello\/","url":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/07\/10\/robby-rosa-hello\/","name":"Robby Rosa \/Hello - R\u00c1DIO PLANETA SAUDADE","isPartOf":{"@id":"https:\/\/radioplanetasaudade.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/07\/10\/robby-rosa-hello\/#primaryimage"},"image":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/07\/10\/robby-rosa-hello\/#primaryimage"},"thumbnailUrl":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2024\/07\/ROBBY-ROSA.jpg","datePublished":"2024-07-10T12:27:55+00:00","dateModified":"2024-07-10T12:27:57+00:00","breadcrumb":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/07\/10\/robby-rosa-hello\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/07\/10\/robby-rosa-hello\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/07\/10\/robby-rosa-hello\/#primaryimage","url":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2024\/07\/ROBBY-ROSA.jpg","contentUrl":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2024\/07\/ROBBY-ROSA.jpg","width":650,"height":650},{"@type":"BreadcrumbList","@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/07\/10\/robby-rosa-hello\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/radioplanetasaudade.com.br\/"},{"@type":"ListItem","position":2,"name":"Robby Rosa \/Hello"}]},{"@type":"WebSite","@id":"https:\/\/radioplanetasaudade.com.br\/#website","url":"https:\/\/radioplanetasaudade.com.br\/","name":"R\u00e1dio Planeta Saudade","description":"Relembrando grandes sucessos musicais e informando sobre os maiores artistas do mundo ou\u00e7a no seu celular.","publisher":{"@id":"https:\/\/radioplanetasaudade.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radioplanetasaudade.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/radioplanetasaudade.com.br\/#organization","name":"R\u00e1dio Planeta Saudade","url":"https:\/\/radioplanetasaudade.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radioplanetasaudade.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2023\/10\/capture-20230607-202153.png","contentUrl":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2023\/10\/capture-20230607-202153.png","width":1350,"height":358,"caption":"R\u00e1dio Planeta Saudade"},"image":{"@id":"https:\/\/radioplanetasaudade.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/radioplanetasaudade.com.br\/#\/schema\/person\/1a6f6fc0d987819324e7ed417a1a6581","name":"Planeta Saudade","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g","caption":"Planeta Saudade"},"sameAs":["https:\/\/radioplanetasaudade.com.br"],"url":"https:\/\/radioplanetasaudade.com.br\/index.php\/author\/wendelsantos4567\/"}]}},"_links":{"self":[{"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1920","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=1920"}],"version-history":[{"count":1,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1920\/revisions"}],"predecessor-version":[{"id":1922,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1920\/revisions\/1922"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/media\/1921"}],"wp:attachment":[{"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=1920"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=1920"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=1920"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}