{"id":2627,"date":"2024-09-30T10:09:49","date_gmt":"2024-09-30T13:09:49","guid":{"rendered":"https:\/\/radioplanetasaudade.com.br\/?p=2627"},"modified":"2024-09-30T10:09:51","modified_gmt":"2024-09-30T13:09:51","slug":"radio-planeta-saudade-venha-conhecer-nossa-programacao","status":"publish","type":"post","link":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/09\/30\/radio-planeta-saudade-venha-conhecer-nossa-programacao\/","title":{"rendered":"R\u00e1dio Planeta Saudade, venha conhecer nossa programa\u00e7\u00e3o."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Se voc\u00ea ainda n\u00e3o conhece a R\u00e1dio Planeta Saudade, est\u00e1 na hora de descobrir a melhor programa\u00e7\u00e3o para quem ama m\u00fasica de verdade!<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"586\" height=\"574\" src=\"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2024\/09\/ACESSE-2024.jpg\" alt=\"\" class=\"wp-image-2628\" srcset=\"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2024\/09\/ACESSE-2024.jpg 586w, https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2024\/09\/ACESSE-2024-300x294.jpg 300w\" sizes=\"(max-width: 586px) 100vw, 586px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Oferecendo uma viagem no tempo com os grandes sucessos dos anos 70, 80, 90 e in\u00edcio dos anos 2000, sempre com uma sele\u00e7\u00e3o dos maiores nomes da m\u00fasica nacional e internacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a><\/a>Nossa programa\u00e7\u00e3o \u00e9 diversificada e pensada para todos os gostos e momentos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Logo no inicio da manh\u00e3, o programa Amn\u00e9sia come\u00e7a o dia com muita energia, tocando o melhor do pop, rock nacional, new wave e disco music.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No in\u00edcio da tarde, o programa &#8220;A Hora do Rango&#8221; embala seu almo\u00e7o com sucessos do rock nacional e pop.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">J\u00e1 no fim do dia, o Happy Hour \u00e9 o programa perfeito para relaxar, trazendo hits inesquec\u00edveis que marcaram gera\u00e7\u00f5es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para os apaixonados, o &#8221;Love Night&#8221; de segunda a quinta feira, e o &#8221;Clube do Amor&#8221; aos s\u00e1bados, s\u00e3o os companheiros ideais com suas sele\u00e7\u00f5es de m\u00fasicas rom\u00e2nticas nacionais e internacionais. Nos finais de semana, o Recorda\u00e7\u00f5es traz de volta mem\u00f3rias com as baladas e hits internacionais que fizeram hist\u00f3ria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seja qual for o momento do seu dia, temos um programa especial esperando por voc\u00ea!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sintonize na R\u00e1dio Planeta Saudade e curta os maiores cl\u00e1ssicos, sempre com muita emo\u00e7\u00e3o e qualidade.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Afinal, Planeta Saudade: &#8220;Aqui \u00e9 emo\u00e7\u00e3o!&#8221;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Venha fazer parte dessa viagem musical inesquec\u00edvel!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se voc\u00ea ainda n\u00e3o conhece a R\u00e1dio Planeta Saudade, est\u00e1 na hora de descobrir a&#8230;<\/p>\n","protected":false},"author":1,"featured_media":2628,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[92],"tags":[119,118,120,121,117,561,562,116,99],"class_list":["post-2627","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-baixe-nosso-aplicativo","tag-anos-70","tag-anos-80","tag-anos-90","tag-baixe-nosso-app","tag-flashaback","tag-ouvir","tag-ouvir-radio","tag-radio","tag-radio-planeta-saudade"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>R\u00e1dio Planeta Saudade, venha conhecer nossa programa\u00e7\u00e3o. - R\u00c1DIO PLANETA SAUDADE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/09\/30\/radio-planeta-saudade-venha-conhecer-nossa-programacao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00e1dio Planeta Saudade, venha conhecer nossa programa\u00e7\u00e3o. - R\u00c1DIO PLANETA SAUDADE\" \/>\n<meta property=\"og:description\" content=\"Se voc\u00ea ainda n\u00e3o conhece a R\u00e1dio Planeta Saudade, est\u00e1 na hora de descobrir a...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/09\/30\/radio-planeta-saudade-venha-conhecer-nossa-programacao\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00c1DIO PLANETA SAUDADE\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-30T13:09:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-30T13:09:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2024\/09\/ACESSE-2024.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"586\" \/>\n\t<meta property=\"og:image:height\" content=\"574\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Planeta Saudade\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Planeta Saudade\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2024\\\/09\\\/30\\\/radio-planeta-saudade-venha-conhecer-nossa-programacao\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2024\\\/09\\\/30\\\/radio-planeta-saudade-venha-conhecer-nossa-programacao\\\/\"},\"author\":{\"name\":\"Planeta Saudade\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#\\\/schema\\\/person\\\/1a6f6fc0d987819324e7ed417a1a6581\"},\"headline\":\"R\u00e1dio Planeta Saudade, venha conhecer nossa programa\u00e7\u00e3o.\",\"datePublished\":\"2024-09-30T13:09:49+00:00\",\"dateModified\":\"2024-09-30T13:09:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2024\\\/09\\\/30\\\/radio-planeta-saudade-venha-conhecer-nossa-programacao\\\/\"},\"wordCount\":255,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2024\\\/09\\\/30\\\/radio-planeta-saudade-venha-conhecer-nossa-programacao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/ACESSE-2024.jpg\",\"keywords\":[\"Anos 70\",\"Anos 80\",\"Anos 90\",\"Baixe nosso App\",\"Flashaback\",\"Ouvir\",\"Ouvir r\u00e1dio\",\"R\u00e1dio\",\"R\u00e1dio Planeta Saudade\"],\"articleSection\":[\"BAIXE NOSSO APLICATIVO\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2024\\\/09\\\/30\\\/radio-planeta-saudade-venha-conhecer-nossa-programacao\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2024\\\/09\\\/30\\\/radio-planeta-saudade-venha-conhecer-nossa-programacao\\\/\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2024\\\/09\\\/30\\\/radio-planeta-saudade-venha-conhecer-nossa-programacao\\\/\",\"name\":\"R\u00e1dio Planeta Saudade, venha conhecer nossa programa\u00e7\u00e3o. - R\u00c1DIO PLANETA SAUDADE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2024\\\/09\\\/30\\\/radio-planeta-saudade-venha-conhecer-nossa-programacao\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2024\\\/09\\\/30\\\/radio-planeta-saudade-venha-conhecer-nossa-programacao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/ACESSE-2024.jpg\",\"datePublished\":\"2024-09-30T13:09:49+00:00\",\"dateModified\":\"2024-09-30T13:09:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2024\\\/09\\\/30\\\/radio-planeta-saudade-venha-conhecer-nossa-programacao\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2024\\\/09\\\/30\\\/radio-planeta-saudade-venha-conhecer-nossa-programacao\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2024\\\/09\\\/30\\\/radio-planeta-saudade-venha-conhecer-nossa-programacao\\\/#primaryimage\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/ACESSE-2024.jpg\",\"contentUrl\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/ACESSE-2024.jpg\",\"width\":586,\"height\":574},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2024\\\/09\\\/30\\\/radio-planeta-saudade-venha-conhecer-nossa-programacao\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R\u00e1dio Planeta Saudade, venha conhecer nossa programa\u00e7\u00e3o.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#website\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/\",\"name\":\"R\u00e1dio Planeta Saudade\",\"description\":\"Relembrando grandes sucessos musicais e informando sobre os maiores artistas do mundo ou\u00e7a no seu celular.\",\"publisher\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#organization\",\"name\":\"R\u00e1dio Planeta Saudade\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/capture-20230607-202153.png\",\"contentUrl\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/capture-20230607-202153.png\",\"width\":1350,\"height\":358,\"caption\":\"R\u00e1dio Planeta Saudade\"},\"image\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#\\\/schema\\\/person\\\/1a6f6fc0d987819324e7ed417a1a6581\",\"name\":\"Planeta Saudade\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g\",\"caption\":\"Planeta Saudade\"},\"sameAs\":[\"https:\\\/\\\/radioplanetasaudade.com.br\"],\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/author\\\/wendelsantos4567\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"R\u00e1dio Planeta Saudade, venha conhecer nossa programa\u00e7\u00e3o. - R\u00c1DIO PLANETA SAUDADE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/09\/30\/radio-planeta-saudade-venha-conhecer-nossa-programacao\/","og_locale":"pt_BR","og_type":"article","og_title":"R\u00e1dio Planeta Saudade, venha conhecer nossa programa\u00e7\u00e3o. - R\u00c1DIO PLANETA SAUDADE","og_description":"Se voc\u00ea ainda n\u00e3o conhece a R\u00e1dio Planeta Saudade, est\u00e1 na hora de descobrir a...","og_url":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/09\/30\/radio-planeta-saudade-venha-conhecer-nossa-programacao\/","og_site_name":"R\u00c1DIO PLANETA SAUDADE","article_published_time":"2024-09-30T13:09:49+00:00","article_modified_time":"2024-09-30T13:09:51+00:00","og_image":[{"width":586,"height":574,"url":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2024\/09\/ACESSE-2024.jpg","type":"image\/jpeg"}],"author":"Planeta Saudade","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Planeta Saudade","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/09\/30\/radio-planeta-saudade-venha-conhecer-nossa-programacao\/#article","isPartOf":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/09\/30\/radio-planeta-saudade-venha-conhecer-nossa-programacao\/"},"author":{"name":"Planeta Saudade","@id":"https:\/\/radioplanetasaudade.com.br\/#\/schema\/person\/1a6f6fc0d987819324e7ed417a1a6581"},"headline":"R\u00e1dio Planeta Saudade, venha conhecer nossa programa\u00e7\u00e3o.","datePublished":"2024-09-30T13:09:49+00:00","dateModified":"2024-09-30T13:09:51+00:00","mainEntityOfPage":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/09\/30\/radio-planeta-saudade-venha-conhecer-nossa-programacao\/"},"wordCount":255,"commentCount":0,"publisher":{"@id":"https:\/\/radioplanetasaudade.com.br\/#organization"},"image":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/09\/30\/radio-planeta-saudade-venha-conhecer-nossa-programacao\/#primaryimage"},"thumbnailUrl":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2024\/09\/ACESSE-2024.jpg","keywords":["Anos 70","Anos 80","Anos 90","Baixe nosso App","Flashaback","Ouvir","Ouvir r\u00e1dio","R\u00e1dio","R\u00e1dio Planeta Saudade"],"articleSection":["BAIXE NOSSO APLICATIVO"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/09\/30\/radio-planeta-saudade-venha-conhecer-nossa-programacao\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/09\/30\/radio-planeta-saudade-venha-conhecer-nossa-programacao\/","url":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/09\/30\/radio-planeta-saudade-venha-conhecer-nossa-programacao\/","name":"R\u00e1dio Planeta Saudade, venha conhecer nossa programa\u00e7\u00e3o. - R\u00c1DIO PLANETA SAUDADE","isPartOf":{"@id":"https:\/\/radioplanetasaudade.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/09\/30\/radio-planeta-saudade-venha-conhecer-nossa-programacao\/#primaryimage"},"image":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/09\/30\/radio-planeta-saudade-venha-conhecer-nossa-programacao\/#primaryimage"},"thumbnailUrl":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2024\/09\/ACESSE-2024.jpg","datePublished":"2024-09-30T13:09:49+00:00","dateModified":"2024-09-30T13:09:51+00:00","breadcrumb":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/09\/30\/radio-planeta-saudade-venha-conhecer-nossa-programacao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/09\/30\/radio-planeta-saudade-venha-conhecer-nossa-programacao\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/09\/30\/radio-planeta-saudade-venha-conhecer-nossa-programacao\/#primaryimage","url":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2024\/09\/ACESSE-2024.jpg","contentUrl":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2024\/09\/ACESSE-2024.jpg","width":586,"height":574},{"@type":"BreadcrumbList","@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/09\/30\/radio-planeta-saudade-venha-conhecer-nossa-programacao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/radioplanetasaudade.com.br\/"},{"@type":"ListItem","position":2,"name":"R\u00e1dio Planeta Saudade, venha conhecer nossa programa\u00e7\u00e3o."}]},{"@type":"WebSite","@id":"https:\/\/radioplanetasaudade.com.br\/#website","url":"https:\/\/radioplanetasaudade.com.br\/","name":"R\u00e1dio Planeta Saudade","description":"Relembrando grandes sucessos musicais e informando sobre os maiores artistas do mundo ou\u00e7a no seu celular.","publisher":{"@id":"https:\/\/radioplanetasaudade.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radioplanetasaudade.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/radioplanetasaudade.com.br\/#organization","name":"R\u00e1dio Planeta Saudade","url":"https:\/\/radioplanetasaudade.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radioplanetasaudade.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2023\/10\/capture-20230607-202153.png","contentUrl":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2023\/10\/capture-20230607-202153.png","width":1350,"height":358,"caption":"R\u00e1dio Planeta Saudade"},"image":{"@id":"https:\/\/radioplanetasaudade.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/radioplanetasaudade.com.br\/#\/schema\/person\/1a6f6fc0d987819324e7ed417a1a6581","name":"Planeta Saudade","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g","caption":"Planeta Saudade"},"sameAs":["https:\/\/radioplanetasaudade.com.br"],"url":"https:\/\/radioplanetasaudade.com.br\/index.php\/author\/wendelsantos4567\/"}]}},"_links":{"self":[{"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2627","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=2627"}],"version-history":[{"count":1,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2627\/revisions"}],"predecessor-version":[{"id":2629,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2627\/revisions\/2629"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/media\/2628"}],"wp:attachment":[{"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=2627"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=2627"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=2627"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}