{"id":2708,"date":"2024-10-14T10:17:59","date_gmt":"2024-10-14T13:17:59","guid":{"rendered":"https:\/\/radioplanetasaudade.com.br\/?p=2708"},"modified":"2024-10-14T10:18:00","modified_gmt":"2024-10-14T13:18:00","slug":"essa-voce-ouve-na-radio-planeta-saudade-16","status":"publish","type":"post","link":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/10\/14\/essa-voce-ouve-na-radio-planeta-saudade-16\/","title":{"rendered":"&#8220;Essa voc\u00ea ouve na R\u00e1dio Planeta Saudade&#8221;"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">&#8220;One More Try&#8221;, can\u00e7\u00e3o de George Michael, lan\u00e7ada em 1988 como o quinto single do \u00e1lbum Faith, \u00e9 uma das baladas mais emocionantes e introspectivas do cantor brit\u00e2nico.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"588\" height=\"577\" src=\"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2024\/10\/GEORGE-MICHAEL.jpg\" alt=\"\" class=\"wp-image-2709\" srcset=\"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2024\/10\/GEORGE-MICHAEL.jpg 588w, https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2024\/10\/GEORGE-MICHAEL-300x294.jpg 300w\" sizes=\"(max-width: 588px) 100vw, 588px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">A can\u00e7\u00e3o foi aclamada por sua profundidade l\u00edrica e pela poderosa interpreta\u00e7\u00e3o vocal de George Michael, que retrata um sentimento de vulnerabilidade e dor ao lidar com a incerteza do amor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Musicalmente, a can\u00e7\u00e3o se destaca por sua simplicidade, constru\u00edda em torno de uma melodia suave ao piano, permitindo que a voz de George Michael seja o principal elemento emocional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A letra fala sobre algu\u00e9m que, ap\u00f3s sofrer no amor, hesita em se abrir novamente, mas ao mesmo tempo sente o desejo de tentar mais uma vez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A melancolia da can\u00e7\u00e3o ressoou fortemente com o p\u00fablico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nas paradas de sucesso, &#8220;One More Try&#8221; foi um verdadeiro fen\u00f4meno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Atingiu o primeiro lugar na Billboard Hot 100 dos Estados Unidos em maio de 1988, permanecendo no topo por tr\u00eas semanas consecutivas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, alcan\u00e7ou o topo das paradas de R&amp;B, destacando a versatilidade de George Michael em atravessar g\u00eaneros musicais. Internacionalmente, a m\u00fasica tamb\u00e9m fez sucesso, chegando ao top 10 em v\u00e1rios pa\u00edses, incluindo o Reino Unido, Canad\u00e1 e Irlanda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A balada consolidou ainda mais George Michael como um dos maiores artistas de sua \u00e9poca.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ele demonstrou sua capacidade de criar can\u00e7\u00f5es profundamente pessoais, que se conectavam com o p\u00fablico em um n\u00edvel emocional. &#8220;One More Try&#8221; continua a ser uma de suas m\u00fasicas mais lembradas e respeitadas, frequentemente inclu\u00edda em compila\u00e7\u00f5es e playlists de baladas rom\u00e2nticas nas r\u00e1dios e plataformas de streaming, como na R\u00e1dio Planeta Saudade, onde o cl\u00e1ssico emociona ouvintes at\u00e9 hoje.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.facebook.com\/photo\/?fbid=122234946716002213&amp;set=a.122106579512002213&amp;__cft__[0]=AZW4oVO5vxo4k1eZTE3SwEVEyy-FyrwdPTj3jwkfU7pcugf4ytjTxRPAHx3RZs5L3PLB9r0W3pMlekGd1wf-de0dF2fmSg9DuTN6fQqtJ5wc8afZPTKRmasCwYdM44eCGH6FuEyQ7YjR4A9HuqYcAfze5wsdgniDJ77hYx3ZrCYgd0OKlVjiIlcdnm1HR9usbAxxN4NI1vk_FAtH52a3onsV&amp;__tn__=EH-R\"><\/a><\/p>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/www.facebook.com\/photo\/?fbid=122234946716002213&amp;set=a.122106579512002213&amp;__cft__[0]=AZW4oVO5vxo4k1eZTE3SwEVEyy-FyrwdPTj3jwkfU7pcugf4ytjTxRPAHx3RZs5L3PLB9r0W3pMlekGd1wf-de0dF2fmSg9DuTN6fQqtJ5wc8afZPTKRmasCwYdM44eCGH6FuEyQ7YjR4A9HuqYcAfze5wsdgniDJ77hYx3ZrCYgd0OKlVjiIlcdnm1HR9usbAxxN4NI1vk_FAtH52a3onsV&amp;__tn__=EH-R\"><img decoding=\"async\" src=\"https:\/\/scontent.fvix20-1.fna.fbcdn.net\/v\/t39.30808-6\/463246758_122234946722002213_2680286158908610601_n.jpg?stp=dst-jpg_p526x296&amp;_nc_cat=105&amp;ccb=1-7&amp;_nc_sid=127cfc&amp;_nc_ohc=_Kk7RUjjh0oQ7kNvgHyvCQ9&amp;_nc_zt=23&amp;_nc_ht=scontent.fvix20-1.fna&amp;_nc_gid=A_RQMu22X_Qgp4zWJnc6zvC&amp;oh=00_AYBicHOOeaBzZ4WJWNQ5C21hRWjdCpDpf38h84vTky_qJw&amp;oe=6712D800\" alt=\"Pode ser uma imagem de 1 pessoa e a texto\"\/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Ver estat\u00edsticas e an\u00fancios<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.facebook.com\/ad_center\/create\/boostpost\/?entry_point=www_profile_plus_timeline&amp;page_id=138481246020126&amp;target_id=122234946770002213&amp;__cft__[0]=AZW4oVO5vxo4k1eZTE3SwEVEyy-FyrwdPTj3jwkfU7pcugf4ytjTxRPAHx3RZs5L3PLB9r0W3pMlekGd1wf-de0dF2fmSg9DuTN6fQqtJ5wc8afZPTKRmasCwYdM44eCGH6FuEyQ7YjR4A9HuqYcAfze5wsdgniDJ77hYx3ZrCYgd0OKlVjiIlcdnm1HR9usbAxxN4NI1vk_FAtH52a3onsV&amp;__tn__=*W-R\"><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.facebook.com\/ad_center\/create\/boostpost\/?entry_point=www_profile_plus_timeline&amp;page_id=138481246020126&amp;target_id=122234946770002213&amp;__cft__[0]=AZW4oVO5vxo4k1eZTE3SwEVEyy-FyrwdPTj3jwkfU7pcugf4ytjTxRPAHx3RZs5L3PLB9r0W3pMlekGd1wf-de0dF2fmSg9DuTN6fQqtJ5wc8afZPTKRmasCwYdM44eCGH6FuEyQ7YjR4A9HuqYcAfze5wsdgniDJ77hYx3ZrCYgd0OKlVjiIlcdnm1HR9usbAxxN4NI1vk_FAtH52a3onsV&amp;__tn__=*W-R\">Promover publica\u00e7\u00e3o<\/a><\/p>\n\n\n\n\n\n<p class=\"wp-block-paragraph\">Todas as rea\u00e7\u00f5es:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2Tu&nbsp;e a Cezar Muzzio<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;One More Try&#8221;, can\u00e7\u00e3o de George Michael, lan\u00e7ada em 1988 como o quinto single do&#8230;<\/p>\n","protected":false},"author":1,"featured_media":2709,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[213],"tags":[1021,119,118,120,121,117,631,1022,561,562,116,99],"class_list":["post-2708","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-qual-e-a-sua-saudade","tag-album-faith","tag-anos-70","tag-anos-80","tag-anos-90","tag-baixe-nosso-app","tag-flashaback","tag-george-michael","tag-one-more-try","tag-ouvir","tag-ouvir-radio","tag-radio","tag-radio-planeta-saudade"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;Essa voc\u00ea ouve na R\u00e1dio Planeta Saudade&quot; - R\u00c1DIO PLANETA SAUDADE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/10\/14\/essa-voce-ouve-na-radio-planeta-saudade-16\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Essa voc\u00ea ouve na R\u00e1dio Planeta Saudade&quot; - R\u00c1DIO PLANETA SAUDADE\" \/>\n<meta property=\"og:description\" content=\"&#8220;One More Try&#8221;, can\u00e7\u00e3o de George Michael, lan\u00e7ada em 1988 como o quinto single do...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/10\/14\/essa-voce-ouve-na-radio-planeta-saudade-16\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00c1DIO PLANETA SAUDADE\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-14T13:17:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-14T13:18:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2024\/10\/GEORGE-MICHAEL.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"588\" \/>\n\t<meta property=\"og:image:height\" content=\"577\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Planeta Saudade\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Planeta Saudade\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2024\\\/10\\\/14\\\/essa-voce-ouve-na-radio-planeta-saudade-16\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2024\\\/10\\\/14\\\/essa-voce-ouve-na-radio-planeta-saudade-16\\\/\"},\"author\":{\"name\":\"Planeta Saudade\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#\\\/schema\\\/person\\\/1a6f6fc0d987819324e7ed417a1a6581\"},\"headline\":\"&#8220;Essa voc\u00ea ouve na R\u00e1dio Planeta Saudade&#8221;\",\"datePublished\":\"2024-10-14T13:17:59+00:00\",\"dateModified\":\"2024-10-14T13:18:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2024\\\/10\\\/14\\\/essa-voce-ouve-na-radio-planeta-saudade-16\\\/\"},\"wordCount\":326,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2024\\\/10\\\/14\\\/essa-voce-ouve-na-radio-planeta-saudade-16\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/GEORGE-MICHAEL.jpg\",\"keywords\":[\"\u00e1lbum Faith\",\"Anos 70\",\"Anos 80\",\"Anos 90\",\"Baixe nosso App\",\"Flashaback\",\"George Michael\",\"One More Try\",\"Ouvir\",\"Ouvir r\u00e1dio\",\"R\u00e1dio\",\"R\u00e1dio Planeta Saudade\"],\"articleSection\":[\"QUAL \u00c9 A SUA SAUDADE?\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2024\\\/10\\\/14\\\/essa-voce-ouve-na-radio-planeta-saudade-16\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2024\\\/10\\\/14\\\/essa-voce-ouve-na-radio-planeta-saudade-16\\\/\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2024\\\/10\\\/14\\\/essa-voce-ouve-na-radio-planeta-saudade-16\\\/\",\"name\":\"\\\"Essa voc\u00ea ouve na R\u00e1dio Planeta Saudade\\\" - R\u00c1DIO PLANETA SAUDADE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2024\\\/10\\\/14\\\/essa-voce-ouve-na-radio-planeta-saudade-16\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2024\\\/10\\\/14\\\/essa-voce-ouve-na-radio-planeta-saudade-16\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/GEORGE-MICHAEL.jpg\",\"datePublished\":\"2024-10-14T13:17:59+00:00\",\"dateModified\":\"2024-10-14T13:18:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2024\\\/10\\\/14\\\/essa-voce-ouve-na-radio-planeta-saudade-16\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2024\\\/10\\\/14\\\/essa-voce-ouve-na-radio-planeta-saudade-16\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2024\\\/10\\\/14\\\/essa-voce-ouve-na-radio-planeta-saudade-16\\\/#primaryimage\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/GEORGE-MICHAEL.jpg\",\"contentUrl\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/GEORGE-MICHAEL.jpg\",\"width\":588,\"height\":577},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2024\\\/10\\\/14\\\/essa-voce-ouve-na-radio-planeta-saudade-16\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;Essa voc\u00ea ouve na R\u00e1dio Planeta Saudade&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#website\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/\",\"name\":\"R\u00e1dio Planeta Saudade\",\"description\":\"Relembrando grandes sucessos musicais e informando sobre os maiores artistas do mundo ou\u00e7a no seu celular.\",\"publisher\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#organization\",\"name\":\"R\u00e1dio Planeta Saudade\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/capture-20230607-202153.png\",\"contentUrl\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/capture-20230607-202153.png\",\"width\":1350,\"height\":358,\"caption\":\"R\u00e1dio Planeta Saudade\"},\"image\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#\\\/schema\\\/person\\\/1a6f6fc0d987819324e7ed417a1a6581\",\"name\":\"Planeta Saudade\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g\",\"caption\":\"Planeta Saudade\"},\"sameAs\":[\"https:\\\/\\\/radioplanetasaudade.com.br\"],\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/author\\\/wendelsantos4567\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Essa voc\u00ea ouve na R\u00e1dio Planeta Saudade\" - R\u00c1DIO PLANETA SAUDADE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/10\/14\/essa-voce-ouve-na-radio-planeta-saudade-16\/","og_locale":"pt_BR","og_type":"article","og_title":"\"Essa voc\u00ea ouve na R\u00e1dio Planeta Saudade\" - R\u00c1DIO PLANETA SAUDADE","og_description":"&#8220;One More Try&#8221;, can\u00e7\u00e3o de George Michael, lan\u00e7ada em 1988 como o quinto single do...","og_url":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/10\/14\/essa-voce-ouve-na-radio-planeta-saudade-16\/","og_site_name":"R\u00c1DIO PLANETA SAUDADE","article_published_time":"2024-10-14T13:17:59+00:00","article_modified_time":"2024-10-14T13:18:00+00:00","og_image":[{"width":588,"height":577,"url":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2024\/10\/GEORGE-MICHAEL.jpg","type":"image\/jpeg"}],"author":"Planeta Saudade","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Planeta Saudade","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/10\/14\/essa-voce-ouve-na-radio-planeta-saudade-16\/#article","isPartOf":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/10\/14\/essa-voce-ouve-na-radio-planeta-saudade-16\/"},"author":{"name":"Planeta Saudade","@id":"https:\/\/radioplanetasaudade.com.br\/#\/schema\/person\/1a6f6fc0d987819324e7ed417a1a6581"},"headline":"&#8220;Essa voc\u00ea ouve na R\u00e1dio Planeta Saudade&#8221;","datePublished":"2024-10-14T13:17:59+00:00","dateModified":"2024-10-14T13:18:00+00:00","mainEntityOfPage":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/10\/14\/essa-voce-ouve-na-radio-planeta-saudade-16\/"},"wordCount":326,"commentCount":0,"publisher":{"@id":"https:\/\/radioplanetasaudade.com.br\/#organization"},"image":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/10\/14\/essa-voce-ouve-na-radio-planeta-saudade-16\/#primaryimage"},"thumbnailUrl":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2024\/10\/GEORGE-MICHAEL.jpg","keywords":["\u00e1lbum Faith","Anos 70","Anos 80","Anos 90","Baixe nosso App","Flashaback","George Michael","One More Try","Ouvir","Ouvir r\u00e1dio","R\u00e1dio","R\u00e1dio Planeta Saudade"],"articleSection":["QUAL \u00c9 A SUA SAUDADE?"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/10\/14\/essa-voce-ouve-na-radio-planeta-saudade-16\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/10\/14\/essa-voce-ouve-na-radio-planeta-saudade-16\/","url":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/10\/14\/essa-voce-ouve-na-radio-planeta-saudade-16\/","name":"\"Essa voc\u00ea ouve na R\u00e1dio Planeta Saudade\" - R\u00c1DIO PLANETA SAUDADE","isPartOf":{"@id":"https:\/\/radioplanetasaudade.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/10\/14\/essa-voce-ouve-na-radio-planeta-saudade-16\/#primaryimage"},"image":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/10\/14\/essa-voce-ouve-na-radio-planeta-saudade-16\/#primaryimage"},"thumbnailUrl":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2024\/10\/GEORGE-MICHAEL.jpg","datePublished":"2024-10-14T13:17:59+00:00","dateModified":"2024-10-14T13:18:00+00:00","breadcrumb":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/10\/14\/essa-voce-ouve-na-radio-planeta-saudade-16\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/10\/14\/essa-voce-ouve-na-radio-planeta-saudade-16\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/10\/14\/essa-voce-ouve-na-radio-planeta-saudade-16\/#primaryimage","url":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2024\/10\/GEORGE-MICHAEL.jpg","contentUrl":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2024\/10\/GEORGE-MICHAEL.jpg","width":588,"height":577},{"@type":"BreadcrumbList","@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/10\/14\/essa-voce-ouve-na-radio-planeta-saudade-16\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/radioplanetasaudade.com.br\/"},{"@type":"ListItem","position":2,"name":"&#8220;Essa voc\u00ea ouve na R\u00e1dio Planeta Saudade&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/radioplanetasaudade.com.br\/#website","url":"https:\/\/radioplanetasaudade.com.br\/","name":"R\u00e1dio Planeta Saudade","description":"Relembrando grandes sucessos musicais e informando sobre os maiores artistas do mundo ou\u00e7a no seu celular.","publisher":{"@id":"https:\/\/radioplanetasaudade.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radioplanetasaudade.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/radioplanetasaudade.com.br\/#organization","name":"R\u00e1dio Planeta Saudade","url":"https:\/\/radioplanetasaudade.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radioplanetasaudade.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2023\/10\/capture-20230607-202153.png","contentUrl":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2023\/10\/capture-20230607-202153.png","width":1350,"height":358,"caption":"R\u00e1dio Planeta Saudade"},"image":{"@id":"https:\/\/radioplanetasaudade.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/radioplanetasaudade.com.br\/#\/schema\/person\/1a6f6fc0d987819324e7ed417a1a6581","name":"Planeta Saudade","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g","caption":"Planeta Saudade"},"sameAs":["https:\/\/radioplanetasaudade.com.br"],"url":"https:\/\/radioplanetasaudade.com.br\/index.php\/author\/wendelsantos4567\/"}]}},"_links":{"self":[{"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2708","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=2708"}],"version-history":[{"count":1,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2708\/revisions"}],"predecessor-version":[{"id":2710,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2708\/revisions\/2710"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/media\/2709"}],"wp:attachment":[{"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=2708"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=2708"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=2708"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}