{"id":3576,"date":"2025-02-16T11:34:12","date_gmt":"2025-02-16T14:34:12","guid":{"rendered":"https:\/\/radioplanetasaudade.com.br\/?p=3576"},"modified":"2025-02-16T11:34:13","modified_gmt":"2025-02-16T14:34:13","slug":"feliz-aniversario-socorro-lima","status":"publish","type":"post","link":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/02\/16\/feliz-aniversario-socorro-lima\/","title":{"rendered":"Feliz Anivers\u00e1rio, Socorro Lima!"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><em>Hoje \u00e9 dia de festa aqui na R\u00e1dio Planeta Saudade! Queremos dedicar um momento especial para parabenizar nossa querida ouvinte Socorro Lima, da cidade de Carapicu\u00edba &#8211; S\u00e3o Paulo.<\/em><\/strong> <img decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t5\/1\/16\/1f382.png\" alt=\"\ud83c\udf82\"><img decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/tb\/1\/16\/1f388.png\" alt=\"\ud83c\udf88\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"1022\" src=\"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2025\/02\/ANIVERSARIANTE-DO-DIA-1024x1022.jpg\" alt=\"\" class=\"wp-image-3577\" srcset=\"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2025\/02\/ANIVERSARIANTE-DO-DIA-1024x1022.jpg 1024w, https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2025\/02\/ANIVERSARIANTE-DO-DIA-300x300.jpg 300w, https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2025\/02\/ANIVERSARIANTE-DO-DIA-150x150.jpg 150w, https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2025\/02\/ANIVERSARIANTE-DO-DIA-768x766.jpg 768w, https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2025\/02\/ANIVERSARIANTE-DO-DIA-1536x1533.jpg 1536w, https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2025\/02\/ANIVERSARIANTE-DO-DIA-2048x2044.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Carinhosamente chamada de patroa, voc\u00ea faz parte da nossa fam\u00edlia h\u00e1 muitos anos, sempre acompanhando nossa programa\u00e7\u00e3o, vibrando com cada m\u00fasica e compartilhando seu carinho com a gente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9 uma alegria enorme saber que temos ouvintes fi\u00e9is como voc\u00ea, que fazem da R\u00e1dio Planeta Saudade um verdadeiro lar de boas lembran\u00e7as e emo\u00e7\u00f5es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Que este novo ciclo seja repleto de muita paz, sa\u00fade e felicidade! Que sua vida seja iluminada por momentos de alegria, cercada por amor e sempre embalada pelas can\u00e7\u00f5es que tocam seu cora\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Continue sempre ligadinha na nossa programa\u00e7\u00e3o, porque a R\u00e1dio Planeta Saudade estar\u00e1 aqui para levar emo\u00e7\u00e3o e nostalgia para voc\u00ea e todos os nossos ouvintes apaixonados por boa m\u00fasica!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Um grande abra\u00e7o de toda a equipe da R\u00e1dio Planeta Saudade! Parab\u00e9ns, Socorro! <img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83c\udfb6\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t1f\/1\/16\/1f3b6.png\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\u2764\ufe0f\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t6c\/1\/16\/2764.png\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83c\udf8a\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/tb4\/1\/16\/1f38a.png\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoje \u00e9 dia de festa aqui na R\u00e1dio Planeta Saudade! Queremos dedicar um momento especial&#8230;<\/p>\n","protected":false},"author":1,"featured_media":3577,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1706],"tags":[119,118,120,121,117,1707,561,562,116,99],"class_list":["post-3576","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ouvinte-aniversariante","tag-anos-70","tag-anos-80","tag-anos-90","tag-baixe-nosso-app","tag-flashaback","tag-ouvinte-aniversariante","tag-ouvir","tag-ouvir-radio","tag-radio","tag-radio-planeta-saudade"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Feliz Anivers\u00e1rio, Socorro Lima! - R\u00c1DIO PLANETA SAUDADE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/02\/16\/feliz-aniversario-socorro-lima\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Feliz Anivers\u00e1rio, Socorro Lima! - R\u00c1DIO PLANETA SAUDADE\" \/>\n<meta property=\"og:description\" content=\"Hoje \u00e9 dia de festa aqui na R\u00e1dio Planeta Saudade! Queremos dedicar um momento especial...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/02\/16\/feliz-aniversario-socorro-lima\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00c1DIO PLANETA SAUDADE\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-16T14:34:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-16T14:34:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2025\/02\/ANIVERSARIANTE-DO-DIA-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2555\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Planeta Saudade\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Planeta Saudade\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/02\\\/16\\\/feliz-aniversario-socorro-lima\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/02\\\/16\\\/feliz-aniversario-socorro-lima\\\/\"},\"author\":{\"name\":\"Planeta Saudade\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#\\\/schema\\\/person\\\/1a6f6fc0d987819324e7ed417a1a6581\"},\"headline\":\"Feliz Anivers\u00e1rio, Socorro Lima!\",\"datePublished\":\"2025-02-16T14:34:12+00:00\",\"dateModified\":\"2025-02-16T14:34:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/02\\\/16\\\/feliz-aniversario-socorro-lima\\\/\"},\"wordCount\":180,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/02\\\/16\\\/feliz-aniversario-socorro-lima\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/ANIVERSARIANTE-DO-DIA-scaled.jpg\",\"keywords\":[\"Anos 70\",\"Anos 80\",\"Anos 90\",\"Baixe nosso App\",\"Flashaback\",\"OUVINTE ANIVERSARIANTE\",\"Ouvir\",\"Ouvir r\u00e1dio\",\"R\u00e1dio\",\"R\u00e1dio Planeta Saudade\"],\"articleSection\":[\"OUVINTE ANIVERSARIANTE\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/02\\\/16\\\/feliz-aniversario-socorro-lima\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/02\\\/16\\\/feliz-aniversario-socorro-lima\\\/\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/02\\\/16\\\/feliz-aniversario-socorro-lima\\\/\",\"name\":\"Feliz Anivers\u00e1rio, Socorro Lima! - R\u00c1DIO PLANETA SAUDADE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/02\\\/16\\\/feliz-aniversario-socorro-lima\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/02\\\/16\\\/feliz-aniversario-socorro-lima\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/ANIVERSARIANTE-DO-DIA-scaled.jpg\",\"datePublished\":\"2025-02-16T14:34:12+00:00\",\"dateModified\":\"2025-02-16T14:34:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/02\\\/16\\\/feliz-aniversario-socorro-lima\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/02\\\/16\\\/feliz-aniversario-socorro-lima\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/02\\\/16\\\/feliz-aniversario-socorro-lima\\\/#primaryimage\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/ANIVERSARIANTE-DO-DIA-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/ANIVERSARIANTE-DO-DIA-scaled.jpg\",\"width\":2560,\"height\":2555},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/02\\\/16\\\/feliz-aniversario-socorro-lima\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Feliz Anivers\u00e1rio, Socorro Lima!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#website\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/\",\"name\":\"R\u00e1dio Planeta Saudade\",\"description\":\"Relembrando grandes sucessos musicais e informando sobre os maiores artistas do mundo ou\u00e7a no seu celular.\",\"publisher\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#organization\",\"name\":\"R\u00e1dio Planeta Saudade\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/capture-20230607-202153.png\",\"contentUrl\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/capture-20230607-202153.png\",\"width\":1350,\"height\":358,\"caption\":\"R\u00e1dio Planeta Saudade\"},\"image\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#\\\/schema\\\/person\\\/1a6f6fc0d987819324e7ed417a1a6581\",\"name\":\"Planeta Saudade\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g\",\"caption\":\"Planeta Saudade\"},\"sameAs\":[\"https:\\\/\\\/radioplanetasaudade.com.br\"],\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/author\\\/wendelsantos4567\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Feliz Anivers\u00e1rio, Socorro Lima! - R\u00c1DIO PLANETA SAUDADE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/02\/16\/feliz-aniversario-socorro-lima\/","og_locale":"pt_BR","og_type":"article","og_title":"Feliz Anivers\u00e1rio, Socorro Lima! - R\u00c1DIO PLANETA SAUDADE","og_description":"Hoje \u00e9 dia de festa aqui na R\u00e1dio Planeta Saudade! Queremos dedicar um momento especial...","og_url":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/02\/16\/feliz-aniversario-socorro-lima\/","og_site_name":"R\u00c1DIO PLANETA SAUDADE","article_published_time":"2025-02-16T14:34:12+00:00","article_modified_time":"2025-02-16T14:34:13+00:00","og_image":[{"width":2560,"height":2555,"url":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2025\/02\/ANIVERSARIANTE-DO-DIA-scaled.jpg","type":"image\/jpeg"}],"author":"Planeta Saudade","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Planeta Saudade","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/02\/16\/feliz-aniversario-socorro-lima\/#article","isPartOf":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/02\/16\/feliz-aniversario-socorro-lima\/"},"author":{"name":"Planeta Saudade","@id":"https:\/\/radioplanetasaudade.com.br\/#\/schema\/person\/1a6f6fc0d987819324e7ed417a1a6581"},"headline":"Feliz Anivers\u00e1rio, Socorro Lima!","datePublished":"2025-02-16T14:34:12+00:00","dateModified":"2025-02-16T14:34:13+00:00","mainEntityOfPage":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/02\/16\/feliz-aniversario-socorro-lima\/"},"wordCount":180,"commentCount":0,"publisher":{"@id":"https:\/\/radioplanetasaudade.com.br\/#organization"},"image":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/02\/16\/feliz-aniversario-socorro-lima\/#primaryimage"},"thumbnailUrl":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2025\/02\/ANIVERSARIANTE-DO-DIA-scaled.jpg","keywords":["Anos 70","Anos 80","Anos 90","Baixe nosso App","Flashaback","OUVINTE ANIVERSARIANTE","Ouvir","Ouvir r\u00e1dio","R\u00e1dio","R\u00e1dio Planeta Saudade"],"articleSection":["OUVINTE ANIVERSARIANTE"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/02\/16\/feliz-aniversario-socorro-lima\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/02\/16\/feliz-aniversario-socorro-lima\/","url":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/02\/16\/feliz-aniversario-socorro-lima\/","name":"Feliz Anivers\u00e1rio, Socorro Lima! - R\u00c1DIO PLANETA SAUDADE","isPartOf":{"@id":"https:\/\/radioplanetasaudade.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/02\/16\/feliz-aniversario-socorro-lima\/#primaryimage"},"image":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/02\/16\/feliz-aniversario-socorro-lima\/#primaryimage"},"thumbnailUrl":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2025\/02\/ANIVERSARIANTE-DO-DIA-scaled.jpg","datePublished":"2025-02-16T14:34:12+00:00","dateModified":"2025-02-16T14:34:13+00:00","breadcrumb":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/02\/16\/feliz-aniversario-socorro-lima\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/02\/16\/feliz-aniversario-socorro-lima\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/02\/16\/feliz-aniversario-socorro-lima\/#primaryimage","url":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2025\/02\/ANIVERSARIANTE-DO-DIA-scaled.jpg","contentUrl":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2025\/02\/ANIVERSARIANTE-DO-DIA-scaled.jpg","width":2560,"height":2555},{"@type":"BreadcrumbList","@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/02\/16\/feliz-aniversario-socorro-lima\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/radioplanetasaudade.com.br\/"},{"@type":"ListItem","position":2,"name":"Feliz Anivers\u00e1rio, Socorro Lima!"}]},{"@type":"WebSite","@id":"https:\/\/radioplanetasaudade.com.br\/#website","url":"https:\/\/radioplanetasaudade.com.br\/","name":"R\u00e1dio Planeta Saudade","description":"Relembrando grandes sucessos musicais e informando sobre os maiores artistas do mundo ou\u00e7a no seu celular.","publisher":{"@id":"https:\/\/radioplanetasaudade.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radioplanetasaudade.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/radioplanetasaudade.com.br\/#organization","name":"R\u00e1dio Planeta Saudade","url":"https:\/\/radioplanetasaudade.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radioplanetasaudade.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2023\/10\/capture-20230607-202153.png","contentUrl":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2023\/10\/capture-20230607-202153.png","width":1350,"height":358,"caption":"R\u00e1dio Planeta Saudade"},"image":{"@id":"https:\/\/radioplanetasaudade.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/radioplanetasaudade.com.br\/#\/schema\/person\/1a6f6fc0d987819324e7ed417a1a6581","name":"Planeta Saudade","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g","caption":"Planeta Saudade"},"sameAs":["https:\/\/radioplanetasaudade.com.br"],"url":"https:\/\/radioplanetasaudade.com.br\/index.php\/author\/wendelsantos4567\/"}]}},"_links":{"self":[{"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3576","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=3576"}],"version-history":[{"count":1,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3576\/revisions"}],"predecessor-version":[{"id":3578,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3576\/revisions\/3578"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/media\/3577"}],"wp:attachment":[{"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=3576"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=3576"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=3576"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}