{"id":3673,"date":"2025-03-02T14:00:55","date_gmt":"2025-03-02T17:00:55","guid":{"rendered":"https:\/\/radioplanetasaudade.com.br\/?p=3673"},"modified":"2025-03-02T14:00:57","modified_gmt":"2025-03-02T17:00:57","slug":"a-radio-planeta-saudade-tem-a-alegria-de-celebrar-sua-presenca-em-audiencia-em-todos-os-estados-do-pais-conquistando-cada-vez-mais-ouvintes-apaixonados-pela-melhor-selecao-musical-das-decadas-de-70","status":"publish","type":"post","link":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/03\/02\/a-radio-planeta-saudade-tem-a-alegria-de-celebrar-sua-presenca-em-audiencia-em-todos-os-estados-do-pais-conquistando-cada-vez-mais-ouvintes-apaixonados-pela-melhor-selecao-musical-das-decadas-de-70\/","title":{"rendered":"A R\u00e1dio Planeta Saudade tem a alegria de celebrar sua presen\u00e7a em audi\u00eancia em todos os estados do pa\u00eds, conquistando cada vez mais ouvintes apaixonados pela melhor sele\u00e7\u00e3o musical das d\u00e9cadas de 70, 80, 90 e 2000."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><em>Com uma programa\u00e7\u00e3o cuidadosamente elaborada, buscamos proporcionar momentos inesquec\u00edveis atrav\u00e9s das can\u00e7\u00f5es que marcaram \u00e9poca e continuam emocionando gera\u00e7\u00f5es.<\/em><\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Hoje, queremos expressar nossa gratid\u00e3o a tr\u00eas ouvintes especiais que se destacaram por sua grande audi\u00eancia e participa\u00e7\u00e3o ativa em nossa programa\u00e7\u00e3o.<\/p>\n<\/blockquote>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"498\" height=\"485\" src=\"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2025\/03\/PERFEITO.png\" alt=\"\" class=\"wp-image-3674\" srcset=\"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2025\/03\/PERFEITO.png 498w, https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2025\/03\/PERFEITO-300x292.png 300w\" sizes=\"(max-width: 498px) 100vw, 498px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Voc\u00eas fazem parte da nossa hist\u00f3ria e tornam a R\u00e1dio Planeta Saudade ainda mais vibrante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nossa audi\u00eancia fiel nos acompanha diariamente pelas ondas do r\u00e1dio e pelas diversas plataformas digitais, interagindo, enviando mensagens, fazendo pedidos musicais e compartilhando lembran\u00e7as especiais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esse envolvimento \u00e9 a prova de que a m\u00fasica tem o poder de unir pessoas, despertar emo\u00e7\u00f5es e reviver os melhores momentos da vida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cada ouvinte \u00e9 essencial para o sucesso da R\u00e1dio Planeta Saudade, e \u00e9 por isso que seguimos dedicados a oferecer uma programa\u00e7\u00e3o de qualidade, trazendo o melhor da m\u00fasica nacional e internacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Agradecemos por fazerem parte dessa jornada! Continuem sintonizados e participando, porque a nossa hist\u00f3ria continua sendo escrita por voc\u00eas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.facebook.com\/photo\/?fbid=639305149042557&amp;set=a.101160866190324&amp;__cft__[0]=AZVSCHS8s98VX9qQTisSk6-RB2OZ1MGE_WzEE_l2rYhFWBThCJ-sf1D6LDovF38oemJjf-bzCwvlzW34K_pPzyAdlDG2hXggkgV-mPIwDXRfjB3WtZ8-7rKaeFJPb9O6s0tqDR6br6uPNq0rD_JQwbZdls_Ehelvgh_WcWyXzgbuIu4QW3TwVBcQbfngYvcWbu0&amp;__tn__=EH-R\"><\/a><\/p>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/www.facebook.com\/photo\/?fbid=639305149042557&amp;set=a.101160866190324&amp;__cft__[0]=AZVSCHS8s98VX9qQTisSk6-RB2OZ1MGE_WzEE_l2rYhFWBThCJ-sf1D6LDovF38oemJjf-bzCwvlzW34K_pPzyAdlDG2hXggkgV-mPIwDXRfjB3WtZ8-7rKaeFJPb9O6s0tqDR6br6uPNq0rD_JQwbZdls_Ehelvgh_WcWyXzgbuIu4QW3TwVBcQbfngYvcWbu0&amp;__tn__=EH-R\"><img decoding=\"async\" src=\"https:\/\/scontent.fvix20-1.fna.fbcdn.net\/v\/t39.30808-6\/481689911_639305159042556_3368996950463341823_n.jpg?_nc_cat=107&amp;ccb=1-7&amp;_nc_sid=127cfc&amp;_nc_ohc=3x6EHeXE6X4Q7kNvgFIEvXT&amp;_nc_oc=Adhf2NxCZmSmV0rEhA5OZoSjDA4aQvslRfJsfprQraKZB94TDfN_I1l_pn8x43xfgLliYmdQZIeZm6VbRGwbmBjr&amp;_nc_zt=23&amp;_nc_ht=scontent.fvix20-1.fna&amp;_nc_gid=A3r-xkcZJ8enVhl2byRoDmt&amp;oh=00_AYDuCHpvP4-b5BA7ZfGFQBV3F8a5smOs8O_s6Yi4Q3pM9A&amp;oe=67CA5D4C\" alt=\"Pode ser uma imagem de 3 pessoas e texto que diz &quot;PLANETA SAUDADE falaoma COM ELES DE MUSICA ROSANGELA JORGE LUCIA CARVALHO BELO HORIZONTE \/MG CAUCAIA \/CE CARLOS ROBERTO POUSO ALEGRE MG TODOS VAO RESPONDER RADIO PLANETA SAUDADE BAIXE NOSSO APP Google Play f 0G You YouTube Kwai&quot;\"\/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Ver insights<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Turbinar um post<\/p>\n\n\n\n\n\n<p class=\"wp-block-paragraph\">Todas as rea\u00e7\u00f5es:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1Wendel Santos<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Com uma programa\u00e7\u00e3o cuidadosamente elaborada, buscamos proporcionar momentos inesquec\u00edveis atrav\u00e9s das can\u00e7\u00f5es que marcaram \u00e9poca&#8230;<\/p>\n","protected":false},"author":1,"featured_media":3674,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[94],"tags":[119,118,120,121,117,1574,561,562,116,99],"class_list":["post-3673","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ouvinte-da-semana","tag-anos-70","tag-anos-80","tag-anos-90","tag-baixe-nosso-app","tag-flashaback","tag-ouvintes-da-semana","tag-ouvir","tag-ouvir-radio","tag-radio","tag-radio-planeta-saudade"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A R\u00e1dio Planeta Saudade tem a alegria de celebrar sua presen\u00e7a em audi\u00eancia em todos os estados do pa\u00eds, conquistando cada vez mais ouvintes apaixonados pela melhor sele\u00e7\u00e3o musical das d\u00e9cadas de 70, 80, 90 e 2000. - R\u00c1DIO PLANETA SAUDADE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/03\/02\/a-radio-planeta-saudade-tem-a-alegria-de-celebrar-sua-presenca-em-audiencia-em-todos-os-estados-do-pais-conquistando-cada-vez-mais-ouvintes-apaixonados-pela-melhor-selecao-musical-das-decadas-de-70\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A R\u00e1dio Planeta Saudade tem a alegria de celebrar sua presen\u00e7a em audi\u00eancia em todos os estados do pa\u00eds, conquistando cada vez mais ouvintes apaixonados pela melhor sele\u00e7\u00e3o musical das d\u00e9cadas de 70, 80, 90 e 2000. - R\u00c1DIO PLANETA SAUDADE\" \/>\n<meta property=\"og:description\" content=\"Com uma programa\u00e7\u00e3o cuidadosamente elaborada, buscamos proporcionar momentos inesquec\u00edveis atrav\u00e9s das can\u00e7\u00f5es que marcaram \u00e9poca...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/03\/02\/a-radio-planeta-saudade-tem-a-alegria-de-celebrar-sua-presenca-em-audiencia-em-todos-os-estados-do-pais-conquistando-cada-vez-mais-ouvintes-apaixonados-pela-melhor-selecao-musical-das-decadas-de-70\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00c1DIO PLANETA SAUDADE\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-02T17:00:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-02T17:00:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2025\/03\/PERFEITO.png\" \/>\n\t<meta property=\"og:image:width\" content=\"498\" \/>\n\t<meta property=\"og:image:height\" content=\"485\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Planeta Saudade\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Planeta Saudade\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/03\\\/02\\\/a-radio-planeta-saudade-tem-a-alegria-de-celebrar-sua-presenca-em-audiencia-em-todos-os-estados-do-pais-conquistando-cada-vez-mais-ouvintes-apaixonados-pela-melhor-selecao-musical-das-decadas-de-70\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/03\\\/02\\\/a-radio-planeta-saudade-tem-a-alegria-de-celebrar-sua-presenca-em-audiencia-em-todos-os-estados-do-pais-conquistando-cada-vez-mais-ouvintes-apaixonados-pela-melhor-selecao-musical-das-decadas-de-70\\\/\"},\"author\":{\"name\":\"Planeta Saudade\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#\\\/schema\\\/person\\\/1a6f6fc0d987819324e7ed417a1a6581\"},\"headline\":\"A R\u00e1dio Planeta Saudade tem a alegria de celebrar sua presen\u00e7a em audi\u00eancia em todos os estados do pa\u00eds, conquistando cada vez mais ouvintes apaixonados pela melhor sele\u00e7\u00e3o musical das d\u00e9cadas de 70, 80, 90 e 2000.\",\"datePublished\":\"2025-03-02T17:00:55+00:00\",\"dateModified\":\"2025-03-02T17:00:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/03\\\/02\\\/a-radio-planeta-saudade-tem-a-alegria-de-celebrar-sua-presenca-em-audiencia-em-todos-os-estados-do-pais-conquistando-cada-vez-mais-ouvintes-apaixonados-pela-melhor-selecao-musical-das-decadas-de-70\\\/\"},\"wordCount\":226,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/03\\\/02\\\/a-radio-planeta-saudade-tem-a-alegria-de-celebrar-sua-presenca-em-audiencia-em-todos-os-estados-do-pais-conquistando-cada-vez-mais-ouvintes-apaixonados-pela-melhor-selecao-musical-das-decadas-de-70\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/PERFEITO.png\",\"keywords\":[\"Anos 70\",\"Anos 80\",\"Anos 90\",\"Baixe nosso App\",\"Flashaback\",\"Ouvintes da semana\",\"Ouvir\",\"Ouvir r\u00e1dio\",\"R\u00e1dio\",\"R\u00e1dio Planeta Saudade\"],\"articleSection\":[\"OUVINTE DA SEMANA\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/03\\\/02\\\/a-radio-planeta-saudade-tem-a-alegria-de-celebrar-sua-presenca-em-audiencia-em-todos-os-estados-do-pais-conquistando-cada-vez-mais-ouvintes-apaixonados-pela-melhor-selecao-musical-das-decadas-de-70\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/03\\\/02\\\/a-radio-planeta-saudade-tem-a-alegria-de-celebrar-sua-presenca-em-audiencia-em-todos-os-estados-do-pais-conquistando-cada-vez-mais-ouvintes-apaixonados-pela-melhor-selecao-musical-das-decadas-de-70\\\/\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/03\\\/02\\\/a-radio-planeta-saudade-tem-a-alegria-de-celebrar-sua-presenca-em-audiencia-em-todos-os-estados-do-pais-conquistando-cada-vez-mais-ouvintes-apaixonados-pela-melhor-selecao-musical-das-decadas-de-70\\\/\",\"name\":\"A R\u00e1dio Planeta Saudade tem a alegria de celebrar sua presen\u00e7a em audi\u00eancia em todos os estados do pa\u00eds, conquistando cada vez mais ouvintes apaixonados pela melhor sele\u00e7\u00e3o musical das d\u00e9cadas de 70, 80, 90 e 2000. - R\u00c1DIO PLANETA SAUDADE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/03\\\/02\\\/a-radio-planeta-saudade-tem-a-alegria-de-celebrar-sua-presenca-em-audiencia-em-todos-os-estados-do-pais-conquistando-cada-vez-mais-ouvintes-apaixonados-pela-melhor-selecao-musical-das-decadas-de-70\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/03\\\/02\\\/a-radio-planeta-saudade-tem-a-alegria-de-celebrar-sua-presenca-em-audiencia-em-todos-os-estados-do-pais-conquistando-cada-vez-mais-ouvintes-apaixonados-pela-melhor-selecao-musical-das-decadas-de-70\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/PERFEITO.png\",\"datePublished\":\"2025-03-02T17:00:55+00:00\",\"dateModified\":\"2025-03-02T17:00:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/03\\\/02\\\/a-radio-planeta-saudade-tem-a-alegria-de-celebrar-sua-presenca-em-audiencia-em-todos-os-estados-do-pais-conquistando-cada-vez-mais-ouvintes-apaixonados-pela-melhor-selecao-musical-das-decadas-de-70\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/03\\\/02\\\/a-radio-planeta-saudade-tem-a-alegria-de-celebrar-sua-presenca-em-audiencia-em-todos-os-estados-do-pais-conquistando-cada-vez-mais-ouvintes-apaixonados-pela-melhor-selecao-musical-das-decadas-de-70\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/03\\\/02\\\/a-radio-planeta-saudade-tem-a-alegria-de-celebrar-sua-presenca-em-audiencia-em-todos-os-estados-do-pais-conquistando-cada-vez-mais-ouvintes-apaixonados-pela-melhor-selecao-musical-das-decadas-de-70\\\/#primaryimage\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/PERFEITO.png\",\"contentUrl\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/PERFEITO.png\",\"width\":498,\"height\":485},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/03\\\/02\\\/a-radio-planeta-saudade-tem-a-alegria-de-celebrar-sua-presenca-em-audiencia-em-todos-os-estados-do-pais-conquistando-cada-vez-mais-ouvintes-apaixonados-pela-melhor-selecao-musical-das-decadas-de-70\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A R\u00e1dio Planeta Saudade tem a alegria de celebrar sua presen\u00e7a em audi\u00eancia em todos os estados do pa\u00eds, conquistando cada vez mais ouvintes apaixonados pela melhor sele\u00e7\u00e3o musical das d\u00e9cadas de 70, 80, 90 e 2000.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#website\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/\",\"name\":\"R\u00e1dio Planeta Saudade\",\"description\":\"Relembrando grandes sucessos musicais e informando sobre os maiores artistas do mundo ou\u00e7a no seu celular.\",\"publisher\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#organization\",\"name\":\"R\u00e1dio Planeta Saudade\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/capture-20230607-202153.png\",\"contentUrl\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/capture-20230607-202153.png\",\"width\":1350,\"height\":358,\"caption\":\"R\u00e1dio Planeta Saudade\"},\"image\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#\\\/schema\\\/person\\\/1a6f6fc0d987819324e7ed417a1a6581\",\"name\":\"Planeta Saudade\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g\",\"caption\":\"Planeta Saudade\"},\"sameAs\":[\"https:\\\/\\\/radioplanetasaudade.com.br\"],\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/author\\\/wendelsantos4567\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A R\u00e1dio Planeta Saudade tem a alegria de celebrar sua presen\u00e7a em audi\u00eancia em todos os estados do pa\u00eds, conquistando cada vez mais ouvintes apaixonados pela melhor sele\u00e7\u00e3o musical das d\u00e9cadas de 70, 80, 90 e 2000. - R\u00c1DIO PLANETA SAUDADE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/03\/02\/a-radio-planeta-saudade-tem-a-alegria-de-celebrar-sua-presenca-em-audiencia-em-todos-os-estados-do-pais-conquistando-cada-vez-mais-ouvintes-apaixonados-pela-melhor-selecao-musical-das-decadas-de-70\/","og_locale":"pt_BR","og_type":"article","og_title":"A R\u00e1dio Planeta Saudade tem a alegria de celebrar sua presen\u00e7a em audi\u00eancia em todos os estados do pa\u00eds, conquistando cada vez mais ouvintes apaixonados pela melhor sele\u00e7\u00e3o musical das d\u00e9cadas de 70, 80, 90 e 2000. - R\u00c1DIO PLANETA SAUDADE","og_description":"Com uma programa\u00e7\u00e3o cuidadosamente elaborada, buscamos proporcionar momentos inesquec\u00edveis atrav\u00e9s das can\u00e7\u00f5es que marcaram \u00e9poca...","og_url":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/03\/02\/a-radio-planeta-saudade-tem-a-alegria-de-celebrar-sua-presenca-em-audiencia-em-todos-os-estados-do-pais-conquistando-cada-vez-mais-ouvintes-apaixonados-pela-melhor-selecao-musical-das-decadas-de-70\/","og_site_name":"R\u00c1DIO PLANETA SAUDADE","article_published_time":"2025-03-02T17:00:55+00:00","article_modified_time":"2025-03-02T17:00:57+00:00","og_image":[{"width":498,"height":485,"url":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2025\/03\/PERFEITO.png","type":"image\/png"}],"author":"Planeta Saudade","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Planeta Saudade","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/03\/02\/a-radio-planeta-saudade-tem-a-alegria-de-celebrar-sua-presenca-em-audiencia-em-todos-os-estados-do-pais-conquistando-cada-vez-mais-ouvintes-apaixonados-pela-melhor-selecao-musical-das-decadas-de-70\/#article","isPartOf":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/03\/02\/a-radio-planeta-saudade-tem-a-alegria-de-celebrar-sua-presenca-em-audiencia-em-todos-os-estados-do-pais-conquistando-cada-vez-mais-ouvintes-apaixonados-pela-melhor-selecao-musical-das-decadas-de-70\/"},"author":{"name":"Planeta Saudade","@id":"https:\/\/radioplanetasaudade.com.br\/#\/schema\/person\/1a6f6fc0d987819324e7ed417a1a6581"},"headline":"A R\u00e1dio Planeta Saudade tem a alegria de celebrar sua presen\u00e7a em audi\u00eancia em todos os estados do pa\u00eds, conquistando cada vez mais ouvintes apaixonados pela melhor sele\u00e7\u00e3o musical das d\u00e9cadas de 70, 80, 90 e 2000.","datePublished":"2025-03-02T17:00:55+00:00","dateModified":"2025-03-02T17:00:57+00:00","mainEntityOfPage":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/03\/02\/a-radio-planeta-saudade-tem-a-alegria-de-celebrar-sua-presenca-em-audiencia-em-todos-os-estados-do-pais-conquistando-cada-vez-mais-ouvintes-apaixonados-pela-melhor-selecao-musical-das-decadas-de-70\/"},"wordCount":226,"commentCount":0,"publisher":{"@id":"https:\/\/radioplanetasaudade.com.br\/#organization"},"image":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/03\/02\/a-radio-planeta-saudade-tem-a-alegria-de-celebrar-sua-presenca-em-audiencia-em-todos-os-estados-do-pais-conquistando-cada-vez-mais-ouvintes-apaixonados-pela-melhor-selecao-musical-das-decadas-de-70\/#primaryimage"},"thumbnailUrl":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2025\/03\/PERFEITO.png","keywords":["Anos 70","Anos 80","Anos 90","Baixe nosso App","Flashaback","Ouvintes da semana","Ouvir","Ouvir r\u00e1dio","R\u00e1dio","R\u00e1dio Planeta Saudade"],"articleSection":["OUVINTE DA SEMANA"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/03\/02\/a-radio-planeta-saudade-tem-a-alegria-de-celebrar-sua-presenca-em-audiencia-em-todos-os-estados-do-pais-conquistando-cada-vez-mais-ouvintes-apaixonados-pela-melhor-selecao-musical-das-decadas-de-70\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/03\/02\/a-radio-planeta-saudade-tem-a-alegria-de-celebrar-sua-presenca-em-audiencia-em-todos-os-estados-do-pais-conquistando-cada-vez-mais-ouvintes-apaixonados-pela-melhor-selecao-musical-das-decadas-de-70\/","url":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/03\/02\/a-radio-planeta-saudade-tem-a-alegria-de-celebrar-sua-presenca-em-audiencia-em-todos-os-estados-do-pais-conquistando-cada-vez-mais-ouvintes-apaixonados-pela-melhor-selecao-musical-das-decadas-de-70\/","name":"A R\u00e1dio Planeta Saudade tem a alegria de celebrar sua presen\u00e7a em audi\u00eancia em todos os estados do pa\u00eds, conquistando cada vez mais ouvintes apaixonados pela melhor sele\u00e7\u00e3o musical das d\u00e9cadas de 70, 80, 90 e 2000. - R\u00c1DIO PLANETA SAUDADE","isPartOf":{"@id":"https:\/\/radioplanetasaudade.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/03\/02\/a-radio-planeta-saudade-tem-a-alegria-de-celebrar-sua-presenca-em-audiencia-em-todos-os-estados-do-pais-conquistando-cada-vez-mais-ouvintes-apaixonados-pela-melhor-selecao-musical-das-decadas-de-70\/#primaryimage"},"image":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/03\/02\/a-radio-planeta-saudade-tem-a-alegria-de-celebrar-sua-presenca-em-audiencia-em-todos-os-estados-do-pais-conquistando-cada-vez-mais-ouvintes-apaixonados-pela-melhor-selecao-musical-das-decadas-de-70\/#primaryimage"},"thumbnailUrl":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2025\/03\/PERFEITO.png","datePublished":"2025-03-02T17:00:55+00:00","dateModified":"2025-03-02T17:00:57+00:00","breadcrumb":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/03\/02\/a-radio-planeta-saudade-tem-a-alegria-de-celebrar-sua-presenca-em-audiencia-em-todos-os-estados-do-pais-conquistando-cada-vez-mais-ouvintes-apaixonados-pela-melhor-selecao-musical-das-decadas-de-70\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/03\/02\/a-radio-planeta-saudade-tem-a-alegria-de-celebrar-sua-presenca-em-audiencia-em-todos-os-estados-do-pais-conquistando-cada-vez-mais-ouvintes-apaixonados-pela-melhor-selecao-musical-das-decadas-de-70\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/03\/02\/a-radio-planeta-saudade-tem-a-alegria-de-celebrar-sua-presenca-em-audiencia-em-todos-os-estados-do-pais-conquistando-cada-vez-mais-ouvintes-apaixonados-pela-melhor-selecao-musical-das-decadas-de-70\/#primaryimage","url":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2025\/03\/PERFEITO.png","contentUrl":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2025\/03\/PERFEITO.png","width":498,"height":485},{"@type":"BreadcrumbList","@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/03\/02\/a-radio-planeta-saudade-tem-a-alegria-de-celebrar-sua-presenca-em-audiencia-em-todos-os-estados-do-pais-conquistando-cada-vez-mais-ouvintes-apaixonados-pela-melhor-selecao-musical-das-decadas-de-70\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/radioplanetasaudade.com.br\/"},{"@type":"ListItem","position":2,"name":"A R\u00e1dio Planeta Saudade tem a alegria de celebrar sua presen\u00e7a em audi\u00eancia em todos os estados do pa\u00eds, conquistando cada vez mais ouvintes apaixonados pela melhor sele\u00e7\u00e3o musical das d\u00e9cadas de 70, 80, 90 e 2000."}]},{"@type":"WebSite","@id":"https:\/\/radioplanetasaudade.com.br\/#website","url":"https:\/\/radioplanetasaudade.com.br\/","name":"R\u00e1dio Planeta Saudade","description":"Relembrando grandes sucessos musicais e informando sobre os maiores artistas do mundo ou\u00e7a no seu celular.","publisher":{"@id":"https:\/\/radioplanetasaudade.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radioplanetasaudade.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/radioplanetasaudade.com.br\/#organization","name":"R\u00e1dio Planeta Saudade","url":"https:\/\/radioplanetasaudade.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radioplanetasaudade.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2023\/10\/capture-20230607-202153.png","contentUrl":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2023\/10\/capture-20230607-202153.png","width":1350,"height":358,"caption":"R\u00e1dio Planeta Saudade"},"image":{"@id":"https:\/\/radioplanetasaudade.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/radioplanetasaudade.com.br\/#\/schema\/person\/1a6f6fc0d987819324e7ed417a1a6581","name":"Planeta Saudade","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g","caption":"Planeta Saudade"},"sameAs":["https:\/\/radioplanetasaudade.com.br"],"url":"https:\/\/radioplanetasaudade.com.br\/index.php\/author\/wendelsantos4567\/"}]}},"_links":{"self":[{"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=3673"}],"version-history":[{"count":1,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3673\/revisions"}],"predecessor-version":[{"id":3675,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3673\/revisions\/3675"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/media\/3674"}],"wp:attachment":[{"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=3673"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=3673"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=3673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}