{"id":3983,"date":"2025-05-03T17:46:43","date_gmt":"2025-05-03T20:46:43","guid":{"rendered":"https:\/\/radioplanetasaudade.com.br\/?p=3983"},"modified":"2025-05-03T17:46:44","modified_gmt":"2025-05-03T20:46:44","slug":"sintonize-com-aquela-saudade-que-faz-bem-seu-ao-seu-coracao","status":"publish","type":"post","link":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/05\/03\/sintonize-com-aquela-saudade-que-faz-bem-seu-ao-seu-coracao\/","title":{"rendered":"Sintonize com aquela saudade que faz bem seu ao seu cora\u00e7\u00e3o!"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><em>Na R\u00e1dio Planeta Saudade, a viagem musical \u00e9 todo dia, toda hora \u2014 e o melhor: sem precisar de mala!<\/em><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"650\" height=\"646\" src=\"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2025\/05\/CLUBE-DA-INSONIA.jpg\" alt=\"\" class=\"wp-image-3984\" srcset=\"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2025\/05\/CLUBE-DA-INSONIA.jpg 650w, https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2025\/05\/CLUBE-DA-INSONIA-300x298.jpg 300w, https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2025\/05\/CLUBE-DA-INSONIA-150x150.jpg 150w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Aqui, a trilha sonora \u00e9 feita com amor, qualidade de verdade e aquele toque especial que s\u00f3 quem entende de boas lembran\u00e7as consegue dar.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dos passinhos animados dos anos 70 e 80 aos sucessos inesquec\u00edveis dos anos 90 e 2000, nossa sele\u00e7\u00e3o \u00e9 um verdadeiro t\u00fanel do tempo musical.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cada can\u00e7\u00e3o \u00e9 escolhida com carinho pra te fazer sorrir, dan\u00e7ar ou at\u00e9 soltar aquele \u201cnossa, essa m\u00fasica!\u201d com brilho nos olhos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/tf4\/1\/16\/2728.png\" alt=\"\u2728\"> <strong>E quem comanda esse show de emo\u00e7\u00f5es?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Wendel Santos<\/strong> e seu carisma que j\u00e1 vem com trilha sonora pr\u00f3pria;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ivy Costa<\/strong>, que transforma a tarde em um abra\u00e7o musical;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>L\u00e9o Campos<\/strong>, com energia de sobra pra levantar qualquer astral;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Cris Alves<\/strong>, trazendo poesia e boas vibes nas noites de s\u00e1bado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t57\/1\/16\/1f4f1.png\" alt=\"\ud83d\udcf1\"> <strong>Quer ouvir sua m\u00fasica favorita?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9 s\u00f3 pedir no site ou baixar nosso app na Play Store.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Agora, aumenta o som, chama a nostalgia e deixa a saudade fazer festa no cora\u00e7\u00e3o! <img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\udc83\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/tc7\/1\/16\/1f483.png\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\udd7a\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t97\/1\/16\/1f57a.png\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na R\u00e1dio Planeta Saudade, a viagem musical \u00e9 todo dia, toda hora \u2014 e o&#8230;<\/p>\n","protected":false},"author":1,"featured_media":3984,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[211],"tags":[119,118,120,121,117,561,562,116,99],"class_list":["post-3983","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-memes-da-planeta","tag-anos-70","tag-anos-80","tag-anos-90","tag-baixe-nosso-app","tag-flashaback","tag-ouvir","tag-ouvir-radio","tag-radio","tag-radio-planeta-saudade"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sintonize com aquela saudade que faz bem seu ao seu cora\u00e7\u00e3o! - R\u00c1DIO PLANETA SAUDADE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/05\/03\/sintonize-com-aquela-saudade-que-faz-bem-seu-ao-seu-coracao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sintonize com aquela saudade que faz bem seu ao seu cora\u00e7\u00e3o! - R\u00c1DIO PLANETA SAUDADE\" \/>\n<meta property=\"og:description\" content=\"Na R\u00e1dio Planeta Saudade, a viagem musical \u00e9 todo dia, toda hora \u2014 e o...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/05\/03\/sintonize-com-aquela-saudade-que-faz-bem-seu-ao-seu-coracao\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00c1DIO PLANETA SAUDADE\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-03T20:46:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-03T20:46:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2025\/05\/CLUBE-DA-INSONIA.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"650\" \/>\n\t<meta property=\"og:image:height\" content=\"646\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Planeta Saudade\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Planeta Saudade\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/05\\\/03\\\/sintonize-com-aquela-saudade-que-faz-bem-seu-ao-seu-coracao\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/05\\\/03\\\/sintonize-com-aquela-saudade-que-faz-bem-seu-ao-seu-coracao\\\/\"},\"author\":{\"name\":\"Planeta Saudade\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#\\\/schema\\\/person\\\/1a6f6fc0d987819324e7ed417a1a6581\"},\"headline\":\"Sintonize com aquela saudade que faz bem seu ao seu cora\u00e7\u00e3o!\",\"datePublished\":\"2025-05-03T20:46:43+00:00\",\"dateModified\":\"2025-05-03T20:46:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/05\\\/03\\\/sintonize-com-aquela-saudade-que-faz-bem-seu-ao-seu-coracao\\\/\"},\"wordCount\":190,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/05\\\/03\\\/sintonize-com-aquela-saudade-que-faz-bem-seu-ao-seu-coracao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/CLUBE-DA-INSONIA.jpg\",\"keywords\":[\"Anos 70\",\"Anos 80\",\"Anos 90\",\"Baixe nosso App\",\"Flashaback\",\"Ouvir\",\"Ouvir r\u00e1dio\",\"R\u00e1dio\",\"R\u00e1dio Planeta Saudade\"],\"articleSection\":[\"MEMES DA PLANETA\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/05\\\/03\\\/sintonize-com-aquela-saudade-que-faz-bem-seu-ao-seu-coracao\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/05\\\/03\\\/sintonize-com-aquela-saudade-que-faz-bem-seu-ao-seu-coracao\\\/\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/05\\\/03\\\/sintonize-com-aquela-saudade-que-faz-bem-seu-ao-seu-coracao\\\/\",\"name\":\"Sintonize com aquela saudade que faz bem seu ao seu cora\u00e7\u00e3o! - R\u00c1DIO PLANETA SAUDADE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/05\\\/03\\\/sintonize-com-aquela-saudade-que-faz-bem-seu-ao-seu-coracao\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/05\\\/03\\\/sintonize-com-aquela-saudade-que-faz-bem-seu-ao-seu-coracao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/CLUBE-DA-INSONIA.jpg\",\"datePublished\":\"2025-05-03T20:46:43+00:00\",\"dateModified\":\"2025-05-03T20:46:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/05\\\/03\\\/sintonize-com-aquela-saudade-que-faz-bem-seu-ao-seu-coracao\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/05\\\/03\\\/sintonize-com-aquela-saudade-que-faz-bem-seu-ao-seu-coracao\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/05\\\/03\\\/sintonize-com-aquela-saudade-que-faz-bem-seu-ao-seu-coracao\\\/#primaryimage\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/CLUBE-DA-INSONIA.jpg\",\"contentUrl\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/CLUBE-DA-INSONIA.jpg\",\"width\":650,\"height\":646},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/05\\\/03\\\/sintonize-com-aquela-saudade-que-faz-bem-seu-ao-seu-coracao\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sintonize com aquela saudade que faz bem seu ao seu cora\u00e7\u00e3o!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#website\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/\",\"name\":\"R\u00e1dio Planeta Saudade\",\"description\":\"Relembrando grandes sucessos musicais e informando sobre os maiores artistas do mundo ou\u00e7a no seu celular.\",\"publisher\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#organization\",\"name\":\"R\u00e1dio Planeta Saudade\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/capture-20230607-202153.png\",\"contentUrl\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/capture-20230607-202153.png\",\"width\":1350,\"height\":358,\"caption\":\"R\u00e1dio Planeta Saudade\"},\"image\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#\\\/schema\\\/person\\\/1a6f6fc0d987819324e7ed417a1a6581\",\"name\":\"Planeta Saudade\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g\",\"caption\":\"Planeta Saudade\"},\"sameAs\":[\"https:\\\/\\\/radioplanetasaudade.com.br\"],\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/author\\\/wendelsantos4567\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sintonize com aquela saudade que faz bem seu ao seu cora\u00e7\u00e3o! - R\u00c1DIO PLANETA SAUDADE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/05\/03\/sintonize-com-aquela-saudade-que-faz-bem-seu-ao-seu-coracao\/","og_locale":"pt_BR","og_type":"article","og_title":"Sintonize com aquela saudade que faz bem seu ao seu cora\u00e7\u00e3o! - R\u00c1DIO PLANETA SAUDADE","og_description":"Na R\u00e1dio Planeta Saudade, a viagem musical \u00e9 todo dia, toda hora \u2014 e o...","og_url":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/05\/03\/sintonize-com-aquela-saudade-que-faz-bem-seu-ao-seu-coracao\/","og_site_name":"R\u00c1DIO PLANETA SAUDADE","article_published_time":"2025-05-03T20:46:43+00:00","article_modified_time":"2025-05-03T20:46:44+00:00","og_image":[{"width":650,"height":646,"url":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2025\/05\/CLUBE-DA-INSONIA.jpg","type":"image\/jpeg"}],"author":"Planeta Saudade","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Planeta Saudade","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/05\/03\/sintonize-com-aquela-saudade-que-faz-bem-seu-ao-seu-coracao\/#article","isPartOf":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/05\/03\/sintonize-com-aquela-saudade-que-faz-bem-seu-ao-seu-coracao\/"},"author":{"name":"Planeta Saudade","@id":"https:\/\/radioplanetasaudade.com.br\/#\/schema\/person\/1a6f6fc0d987819324e7ed417a1a6581"},"headline":"Sintonize com aquela saudade que faz bem seu ao seu cora\u00e7\u00e3o!","datePublished":"2025-05-03T20:46:43+00:00","dateModified":"2025-05-03T20:46:44+00:00","mainEntityOfPage":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/05\/03\/sintonize-com-aquela-saudade-que-faz-bem-seu-ao-seu-coracao\/"},"wordCount":190,"commentCount":0,"publisher":{"@id":"https:\/\/radioplanetasaudade.com.br\/#organization"},"image":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/05\/03\/sintonize-com-aquela-saudade-que-faz-bem-seu-ao-seu-coracao\/#primaryimage"},"thumbnailUrl":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2025\/05\/CLUBE-DA-INSONIA.jpg","keywords":["Anos 70","Anos 80","Anos 90","Baixe nosso App","Flashaback","Ouvir","Ouvir r\u00e1dio","R\u00e1dio","R\u00e1dio Planeta Saudade"],"articleSection":["MEMES DA PLANETA"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/05\/03\/sintonize-com-aquela-saudade-que-faz-bem-seu-ao-seu-coracao\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/05\/03\/sintonize-com-aquela-saudade-que-faz-bem-seu-ao-seu-coracao\/","url":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/05\/03\/sintonize-com-aquela-saudade-que-faz-bem-seu-ao-seu-coracao\/","name":"Sintonize com aquela saudade que faz bem seu ao seu cora\u00e7\u00e3o! - R\u00c1DIO PLANETA SAUDADE","isPartOf":{"@id":"https:\/\/radioplanetasaudade.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/05\/03\/sintonize-com-aquela-saudade-que-faz-bem-seu-ao-seu-coracao\/#primaryimage"},"image":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/05\/03\/sintonize-com-aquela-saudade-que-faz-bem-seu-ao-seu-coracao\/#primaryimage"},"thumbnailUrl":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2025\/05\/CLUBE-DA-INSONIA.jpg","datePublished":"2025-05-03T20:46:43+00:00","dateModified":"2025-05-03T20:46:44+00:00","breadcrumb":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/05\/03\/sintonize-com-aquela-saudade-que-faz-bem-seu-ao-seu-coracao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/05\/03\/sintonize-com-aquela-saudade-que-faz-bem-seu-ao-seu-coracao\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/05\/03\/sintonize-com-aquela-saudade-que-faz-bem-seu-ao-seu-coracao\/#primaryimage","url":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2025\/05\/CLUBE-DA-INSONIA.jpg","contentUrl":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2025\/05\/CLUBE-DA-INSONIA.jpg","width":650,"height":646},{"@type":"BreadcrumbList","@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/05\/03\/sintonize-com-aquela-saudade-que-faz-bem-seu-ao-seu-coracao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/radioplanetasaudade.com.br\/"},{"@type":"ListItem","position":2,"name":"Sintonize com aquela saudade que faz bem seu ao seu cora\u00e7\u00e3o!"}]},{"@type":"WebSite","@id":"https:\/\/radioplanetasaudade.com.br\/#website","url":"https:\/\/radioplanetasaudade.com.br\/","name":"R\u00e1dio Planeta Saudade","description":"Relembrando grandes sucessos musicais e informando sobre os maiores artistas do mundo ou\u00e7a no seu celular.","publisher":{"@id":"https:\/\/radioplanetasaudade.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radioplanetasaudade.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/radioplanetasaudade.com.br\/#organization","name":"R\u00e1dio Planeta Saudade","url":"https:\/\/radioplanetasaudade.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radioplanetasaudade.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2023\/10\/capture-20230607-202153.png","contentUrl":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2023\/10\/capture-20230607-202153.png","width":1350,"height":358,"caption":"R\u00e1dio Planeta Saudade"},"image":{"@id":"https:\/\/radioplanetasaudade.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/radioplanetasaudade.com.br\/#\/schema\/person\/1a6f6fc0d987819324e7ed417a1a6581","name":"Planeta Saudade","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g","caption":"Planeta Saudade"},"sameAs":["https:\/\/radioplanetasaudade.com.br"],"url":"https:\/\/radioplanetasaudade.com.br\/index.php\/author\/wendelsantos4567\/"}]}},"_links":{"self":[{"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3983","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=3983"}],"version-history":[{"count":1,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3983\/revisions"}],"predecessor-version":[{"id":3985,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3983\/revisions\/3985"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/media\/3984"}],"wp:attachment":[{"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=3983"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=3983"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=3983"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}