{"id":4179,"date":"2025-06-05T16:36:13","date_gmt":"2025-06-05T19:36:13","guid":{"rendered":"https:\/\/radioplanetasaudade.com.br\/?p=4179"},"modified":"2025-06-05T16:44:28","modified_gmt":"2025-06-05T19:44:28","slug":"hoje-celebramos-os-69-anos-de-kenny-g-e-os-81-anos-de-wanderlea-dois-icones-que-marcaram-a-musica-mundial-e-brasileira","status":"publish","type":"post","link":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/06\/05\/hoje-celebramos-os-69-anos-de-kenny-g-e-os-81-anos-de-wanderlea-dois-icones-que-marcaram-a-musica-mundial-e-brasileira\/","title":{"rendered":"Hoje celebramos os 69 anos de Kenny G e os 81 anos de Wanderl\u00e9a, dois \u00edcones que marcaram a m\u00fasica mundial e brasileira."},"content":{"rendered":"\n<figure class=\"wp-block-image aligncenter size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"488\" height=\"486\" src=\"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2025\/06\/capture-20250605-163701.png\" alt=\"\" class=\"wp-image-4182\" srcset=\"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2025\/06\/capture-20250605-163701.png 488w, https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2025\/06\/capture-20250605-163701-300x300.png 300w, https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2025\/06\/capture-20250605-163701-150x150.png 150w\" sizes=\"(max-width: 488px) 100vw, 488px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><img decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83c\udfb7\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/ta0\/1\/16\/1f3b7.png\"> K<a><\/a>enny G \u00e9 o saxofonista mais vendido da hist\u00f3ria, com mais de 75 milh\u00f5es de discos vendidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seu \u00e1lbum &#8220;Breathless&#8221; (1992) \u00e9 o mais vendido de m\u00fasica instrumental de todos os tempos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com influ\u00eancias do jazz e da m\u00fasica pop, Kenny G conquistou f\u00e3s ao redor do mundo e recebeu diversos pr\u00eamios, incluindo um Grammy.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sua t\u00e9cnica refinada e melodias suaves o tornaram uma refer\u00eancia no g\u00eanero smooth jazz.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83c\udfa4\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t7e\/1\/16\/1f3a4.png\"> Wanderl\u00e9a, a eterna &#8220;Ternurinha&#8221;, foi uma das estrelas da Jovem Guarda, movimento que revolucionou a m\u00fasica brasileira nos anos 60.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com sua voz marcante e presen\u00e7a de palco, conquistou o p\u00fablico jovem da \u00e9poca.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ap\u00f3s a Jovem Guarda, continuou sua carreira com sucesso, explorando diversos estilos musicais e lan\u00e7ando \u00e1lbuns aclamados. Recentemente, lan\u00e7ou o \u00e1lbum &#8220;Wanderl\u00e9a Canta Choros&#8221;, mostrando sua versatilidade art\u00edstica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83c\udf89\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t8c\/1\/16\/1f389.png\"> Parab\u00e9ns a ambos por suas trajet\u00f3rias brilhantes! <img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83c\udfb6\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t1f\/1\/16\/1f3b6.png\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.facebook.com\/hashtag\/kennyg69?__eep__=6&amp;__cft__[0]=AZVTb4hd0NtOsJscHqeJfUeoKHUW7lyY2qgKN_j4b2wgaSMDkMlfglG9H4qAJTTslN8TbVEAfQOPE6FoAPkn6ERGBNFIpXzJKYmXNTvcoWBWx1iP8cLTFo0DtuEr3tL6aQkxqr3vJf7bzmAGIcX9RN8x&amp;__tn__=*NK-R\">#KennyG69<\/a><a href=\"https:\/\/www.facebook.com\/hashtag\/wanderl%C3%A9a81?__eep__=6&amp;__cft__[0]=AZVTb4hd0NtOsJscHqeJfUeoKHUW7lyY2qgKN_j4b2wgaSMDkMlfglG9H4qAJTTslN8TbVEAfQOPE6FoAPkn6ERGBNFIpXzJKYmXNTvcoWBWx1iP8cLTFo0DtuEr3tL6aQkxqr3vJf7bzmAGIcX9RN8x&amp;__tn__=*NK-R\">#Wanderl\u00e9a81<\/a><a href=\"https:\/\/www.facebook.com\/hashtag\/m%C3%BAsicaqueinspira?__eep__=6&amp;__cft__[0]=AZVTb4hd0NtOsJscHqeJfUeoKHUW7lyY2qgKN_j4b2wgaSMDkMlfglG9H4qAJTTslN8TbVEAfQOPE6FoAPkn6ERGBNFIpXzJKYmXNTvcoWBWx1iP8cLTFo0DtuEr3tL6aQkxqr3vJf7bzmAGIcX9RN8x&amp;__tn__=*NK-R\">#M\u00fasicaQueInspira<\/a><a href=\"https:\/\/www.facebook.com\/hashtag\/lendasmusicais?__eep__=6&amp;__cft__[0]=AZVTb4hd0NtOsJscHqeJfUeoKHUW7lyY2qgKN_j4b2wgaSMDkMlfglG9H4qAJTTslN8TbVEAfQOPE6FoAPkn6ERGBNFIpXzJKYmXNTvcoWBWx1iP8cLTFo0DtuEr3tL6aQkxqr3vJf7bzmAGIcX9RN8x&amp;__tn__=*NK-R\">#LendasMusicais<\/a><a href=\"https:\/\/www.facebook.com\/hashtag\/jazz?__eep__=6&amp;__cft__[0]=AZVTb4hd0NtOsJscHqeJfUeoKHUW7lyY2qgKN_j4b2wgaSMDkMlfglG9H4qAJTTslN8TbVEAfQOPE6FoAPkn6ERGBNFIpXzJKYmXNTvcoWBWx1iP8cLTFo0DtuEr3tL6aQkxqr3vJf7bzmAGIcX9RN8x&amp;__tn__=*NK-R\">#Jazz<\/a><a href=\"https:\/\/www.facebook.com\/hashtag\/mpb?__eep__=6&amp;__cft__[0]=AZVTb4hd0NtOsJscHqeJfUeoKHUW7lyY2qgKN_j4b2wgaSMDkMlfglG9H4qAJTTslN8TbVEAfQOPE6FoAPkn6ERGBNFIpXzJKYmXNTvcoWBWx1iP8cLTFo0DtuEr3tL6aQkxqr3vJf7bzmAGIcX9RN8x&amp;__tn__=*NK-R\">#MPB<\/a><a href=\"https:\/\/www.facebook.com\/hashtag\/jovemguarda?__eep__=6&amp;__cft__[0]=AZVTb4hd0NtOsJscHqeJfUeoKHUW7lyY2qgKN_j4b2wgaSMDkMlfglG9H4qAJTTslN8TbVEAfQOPE6FoAPkn6ERGBNFIpXzJKYmXNTvcoWBWx1iP8cLTFo0DtuEr3tL6aQkxqr3vJf7bzmAGIcX9RN8x&amp;__tn__=*NK-R\">#JovemGuarda<\/a><a href=\"https:\/\/www.facebook.com\/hashtag\/anivers%C3%A1riomusical?__eep__=6&amp;__cft__[0]=AZVTb4hd0NtOsJscHqeJfUeoKHUW7lyY2qgKN_j4b2wgaSMDkMlfglG9H4qAJTTslN8TbVEAfQOPE6FoAPkn6ERGBNFIpXzJKYmXNTvcoWBWx1iP8cLTFo0DtuEr3tL6aQkxqr3vJf7bzmAGIcX9RN8x&amp;__tn__=*NK-R\">#Anivers\u00e1rioMusical<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kenny G \u00e9 o saxofonista mais vendido da hist\u00f3ria, com mais de 75 milh\u00f5es de&#8230;<\/p>\n","protected":false},"author":1,"featured_media":4184,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1229],"tags":[119,118,120,121,117,1936,561,562,1231,116,99,1937],"class_list":["post-4179","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artistas-aniversariantes","tag-anos-70","tag-anos-80","tag-anos-90","tag-baixe-nosso-app","tag-flashaback","tag-kenny-g-69-anos","tag-ouvir","tag-ouvir-radio","tag-parabens","tag-radio","tag-radio-planeta-saudade","tag-wanderlea-81-anos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hoje celebramos os 69 anos de Kenny G e os 81 anos de Wanderl\u00e9a, dois \u00edcones que marcaram a m\u00fasica mundial e brasileira. - R\u00c1DIO PLANETA SAUDADE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/06\/05\/hoje-celebramos-os-69-anos-de-kenny-g-e-os-81-anos-de-wanderlea-dois-icones-que-marcaram-a-musica-mundial-e-brasileira\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hoje celebramos os 69 anos de Kenny G e os 81 anos de Wanderl\u00e9a, dois \u00edcones que marcaram a m\u00fasica mundial e brasileira. - R\u00c1DIO PLANETA SAUDADE\" \/>\n<meta property=\"og:description\" content=\"Kenny G \u00e9 o saxofonista mais vendido da hist\u00f3ria, com mais de 75 milh\u00f5es de...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/06\/05\/hoje-celebramos-os-69-anos-de-kenny-g-e-os-81-anos-de-wanderlea-dois-icones-que-marcaram-a-musica-mundial-e-brasileira\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00c1DIO PLANETA SAUDADE\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-05T19:36:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-05T19:44:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2025\/06\/capture-20250605-163701-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"488\" \/>\n\t<meta property=\"og:image:height\" content=\"486\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Planeta Saudade\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Planeta Saudade\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/06\\\/05\\\/hoje-celebramos-os-69-anos-de-kenny-g-e-os-81-anos-de-wanderlea-dois-icones-que-marcaram-a-musica-mundial-e-brasileira\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/06\\\/05\\\/hoje-celebramos-os-69-anos-de-kenny-g-e-os-81-anos-de-wanderlea-dois-icones-que-marcaram-a-musica-mundial-e-brasileira\\\/\"},\"author\":{\"name\":\"Planeta Saudade\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#\\\/schema\\\/person\\\/1a6f6fc0d987819324e7ed417a1a6581\"},\"headline\":\"Hoje celebramos os 69 anos de Kenny G e os 81 anos de Wanderl\u00e9a, dois \u00edcones que marcaram a m\u00fasica mundial e brasileira.\",\"datePublished\":\"2025-06-05T19:36:13+00:00\",\"dateModified\":\"2025-06-05T19:44:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/06\\\/05\\\/hoje-celebramos-os-69-anos-de-kenny-g-e-os-81-anos-de-wanderlea-dois-icones-que-marcaram-a-musica-mundial-e-brasileira\\\/\"},\"wordCount\":189,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/06\\\/05\\\/hoje-celebramos-os-69-anos-de-kenny-g-e-os-81-anos-de-wanderlea-dois-icones-que-marcaram-a-musica-mundial-e-brasileira\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/capture-20250605-163701-1.png\",\"keywords\":[\"Anos 70\",\"Anos 80\",\"Anos 90\",\"Baixe nosso App\",\"Flashaback\",\"Kenny G 69 anos\",\"Ouvir\",\"Ouvir r\u00e1dio\",\"Parab\u00e9ns\",\"R\u00e1dio\",\"R\u00e1dio Planeta Saudade\",\"Wanderl\u00e9a 81 anos\"],\"articleSection\":[\"ARTISTAS ANIVERSARIANTES\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/06\\\/05\\\/hoje-celebramos-os-69-anos-de-kenny-g-e-os-81-anos-de-wanderlea-dois-icones-que-marcaram-a-musica-mundial-e-brasileira\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/06\\\/05\\\/hoje-celebramos-os-69-anos-de-kenny-g-e-os-81-anos-de-wanderlea-dois-icones-que-marcaram-a-musica-mundial-e-brasileira\\\/\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/06\\\/05\\\/hoje-celebramos-os-69-anos-de-kenny-g-e-os-81-anos-de-wanderlea-dois-icones-que-marcaram-a-musica-mundial-e-brasileira\\\/\",\"name\":\"Hoje celebramos os 69 anos de Kenny G e os 81 anos de Wanderl\u00e9a, dois \u00edcones que marcaram a m\u00fasica mundial e brasileira. - R\u00c1DIO PLANETA SAUDADE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/06\\\/05\\\/hoje-celebramos-os-69-anos-de-kenny-g-e-os-81-anos-de-wanderlea-dois-icones-que-marcaram-a-musica-mundial-e-brasileira\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/06\\\/05\\\/hoje-celebramos-os-69-anos-de-kenny-g-e-os-81-anos-de-wanderlea-dois-icones-que-marcaram-a-musica-mundial-e-brasileira\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/capture-20250605-163701-1.png\",\"datePublished\":\"2025-06-05T19:36:13+00:00\",\"dateModified\":\"2025-06-05T19:44:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/06\\\/05\\\/hoje-celebramos-os-69-anos-de-kenny-g-e-os-81-anos-de-wanderlea-dois-icones-que-marcaram-a-musica-mundial-e-brasileira\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/06\\\/05\\\/hoje-celebramos-os-69-anos-de-kenny-g-e-os-81-anos-de-wanderlea-dois-icones-que-marcaram-a-musica-mundial-e-brasileira\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/06\\\/05\\\/hoje-celebramos-os-69-anos-de-kenny-g-e-os-81-anos-de-wanderlea-dois-icones-que-marcaram-a-musica-mundial-e-brasileira\\\/#primaryimage\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/capture-20250605-163701-1.png\",\"contentUrl\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/capture-20250605-163701-1.png\",\"width\":488,\"height\":486},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/06\\\/05\\\/hoje-celebramos-os-69-anos-de-kenny-g-e-os-81-anos-de-wanderlea-dois-icones-que-marcaram-a-musica-mundial-e-brasileira\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hoje celebramos os 69 anos de Kenny G e os 81 anos de Wanderl\u00e9a, dois \u00edcones que marcaram a m\u00fasica mundial e brasileira.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#website\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/\",\"name\":\"R\u00e1dio Planeta Saudade\",\"description\":\"Relembrando grandes sucessos musicais e informando sobre os maiores artistas do mundo ou\u00e7a no seu celular.\",\"publisher\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#organization\",\"name\":\"R\u00e1dio Planeta Saudade\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/capture-20230607-202153.png\",\"contentUrl\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/capture-20230607-202153.png\",\"width\":1350,\"height\":358,\"caption\":\"R\u00e1dio Planeta Saudade\"},\"image\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#\\\/schema\\\/person\\\/1a6f6fc0d987819324e7ed417a1a6581\",\"name\":\"Planeta Saudade\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g\",\"caption\":\"Planeta Saudade\"},\"sameAs\":[\"https:\\\/\\\/radioplanetasaudade.com.br\"],\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/author\\\/wendelsantos4567\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hoje celebramos os 69 anos de Kenny G e os 81 anos de Wanderl\u00e9a, dois \u00edcones que marcaram a m\u00fasica mundial e brasileira. - R\u00c1DIO PLANETA SAUDADE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/06\/05\/hoje-celebramos-os-69-anos-de-kenny-g-e-os-81-anos-de-wanderlea-dois-icones-que-marcaram-a-musica-mundial-e-brasileira\/","og_locale":"pt_BR","og_type":"article","og_title":"Hoje celebramos os 69 anos de Kenny G e os 81 anos de Wanderl\u00e9a, dois \u00edcones que marcaram a m\u00fasica mundial e brasileira. - R\u00c1DIO PLANETA SAUDADE","og_description":"Kenny G \u00e9 o saxofonista mais vendido da hist\u00f3ria, com mais de 75 milh\u00f5es de...","og_url":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/06\/05\/hoje-celebramos-os-69-anos-de-kenny-g-e-os-81-anos-de-wanderlea-dois-icones-que-marcaram-a-musica-mundial-e-brasileira\/","og_site_name":"R\u00c1DIO PLANETA SAUDADE","article_published_time":"2025-06-05T19:36:13+00:00","article_modified_time":"2025-06-05T19:44:28+00:00","og_image":[{"width":488,"height":486,"url":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2025\/06\/capture-20250605-163701-1.png","type":"image\/png"}],"author":"Planeta Saudade","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Planeta Saudade","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/06\/05\/hoje-celebramos-os-69-anos-de-kenny-g-e-os-81-anos-de-wanderlea-dois-icones-que-marcaram-a-musica-mundial-e-brasileira\/#article","isPartOf":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/06\/05\/hoje-celebramos-os-69-anos-de-kenny-g-e-os-81-anos-de-wanderlea-dois-icones-que-marcaram-a-musica-mundial-e-brasileira\/"},"author":{"name":"Planeta Saudade","@id":"https:\/\/radioplanetasaudade.com.br\/#\/schema\/person\/1a6f6fc0d987819324e7ed417a1a6581"},"headline":"Hoje celebramos os 69 anos de Kenny G e os 81 anos de Wanderl\u00e9a, dois \u00edcones que marcaram a m\u00fasica mundial e brasileira.","datePublished":"2025-06-05T19:36:13+00:00","dateModified":"2025-06-05T19:44:28+00:00","mainEntityOfPage":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/06\/05\/hoje-celebramos-os-69-anos-de-kenny-g-e-os-81-anos-de-wanderlea-dois-icones-que-marcaram-a-musica-mundial-e-brasileira\/"},"wordCount":189,"commentCount":0,"publisher":{"@id":"https:\/\/radioplanetasaudade.com.br\/#organization"},"image":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/06\/05\/hoje-celebramos-os-69-anos-de-kenny-g-e-os-81-anos-de-wanderlea-dois-icones-que-marcaram-a-musica-mundial-e-brasileira\/#primaryimage"},"thumbnailUrl":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2025\/06\/capture-20250605-163701-1.png","keywords":["Anos 70","Anos 80","Anos 90","Baixe nosso App","Flashaback","Kenny G 69 anos","Ouvir","Ouvir r\u00e1dio","Parab\u00e9ns","R\u00e1dio","R\u00e1dio Planeta Saudade","Wanderl\u00e9a 81 anos"],"articleSection":["ARTISTAS ANIVERSARIANTES"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/06\/05\/hoje-celebramos-os-69-anos-de-kenny-g-e-os-81-anos-de-wanderlea-dois-icones-que-marcaram-a-musica-mundial-e-brasileira\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/06\/05\/hoje-celebramos-os-69-anos-de-kenny-g-e-os-81-anos-de-wanderlea-dois-icones-que-marcaram-a-musica-mundial-e-brasileira\/","url":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/06\/05\/hoje-celebramos-os-69-anos-de-kenny-g-e-os-81-anos-de-wanderlea-dois-icones-que-marcaram-a-musica-mundial-e-brasileira\/","name":"Hoje celebramos os 69 anos de Kenny G e os 81 anos de Wanderl\u00e9a, dois \u00edcones que marcaram a m\u00fasica mundial e brasileira. - R\u00c1DIO PLANETA SAUDADE","isPartOf":{"@id":"https:\/\/radioplanetasaudade.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/06\/05\/hoje-celebramos-os-69-anos-de-kenny-g-e-os-81-anos-de-wanderlea-dois-icones-que-marcaram-a-musica-mundial-e-brasileira\/#primaryimage"},"image":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/06\/05\/hoje-celebramos-os-69-anos-de-kenny-g-e-os-81-anos-de-wanderlea-dois-icones-que-marcaram-a-musica-mundial-e-brasileira\/#primaryimage"},"thumbnailUrl":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2025\/06\/capture-20250605-163701-1.png","datePublished":"2025-06-05T19:36:13+00:00","dateModified":"2025-06-05T19:44:28+00:00","breadcrumb":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/06\/05\/hoje-celebramos-os-69-anos-de-kenny-g-e-os-81-anos-de-wanderlea-dois-icones-que-marcaram-a-musica-mundial-e-brasileira\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/06\/05\/hoje-celebramos-os-69-anos-de-kenny-g-e-os-81-anos-de-wanderlea-dois-icones-que-marcaram-a-musica-mundial-e-brasileira\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/06\/05\/hoje-celebramos-os-69-anos-de-kenny-g-e-os-81-anos-de-wanderlea-dois-icones-que-marcaram-a-musica-mundial-e-brasileira\/#primaryimage","url":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2025\/06\/capture-20250605-163701-1.png","contentUrl":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2025\/06\/capture-20250605-163701-1.png","width":488,"height":486},{"@type":"BreadcrumbList","@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/06\/05\/hoje-celebramos-os-69-anos-de-kenny-g-e-os-81-anos-de-wanderlea-dois-icones-que-marcaram-a-musica-mundial-e-brasileira\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/radioplanetasaudade.com.br\/"},{"@type":"ListItem","position":2,"name":"Hoje celebramos os 69 anos de Kenny G e os 81 anos de Wanderl\u00e9a, dois \u00edcones que marcaram a m\u00fasica mundial e brasileira."}]},{"@type":"WebSite","@id":"https:\/\/radioplanetasaudade.com.br\/#website","url":"https:\/\/radioplanetasaudade.com.br\/","name":"R\u00e1dio Planeta Saudade","description":"Relembrando grandes sucessos musicais e informando sobre os maiores artistas do mundo ou\u00e7a no seu celular.","publisher":{"@id":"https:\/\/radioplanetasaudade.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radioplanetasaudade.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/radioplanetasaudade.com.br\/#organization","name":"R\u00e1dio Planeta Saudade","url":"https:\/\/radioplanetasaudade.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radioplanetasaudade.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2023\/10\/capture-20230607-202153.png","contentUrl":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2023\/10\/capture-20230607-202153.png","width":1350,"height":358,"caption":"R\u00e1dio Planeta Saudade"},"image":{"@id":"https:\/\/radioplanetasaudade.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/radioplanetasaudade.com.br\/#\/schema\/person\/1a6f6fc0d987819324e7ed417a1a6581","name":"Planeta Saudade","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g","caption":"Planeta Saudade"},"sameAs":["https:\/\/radioplanetasaudade.com.br"],"url":"https:\/\/radioplanetasaudade.com.br\/index.php\/author\/wendelsantos4567\/"}]}},"_links":{"self":[{"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=4179"}],"version-history":[{"count":2,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4179\/revisions"}],"predecessor-version":[{"id":4183,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4179\/revisions\/4183"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/media\/4184"}],"wp:attachment":[{"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=4179"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=4179"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=4179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}