{"id":4185,"date":"2025-06-05T19:47:16","date_gmt":"2025-06-05T22:47:16","guid":{"rendered":"https:\/\/radioplanetasaudade.com.br\/?p=4185"},"modified":"2025-06-05T19:47:18","modified_gmt":"2025-06-05T22:47:18","slug":"a-partir-das-22h-prepare-o-coracao-vem-ai-o-programa-mais-romantico-do-fim-de-noite-e-o-love-night-na-companhia-envolvente-e-carismatica-de-wendel-santos-que-ha-5-anos-encanta-os-coracoes-apa","status":"publish","type":"post","link":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/06\/05\/a-partir-das-22h-prepare-o-coracao-vem-ai-o-programa-mais-romantico-do-fim-de-noite-e-o-love-night-na-companhia-envolvente-e-carismatica-de-wendel-santos-que-ha-5-anos-encanta-os-coracoes-apa\/","title":{"rendered":"A partir das 22h, prepare o cora\u00e7\u00e3o&#8230;  Vem a\u00ed o programa mais rom\u00e2ntico do fim de noite! \u00c9 o Love Night, na companhia envolvente e carism\u00e1tica de Wendel Santos , que h\u00e1 5 anos encanta os cora\u00e7\u00f5es apaixonados na l\u00edder de audi\u00eancia: R\u00e1dio Planeta Saudade ."},"content":{"rendered":"\n<figure class=\"wp-block-image aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"1011\" src=\"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2025\/06\/BOA-TARDE-PLANETA-Copia-1024x1011.jpg\" alt=\"\" class=\"wp-image-4186\" srcset=\"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2025\/06\/BOA-TARDE-PLANETA-Copia-1024x1011.jpg 1024w, https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2025\/06\/BOA-TARDE-PLANETA-Copia-300x296.jpg 300w, https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2025\/06\/BOA-TARDE-PLANETA-Copia-768x759.jpg 768w, https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2025\/06\/BOA-TARDE-PLANETA-Copia-1536x1517.jpg 1536w, https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2025\/06\/BOA-TARDE-PLANETA-Copia-2048x2023.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Com mensagens tocantes, m\u00fasicas inesquec\u00edveis <img decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83c\udfb6\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t1f\/1\/16\/1f3b6.png\"> e aquela vibe perfeita pra curtir a dois <img decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\udc8f\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t7a\/1\/16\/1f48f.png\"> ou recordar um grande amor <img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\udc8c\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/tf7\/1\/16\/1f48c.png\">, o Love Night \u00e9 o ref\u00fagio dos cora\u00e7\u00f5es sens\u00edveis&#8230; <img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83e\udd40\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/td\/1\/16\/1f940.png\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83c\udf39\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t71\/1\/16\/1f339.png\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\udc98\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/teb\/1\/16\/1f498.png\"> Deixe-se levar pela emo\u00e7\u00e3o, pela saudade e pelo amor que est\u00e1 no ar&#8230;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\udd6f\ufe0f\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t7d\/1\/16\/1f56f.png\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83c\udf1b\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/tdc\/1\/16\/1f31b.png\">Sintonize, se apaixone e viva essa magia com a gente&#8230;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.facebook.com\/hashtag\/lovenight?__eep__=6&amp;__cft__[0]=AZVQUKi8fRfWudKQKkax-RYBHu7ZoDCor17j-BoGPR6VqW4xmddBHJ2qo_yzkqugbh2C2v5_Uvr4BoxMya6qQ1gz9Z2suB5bi8WTTPMpZk2kng&amp;__tn__=*NK-R\">#LoveNight<\/a><a href=\"https:\/\/www.facebook.com\/hashtag\/wendelsantos?__eep__=6&amp;__cft__[0]=AZVQUKi8fRfWudKQKkax-RYBHu7ZoDCor17j-BoGPR6VqW4xmddBHJ2qo_yzkqugbh2C2v5_Uvr4BoxMya6qQ1gz9Z2suB5bi8WTTPMpZk2kng&amp;__tn__=*NK-R\">#WendelSantos<\/a><a href=\"https:\/\/www.facebook.com\/hashtag\/romancenoar?__eep__=6&amp;__cft__[0]=AZVQUKi8fRfWudKQKkax-RYBHu7ZoDCor17j-BoGPR6VqW4xmddBHJ2qo_yzkqugbh2C2v5_Uvr4BoxMya6qQ1gz9Z2suB5bi8WTTPMpZk2kng&amp;__tn__=*NK-R\">#RomanceNoAr<\/a><a href=\"https:\/\/www.facebook.com\/hashtag\/planetasaudade?__eep__=6&amp;__cft__[0]=AZVQUKi8fRfWudKQKkax-RYBHu7ZoDCor17j-BoGPR6VqW4xmddBHJ2qo_yzkqugbh2C2v5_Uvr4BoxMya6qQ1gz9Z2suB5bi8WTTPMpZk2kng&amp;__tn__=*NK-R\">#PlanetaSaudade<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.facebook.com\/hashtag\/topdanoite?__eep__=6&amp;__cft__[0]=AZVQUKi8fRfWudKQKkax-RYBHu7ZoDCor17j-BoGPR6VqW4xmddBHJ2qo_yzkqugbh2C2v5_Uvr4BoxMya6qQ1gz9Z2suB5bi8WTTPMpZk2kng&amp;__tn__=*NK-R\">#TopDaNoite<\/a><a href=\"https:\/\/www.facebook.com\/hashtag\/amorsemfim?__eep__=6&amp;__cft__[0]=AZVQUKi8fRfWudKQKkax-RYBHu7ZoDCor17j-BoGPR6VqW4xmddBHJ2qo_yzkqugbh2C2v5_Uvr4BoxMya6qQ1gz9Z2suB5bi8WTTPMpZk2kng&amp;__tn__=*NK-R\">#AmorSemFim<\/a><a href=\"https:\/\/www.facebook.com\/hashtag\/saudadeboa?__eep__=6&amp;__cft__[0]=AZVQUKi8fRfWudKQKkax-RYBHu7ZoDCor17j-BoGPR6VqW4xmddBHJ2qo_yzkqugbh2C2v5_Uvr4BoxMya6qQ1gz9Z2suB5bi8WTTPMpZk2kng&amp;__tn__=*NK-R\">#SaudadeBoa<\/a><a href=\"https:\/\/www.facebook.com\/hashtag\/m%C3%BAsicasquemarcam?__eep__=6&amp;__cft__[0]=AZVQUKi8fRfWudKQKkax-RYBHu7ZoDCor17j-BoGPR6VqW4xmddBHJ2qo_yzkqugbh2C2v5_Uvr4BoxMya6qQ1gz9Z2suB5bi8WTTPMpZk2kng&amp;__tn__=*NK-R\">#M\u00fasicasQueMarcam<\/a><a href=\"https:\/\/www.facebook.com\/hashtag\/cora%C3%A7%C3%A3oapaixonado?__eep__=6&amp;__cft__[0]=AZVQUKi8fRfWudKQKkax-RYBHu7ZoDCor17j-BoGPR6VqW4xmddBHJ2qo_yzkqugbh2C2v5_Uvr4BoxMya6qQ1gz9Z2suB5bi8WTTPMpZk2kng&amp;__tn__=*NK-R\">#Cora\u00e7\u00e3oApaixonado<\/a><a href=\"https:\/\/www.facebook.com\/hashtag\/programacampe%C3%A3o?__eep__=6&amp;__cft__[0]=AZVQUKi8fRfWudKQKkax-RYBHu7ZoDCor17j-BoGPR6VqW4xmddBHJ2qo_yzkqugbh2C2v5_Uvr4BoxMya6qQ1gz9Z2suB5bi8WTTPMpZk2kng&amp;__tn__=*NK-R\">#ProgramaCampe\u00e3o<\/a><a href=\"https:\/\/www.facebook.com\/hashtag\/noiterom%C3%A2ntica?__eep__=6&amp;__cft__[0]=AZVQUKi8fRfWudKQKkax-RYBHu7ZoDCor17j-BoGPR6VqW4xmddBHJ2qo_yzkqugbh2C2v5_Uvr4BoxMya6qQ1gz9Z2suB5bi8WTTPMpZk2kng&amp;__tn__=*NK-R\">#NoiteRom\u00e2ntica<\/a><a href=\"https:\/\/www.facebook.com\/hashtag\/r%C3%A1dio%C3%A9amor?__eep__=6&amp;__cft__[0]=AZVQUKi8fRfWudKQKkax-RYBHu7ZoDCor17j-BoGPR6VqW4xmddBHJ2qo_yzkqugbh2C2v5_Uvr4BoxMya6qQ1gz9Z2suB5bi8WTTPMpZk2kng&amp;__tn__=*NK-R\">#R\u00e1dio\u00c9Amor<\/a><a href=\"https:\/\/www.facebook.com\/hashtag\/noitedosamantes?__eep__=6&amp;__cft__[0]=AZVQUKi8fRfWudKQKkax-RYBHu7ZoDCor17j-BoGPR6VqW4xmddBHJ2qo_yzkqugbh2C2v5_Uvr4BoxMya6qQ1gz9Z2suB5bi8WTTPMpZk2kng&amp;__tn__=*NK-R\">#NoiteDosAmantes<\/a><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\udc9e\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t98\/1\/16\/1f49e.png\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83c\udfa7\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t1\/1\/16\/1f3a7.png\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83c\udf0c\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/tbe\/1\/16\/1f30c.png\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Com mensagens tocantes, m\u00fasicas inesquec\u00edveis e aquela vibe perfeita pra curtir a dois ou recordar&#8230;<\/p>\n","protected":false},"author":1,"featured_media":4186,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[215],"tags":[119,118,120,121,117,1938,561,562,116,99],"class_list":["post-4185","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-love-night","tag-anos-70","tag-anos-80","tag-anos-90","tag-baixe-nosso-app","tag-flashaback","tag-love-night-com-wendel-santos","tag-ouvir","tag-ouvir-radio","tag-radio","tag-radio-planeta-saudade"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A partir das 22h, prepare o cora\u00e7\u00e3o... Vem a\u00ed o programa mais rom\u00e2ntico do fim de noite! \u00c9 o Love Night, na companhia envolvente e carism\u00e1tica de Wendel Santos , que h\u00e1 5 anos encanta os cora\u00e7\u00f5es apaixonados na l\u00edder de audi\u00eancia: R\u00e1dio Planeta Saudade . - R\u00c1DIO PLANETA SAUDADE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/06\/05\/a-partir-das-22h-prepare-o-coracao-vem-ai-o-programa-mais-romantico-do-fim-de-noite-e-o-love-night-na-companhia-envolvente-e-carismatica-de-wendel-santos-que-ha-5-anos-encanta-os-coracoes-apa\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A partir das 22h, prepare o cora\u00e7\u00e3o... Vem a\u00ed o programa mais rom\u00e2ntico do fim de noite! \u00c9 o Love Night, na companhia envolvente e carism\u00e1tica de Wendel Santos , que h\u00e1 5 anos encanta os cora\u00e7\u00f5es apaixonados na l\u00edder de audi\u00eancia: R\u00e1dio Planeta Saudade . - R\u00c1DIO PLANETA SAUDADE\" \/>\n<meta property=\"og:description\" content=\"Com mensagens tocantes, m\u00fasicas inesquec\u00edveis e aquela vibe perfeita pra curtir a dois ou recordar...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/06\/05\/a-partir-das-22h-prepare-o-coracao-vem-ai-o-programa-mais-romantico-do-fim-de-noite-e-o-love-night-na-companhia-envolvente-e-carismatica-de-wendel-santos-que-ha-5-anos-encanta-os-coracoes-apa\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00c1DIO PLANETA SAUDADE\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-05T22:47:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-05T22:47:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2025\/06\/BOA-TARDE-PLANETA-Copia-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2529\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Planeta Saudade\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Planeta Saudade\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/06\\\/05\\\/a-partir-das-22h-prepare-o-coracao-vem-ai-o-programa-mais-romantico-do-fim-de-noite-e-o-love-night-na-companhia-envolvente-e-carismatica-de-wendel-santos-que-ha-5-anos-encanta-os-coracoes-apa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/06\\\/05\\\/a-partir-das-22h-prepare-o-coracao-vem-ai-o-programa-mais-romantico-do-fim-de-noite-e-o-love-night-na-companhia-envolvente-e-carismatica-de-wendel-santos-que-ha-5-anos-encanta-os-coracoes-apa\\\/\"},\"author\":{\"name\":\"Planeta Saudade\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#\\\/schema\\\/person\\\/1a6f6fc0d987819324e7ed417a1a6581\"},\"headline\":\"A partir das 22h, prepare o cora\u00e7\u00e3o&#8230; Vem a\u00ed o programa mais rom\u00e2ntico do fim de noite! \u00c9 o Love Night, na companhia envolvente e carism\u00e1tica de Wendel Santos , que h\u00e1 5 anos encanta os cora\u00e7\u00f5es apaixonados na l\u00edder de audi\u00eancia: R\u00e1dio Planeta Saudade .\",\"datePublished\":\"2025-06-05T22:47:16+00:00\",\"dateModified\":\"2025-06-05T22:47:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/06\\\/05\\\/a-partir-das-22h-prepare-o-coracao-vem-ai-o-programa-mais-romantico-do-fim-de-noite-e-o-love-night-na-companhia-envolvente-e-carismatica-de-wendel-santos-que-ha-5-anos-encanta-os-coracoes-apa\\\/\"},\"wordCount\":123,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/06\\\/05\\\/a-partir-das-22h-prepare-o-coracao-vem-ai-o-programa-mais-romantico-do-fim-de-noite-e-o-love-night-na-companhia-envolvente-e-carismatica-de-wendel-santos-que-ha-5-anos-encanta-os-coracoes-apa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/BOA-TARDE-PLANETA-Copia-scaled.jpg\",\"keywords\":[\"Anos 70\",\"Anos 80\",\"Anos 90\",\"Baixe nosso App\",\"Flashaback\",\"Love Night com Wendel Santos\",\"Ouvir\",\"Ouvir r\u00e1dio\",\"R\u00e1dio\",\"R\u00e1dio Planeta Saudade\"],\"articleSection\":[\"LOVE NIGHT\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/06\\\/05\\\/a-partir-das-22h-prepare-o-coracao-vem-ai-o-programa-mais-romantico-do-fim-de-noite-e-o-love-night-na-companhia-envolvente-e-carismatica-de-wendel-santos-que-ha-5-anos-encanta-os-coracoes-apa\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/06\\\/05\\\/a-partir-das-22h-prepare-o-coracao-vem-ai-o-programa-mais-romantico-do-fim-de-noite-e-o-love-night-na-companhia-envolvente-e-carismatica-de-wendel-santos-que-ha-5-anos-encanta-os-coracoes-apa\\\/\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/06\\\/05\\\/a-partir-das-22h-prepare-o-coracao-vem-ai-o-programa-mais-romantico-do-fim-de-noite-e-o-love-night-na-companhia-envolvente-e-carismatica-de-wendel-santos-que-ha-5-anos-encanta-os-coracoes-apa\\\/\",\"name\":\"A partir das 22h, prepare o cora\u00e7\u00e3o... Vem a\u00ed o programa mais rom\u00e2ntico do fim de noite! \u00c9 o Love Night, na companhia envolvente e carism\u00e1tica de Wendel Santos , que h\u00e1 5 anos encanta os cora\u00e7\u00f5es apaixonados na l\u00edder de audi\u00eancia: R\u00e1dio Planeta Saudade . - R\u00c1DIO PLANETA SAUDADE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/06\\\/05\\\/a-partir-das-22h-prepare-o-coracao-vem-ai-o-programa-mais-romantico-do-fim-de-noite-e-o-love-night-na-companhia-envolvente-e-carismatica-de-wendel-santos-que-ha-5-anos-encanta-os-coracoes-apa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/06\\\/05\\\/a-partir-das-22h-prepare-o-coracao-vem-ai-o-programa-mais-romantico-do-fim-de-noite-e-o-love-night-na-companhia-envolvente-e-carismatica-de-wendel-santos-que-ha-5-anos-encanta-os-coracoes-apa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/BOA-TARDE-PLANETA-Copia-scaled.jpg\",\"datePublished\":\"2025-06-05T22:47:16+00:00\",\"dateModified\":\"2025-06-05T22:47:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/06\\\/05\\\/a-partir-das-22h-prepare-o-coracao-vem-ai-o-programa-mais-romantico-do-fim-de-noite-e-o-love-night-na-companhia-envolvente-e-carismatica-de-wendel-santos-que-ha-5-anos-encanta-os-coracoes-apa\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/06\\\/05\\\/a-partir-das-22h-prepare-o-coracao-vem-ai-o-programa-mais-romantico-do-fim-de-noite-e-o-love-night-na-companhia-envolvente-e-carismatica-de-wendel-santos-que-ha-5-anos-encanta-os-coracoes-apa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/06\\\/05\\\/a-partir-das-22h-prepare-o-coracao-vem-ai-o-programa-mais-romantico-do-fim-de-noite-e-o-love-night-na-companhia-envolvente-e-carismatica-de-wendel-santos-que-ha-5-anos-encanta-os-coracoes-apa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/BOA-TARDE-PLANETA-Copia-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/BOA-TARDE-PLANETA-Copia-scaled.jpg\",\"width\":2560,\"height\":2529},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2025\\\/06\\\/05\\\/a-partir-das-22h-prepare-o-coracao-vem-ai-o-programa-mais-romantico-do-fim-de-noite-e-o-love-night-na-companhia-envolvente-e-carismatica-de-wendel-santos-que-ha-5-anos-encanta-os-coracoes-apa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A partir das 22h, prepare o cora\u00e7\u00e3o&#8230; Vem a\u00ed o programa mais rom\u00e2ntico do fim de noite! \u00c9 o Love Night, na companhia envolvente e carism\u00e1tica de Wendel Santos , que h\u00e1 5 anos encanta os cora\u00e7\u00f5es apaixonados na l\u00edder de audi\u00eancia: R\u00e1dio Planeta Saudade .\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#website\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/\",\"name\":\"R\u00e1dio Planeta Saudade\",\"description\":\"Relembrando grandes sucessos musicais e informando sobre os maiores artistas do mundo ou\u00e7a no seu celular.\",\"publisher\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#organization\",\"name\":\"R\u00e1dio Planeta Saudade\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/capture-20230607-202153.png\",\"contentUrl\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/capture-20230607-202153.png\",\"width\":1350,\"height\":358,\"caption\":\"R\u00e1dio Planeta Saudade\"},\"image\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#\\\/schema\\\/person\\\/1a6f6fc0d987819324e7ed417a1a6581\",\"name\":\"Planeta Saudade\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g\",\"caption\":\"Planeta Saudade\"},\"sameAs\":[\"https:\\\/\\\/radioplanetasaudade.com.br\"],\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/author\\\/wendelsantos4567\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A partir das 22h, prepare o cora\u00e7\u00e3o... Vem a\u00ed o programa mais rom\u00e2ntico do fim de noite! \u00c9 o Love Night, na companhia envolvente e carism\u00e1tica de Wendel Santos , que h\u00e1 5 anos encanta os cora\u00e7\u00f5es apaixonados na l\u00edder de audi\u00eancia: R\u00e1dio Planeta Saudade . - R\u00c1DIO PLANETA SAUDADE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/06\/05\/a-partir-das-22h-prepare-o-coracao-vem-ai-o-programa-mais-romantico-do-fim-de-noite-e-o-love-night-na-companhia-envolvente-e-carismatica-de-wendel-santos-que-ha-5-anos-encanta-os-coracoes-apa\/","og_locale":"pt_BR","og_type":"article","og_title":"A partir das 22h, prepare o cora\u00e7\u00e3o... Vem a\u00ed o programa mais rom\u00e2ntico do fim de noite! \u00c9 o Love Night, na companhia envolvente e carism\u00e1tica de Wendel Santos , que h\u00e1 5 anos encanta os cora\u00e7\u00f5es apaixonados na l\u00edder de audi\u00eancia: R\u00e1dio Planeta Saudade . - R\u00c1DIO PLANETA SAUDADE","og_description":"Com mensagens tocantes, m\u00fasicas inesquec\u00edveis e aquela vibe perfeita pra curtir a dois ou recordar...","og_url":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/06\/05\/a-partir-das-22h-prepare-o-coracao-vem-ai-o-programa-mais-romantico-do-fim-de-noite-e-o-love-night-na-companhia-envolvente-e-carismatica-de-wendel-santos-que-ha-5-anos-encanta-os-coracoes-apa\/","og_site_name":"R\u00c1DIO PLANETA SAUDADE","article_published_time":"2025-06-05T22:47:16+00:00","article_modified_time":"2025-06-05T22:47:18+00:00","og_image":[{"width":2560,"height":2529,"url":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2025\/06\/BOA-TARDE-PLANETA-Copia-scaled.jpg","type":"image\/jpeg"}],"author":"Planeta Saudade","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Planeta Saudade","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/06\/05\/a-partir-das-22h-prepare-o-coracao-vem-ai-o-programa-mais-romantico-do-fim-de-noite-e-o-love-night-na-companhia-envolvente-e-carismatica-de-wendel-santos-que-ha-5-anos-encanta-os-coracoes-apa\/#article","isPartOf":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/06\/05\/a-partir-das-22h-prepare-o-coracao-vem-ai-o-programa-mais-romantico-do-fim-de-noite-e-o-love-night-na-companhia-envolvente-e-carismatica-de-wendel-santos-que-ha-5-anos-encanta-os-coracoes-apa\/"},"author":{"name":"Planeta Saudade","@id":"https:\/\/radioplanetasaudade.com.br\/#\/schema\/person\/1a6f6fc0d987819324e7ed417a1a6581"},"headline":"A partir das 22h, prepare o cora\u00e7\u00e3o&#8230; Vem a\u00ed o programa mais rom\u00e2ntico do fim de noite! \u00c9 o Love Night, na companhia envolvente e carism\u00e1tica de Wendel Santos , que h\u00e1 5 anos encanta os cora\u00e7\u00f5es apaixonados na l\u00edder de audi\u00eancia: R\u00e1dio Planeta Saudade .","datePublished":"2025-06-05T22:47:16+00:00","dateModified":"2025-06-05T22:47:18+00:00","mainEntityOfPage":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/06\/05\/a-partir-das-22h-prepare-o-coracao-vem-ai-o-programa-mais-romantico-do-fim-de-noite-e-o-love-night-na-companhia-envolvente-e-carismatica-de-wendel-santos-que-ha-5-anos-encanta-os-coracoes-apa\/"},"wordCount":123,"commentCount":0,"publisher":{"@id":"https:\/\/radioplanetasaudade.com.br\/#organization"},"image":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/06\/05\/a-partir-das-22h-prepare-o-coracao-vem-ai-o-programa-mais-romantico-do-fim-de-noite-e-o-love-night-na-companhia-envolvente-e-carismatica-de-wendel-santos-que-ha-5-anos-encanta-os-coracoes-apa\/#primaryimage"},"thumbnailUrl":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2025\/06\/BOA-TARDE-PLANETA-Copia-scaled.jpg","keywords":["Anos 70","Anos 80","Anos 90","Baixe nosso App","Flashaback","Love Night com Wendel Santos","Ouvir","Ouvir r\u00e1dio","R\u00e1dio","R\u00e1dio Planeta Saudade"],"articleSection":["LOVE NIGHT"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/06\/05\/a-partir-das-22h-prepare-o-coracao-vem-ai-o-programa-mais-romantico-do-fim-de-noite-e-o-love-night-na-companhia-envolvente-e-carismatica-de-wendel-santos-que-ha-5-anos-encanta-os-coracoes-apa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/06\/05\/a-partir-das-22h-prepare-o-coracao-vem-ai-o-programa-mais-romantico-do-fim-de-noite-e-o-love-night-na-companhia-envolvente-e-carismatica-de-wendel-santos-que-ha-5-anos-encanta-os-coracoes-apa\/","url":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/06\/05\/a-partir-das-22h-prepare-o-coracao-vem-ai-o-programa-mais-romantico-do-fim-de-noite-e-o-love-night-na-companhia-envolvente-e-carismatica-de-wendel-santos-que-ha-5-anos-encanta-os-coracoes-apa\/","name":"A partir das 22h, prepare o cora\u00e7\u00e3o... Vem a\u00ed o programa mais rom\u00e2ntico do fim de noite! \u00c9 o Love Night, na companhia envolvente e carism\u00e1tica de Wendel Santos , que h\u00e1 5 anos encanta os cora\u00e7\u00f5es apaixonados na l\u00edder de audi\u00eancia: R\u00e1dio Planeta Saudade . - R\u00c1DIO PLANETA SAUDADE","isPartOf":{"@id":"https:\/\/radioplanetasaudade.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/06\/05\/a-partir-das-22h-prepare-o-coracao-vem-ai-o-programa-mais-romantico-do-fim-de-noite-e-o-love-night-na-companhia-envolvente-e-carismatica-de-wendel-santos-que-ha-5-anos-encanta-os-coracoes-apa\/#primaryimage"},"image":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/06\/05\/a-partir-das-22h-prepare-o-coracao-vem-ai-o-programa-mais-romantico-do-fim-de-noite-e-o-love-night-na-companhia-envolvente-e-carismatica-de-wendel-santos-que-ha-5-anos-encanta-os-coracoes-apa\/#primaryimage"},"thumbnailUrl":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2025\/06\/BOA-TARDE-PLANETA-Copia-scaled.jpg","datePublished":"2025-06-05T22:47:16+00:00","dateModified":"2025-06-05T22:47:18+00:00","breadcrumb":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/06\/05\/a-partir-das-22h-prepare-o-coracao-vem-ai-o-programa-mais-romantico-do-fim-de-noite-e-o-love-night-na-companhia-envolvente-e-carismatica-de-wendel-santos-que-ha-5-anos-encanta-os-coracoes-apa\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/06\/05\/a-partir-das-22h-prepare-o-coracao-vem-ai-o-programa-mais-romantico-do-fim-de-noite-e-o-love-night-na-companhia-envolvente-e-carismatica-de-wendel-santos-que-ha-5-anos-encanta-os-coracoes-apa\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/06\/05\/a-partir-das-22h-prepare-o-coracao-vem-ai-o-programa-mais-romantico-do-fim-de-noite-e-o-love-night-na-companhia-envolvente-e-carismatica-de-wendel-santos-que-ha-5-anos-encanta-os-coracoes-apa\/#primaryimage","url":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2025\/06\/BOA-TARDE-PLANETA-Copia-scaled.jpg","contentUrl":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2025\/06\/BOA-TARDE-PLANETA-Copia-scaled.jpg","width":2560,"height":2529},{"@type":"BreadcrumbList","@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2025\/06\/05\/a-partir-das-22h-prepare-o-coracao-vem-ai-o-programa-mais-romantico-do-fim-de-noite-e-o-love-night-na-companhia-envolvente-e-carismatica-de-wendel-santos-que-ha-5-anos-encanta-os-coracoes-apa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/radioplanetasaudade.com.br\/"},{"@type":"ListItem","position":2,"name":"A partir das 22h, prepare o cora\u00e7\u00e3o&#8230; Vem a\u00ed o programa mais rom\u00e2ntico do fim de noite! \u00c9 o Love Night, na companhia envolvente e carism\u00e1tica de Wendel Santos , que h\u00e1 5 anos encanta os cora\u00e7\u00f5es apaixonados na l\u00edder de audi\u00eancia: R\u00e1dio Planeta Saudade ."}]},{"@type":"WebSite","@id":"https:\/\/radioplanetasaudade.com.br\/#website","url":"https:\/\/radioplanetasaudade.com.br\/","name":"R\u00e1dio Planeta Saudade","description":"Relembrando grandes sucessos musicais e informando sobre os maiores artistas do mundo ou\u00e7a no seu celular.","publisher":{"@id":"https:\/\/radioplanetasaudade.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radioplanetasaudade.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/radioplanetasaudade.com.br\/#organization","name":"R\u00e1dio Planeta Saudade","url":"https:\/\/radioplanetasaudade.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radioplanetasaudade.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2023\/10\/capture-20230607-202153.png","contentUrl":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2023\/10\/capture-20230607-202153.png","width":1350,"height":358,"caption":"R\u00e1dio Planeta Saudade"},"image":{"@id":"https:\/\/radioplanetasaudade.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/radioplanetasaudade.com.br\/#\/schema\/person\/1a6f6fc0d987819324e7ed417a1a6581","name":"Planeta Saudade","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g","caption":"Planeta Saudade"},"sameAs":["https:\/\/radioplanetasaudade.com.br"],"url":"https:\/\/radioplanetasaudade.com.br\/index.php\/author\/wendelsantos4567\/"}]}},"_links":{"self":[{"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4185","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=4185"}],"version-history":[{"count":1,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4185\/revisions"}],"predecessor-version":[{"id":4187,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4185\/revisions\/4187"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/media\/4186"}],"wp:attachment":[{"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=4185"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=4185"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=4185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}