{"id":440,"date":"2023-11-09T19:48:40","date_gmt":"2023-11-09T22:48:40","guid":{"rendered":"https:\/\/radioplanetasaudade.com.br\/?p=440"},"modified":"2023-11-09T19:48:40","modified_gmt":"2023-11-09T22:48:40","slug":"confira-as-dez-ultimas-tocadas-na-programacao-radio-planeta-saudade","status":"publish","type":"post","link":"https:\/\/radioplanetasaudade.com.br\/index.php\/2023\/11\/09\/confira-as-dez-ultimas-tocadas-na-programacao-radio-planeta-saudade\/","title":{"rendered":"Confira as dez \u00faltimas tocadas na programa\u00e7\u00e3o R\u00e1dio Planeta Saudade"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><img decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t7a\/1\/16\/31_20e3.png\" alt=\"1\ufe0f\u20e3\"> <strong>Capital Inicial \/ M\u00fasica Urbana<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t99\/1\/16\/32_20e3.png\" alt=\"2\ufe0f\u20e3\"> <strong>T.a.t.u. \/ All The Things She Said<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/tb8\/1\/16\/33_20e3.png\" alt=\"3\ufe0f\u20e3\"> <strong>Christopher Cross \/ Ride Like The Wind<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/td7\/1\/16\/34_20e3.png\" alt=\"4\ufe0f\u20e3\"> <strong>Ana Carolina \/ Problemas<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/tf6\/1\/16\/35_20e3.png\" alt=\"5\ufe0f\u20e3\"> <strong>Adrian Gurvitz \/ Classic<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t15\/1\/16\/36_20e3.png\" alt=\"6\ufe0f\u20e3\"> <strong>Guilherme Arantes \/ Loucas horas<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t34\/1\/16\/37_20e3.png\" alt=\"7\ufe0f\u20e3\"> <strong>Kelly Clarkson \/ Breakaway<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t53\/1\/16\/38_20e3.png\" alt=\"8\ufe0f\u20e3\"> <strong>Skank \/ Algo Parecido<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t72\/1\/16\/39_20e3.png\" alt=\"9\ufe0f\u20e3\"> <strong>Snow Patrol &amp; The Police \/ Every Car You Chase<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t62\/1\/16\/1f51f.png\" alt=\"\ud83d\udd1f\"> <strong>Lulu Santos \/ Papo Cabe\u00e7a<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>O Melhor da M\u00fasica Nacional e Mundial VOC\u00ca ouve na<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t1\/1\/16\/1f3a7.png\" alt=\"\ud83c\udfa7\"> <strong>PLANETA SAUDADE <img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t1\/1\/16\/1f3a7.png\" alt=\"\ud83c\udfa7\"> SUA MELHOR OP\u00c7\u00c3O<\/strong> <img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/tcc\/1\/16\/1f3bc.png\" alt=\"\ud83c\udfbc\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Baixe nosso APP pela Google Play<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Dispon\u00edvel tamb\u00e9m pelos portais:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t9e\/1\/16\/27a1.png\" alt=\"\u27a1\ufe0f\"> <strong>R\u00c1DIOS.COM.BR<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t9e\/1\/16\/27a1.png\" alt=\"\u27a1\ufe0f\"> <strong>CX R\u00c1DIO<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t9e\/1\/16\/27a1.png\" alt=\"\u27a1\ufe0f\"> <strong>ONLINE R\u00c1DIO BOX<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t9e\/1\/16\/27a1.png\" alt=\"\u27a1\ufe0f\"> <strong>R\u00c1DIOS. NET<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t9e\/1\/16\/27a1.png\" alt=\"\u27a1\ufe0f\"> <strong>+ R\u00c1DIO<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Capital Inicial \/ M\u00fasica Urbana T.a.t.u. \/ All The Things She Said Christopher Cross \/&#8230;<\/p>\n","protected":false},"author":1,"featured_media":441,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[92],"tags":[119,118,120,130,117,116,99],"class_list":["post-440","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-baixe-nosso-aplicativo","tag-anos-70","tag-anos-80","tag-anos-90","tag-as-10-mais-tocadas","tag-flashaback","tag-radio","tag-radio-planeta-saudade"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Confira as dez \u00faltimas tocadas na programa\u00e7\u00e3o R\u00e1dio Planeta Saudade - R\u00c1DIO PLANETA SAUDADE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radioplanetasaudade.com.br\/index.php\/2023\/11\/09\/confira-as-dez-ultimas-tocadas-na-programacao-radio-planeta-saudade\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Confira as dez \u00faltimas tocadas na programa\u00e7\u00e3o R\u00e1dio Planeta Saudade - R\u00c1DIO PLANETA SAUDADE\" \/>\n<meta property=\"og:description\" content=\"Capital Inicial \/ M\u00fasica Urbana T.a.t.u. \/ All The Things She Said Christopher Cross \/...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radioplanetasaudade.com.br\/index.php\/2023\/11\/09\/confira-as-dez-ultimas-tocadas-na-programacao-radio-planeta-saudade\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00c1DIO PLANETA SAUDADE\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-09T22:48:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2023\/11\/400111931_122155204652002213_932932828564752266_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"596\" \/>\n\t<meta property=\"og:image:height\" content=\"593\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Planeta Saudade\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Planeta Saudade\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2023\\\/11\\\/09\\\/confira-as-dez-ultimas-tocadas-na-programacao-radio-planeta-saudade\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2023\\\/11\\\/09\\\/confira-as-dez-ultimas-tocadas-na-programacao-radio-planeta-saudade\\\/\"},\"author\":{\"name\":\"Planeta Saudade\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#\\\/schema\\\/person\\\/1a6f6fc0d987819324e7ed417a1a6581\"},\"headline\":\"Confira as dez \u00faltimas tocadas na programa\u00e7\u00e3o R\u00e1dio Planeta Saudade\",\"datePublished\":\"2023-11-09T22:48:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2023\\\/11\\\/09\\\/confira-as-dez-ultimas-tocadas-na-programacao-radio-planeta-saudade\\\/\"},\"wordCount\":107,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2023\\\/11\\\/09\\\/confira-as-dez-ultimas-tocadas-na-programacao-radio-planeta-saudade\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/400111931_122155204652002213_932932828564752266_n.jpg\",\"keywords\":[\"Anos 70\",\"Anos 80\",\"Anos 90\",\"As 10 Mais tocadas\",\"Flashaback\",\"R\u00e1dio\",\"R\u00e1dio Planeta Saudade\"],\"articleSection\":[\"BAIXE NOSSO APLICATIVO\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2023\\\/11\\\/09\\\/confira-as-dez-ultimas-tocadas-na-programacao-radio-planeta-saudade\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2023\\\/11\\\/09\\\/confira-as-dez-ultimas-tocadas-na-programacao-radio-planeta-saudade\\\/\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2023\\\/11\\\/09\\\/confira-as-dez-ultimas-tocadas-na-programacao-radio-planeta-saudade\\\/\",\"name\":\"Confira as dez \u00faltimas tocadas na programa\u00e7\u00e3o R\u00e1dio Planeta Saudade - R\u00c1DIO PLANETA SAUDADE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2023\\\/11\\\/09\\\/confira-as-dez-ultimas-tocadas-na-programacao-radio-planeta-saudade\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2023\\\/11\\\/09\\\/confira-as-dez-ultimas-tocadas-na-programacao-radio-planeta-saudade\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/400111931_122155204652002213_932932828564752266_n.jpg\",\"datePublished\":\"2023-11-09T22:48:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2023\\\/11\\\/09\\\/confira-as-dez-ultimas-tocadas-na-programacao-radio-planeta-saudade\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2023\\\/11\\\/09\\\/confira-as-dez-ultimas-tocadas-na-programacao-radio-planeta-saudade\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2023\\\/11\\\/09\\\/confira-as-dez-ultimas-tocadas-na-programacao-radio-planeta-saudade\\\/#primaryimage\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/400111931_122155204652002213_932932828564752266_n.jpg\",\"contentUrl\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/400111931_122155204652002213_932932828564752266_n.jpg\",\"width\":596,\"height\":593},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2023\\\/11\\\/09\\\/confira-as-dez-ultimas-tocadas-na-programacao-radio-planeta-saudade\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Confira as dez \u00faltimas tocadas na programa\u00e7\u00e3o R\u00e1dio Planeta Saudade\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#website\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/\",\"name\":\"R\u00e1dio Planeta Saudade\",\"description\":\"Relembrando grandes sucessos musicais e informando sobre os maiores artistas do mundo ou\u00e7a no seu celular.\",\"publisher\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#organization\",\"name\":\"R\u00e1dio Planeta Saudade\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/capture-20230607-202153.png\",\"contentUrl\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/capture-20230607-202153.png\",\"width\":1350,\"height\":358,\"caption\":\"R\u00e1dio Planeta Saudade\"},\"image\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#\\\/schema\\\/person\\\/1a6f6fc0d987819324e7ed417a1a6581\",\"name\":\"Planeta Saudade\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g\",\"caption\":\"Planeta Saudade\"},\"sameAs\":[\"https:\\\/\\\/radioplanetasaudade.com.br\"],\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/author\\\/wendelsantos4567\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Confira as dez \u00faltimas tocadas na programa\u00e7\u00e3o R\u00e1dio Planeta Saudade - R\u00c1DIO PLANETA SAUDADE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radioplanetasaudade.com.br\/index.php\/2023\/11\/09\/confira-as-dez-ultimas-tocadas-na-programacao-radio-planeta-saudade\/","og_locale":"pt_BR","og_type":"article","og_title":"Confira as dez \u00faltimas tocadas na programa\u00e7\u00e3o R\u00e1dio Planeta Saudade - R\u00c1DIO PLANETA SAUDADE","og_description":"Capital Inicial \/ M\u00fasica Urbana T.a.t.u. \/ All The Things She Said Christopher Cross \/...","og_url":"https:\/\/radioplanetasaudade.com.br\/index.php\/2023\/11\/09\/confira-as-dez-ultimas-tocadas-na-programacao-radio-planeta-saudade\/","og_site_name":"R\u00c1DIO PLANETA SAUDADE","article_published_time":"2023-11-09T22:48:40+00:00","og_image":[{"width":596,"height":593,"url":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2023\/11\/400111931_122155204652002213_932932828564752266_n.jpg","type":"image\/jpeg"}],"author":"Planeta Saudade","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Planeta Saudade","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2023\/11\/09\/confira-as-dez-ultimas-tocadas-na-programacao-radio-planeta-saudade\/#article","isPartOf":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2023\/11\/09\/confira-as-dez-ultimas-tocadas-na-programacao-radio-planeta-saudade\/"},"author":{"name":"Planeta Saudade","@id":"https:\/\/radioplanetasaudade.com.br\/#\/schema\/person\/1a6f6fc0d987819324e7ed417a1a6581"},"headline":"Confira as dez \u00faltimas tocadas na programa\u00e7\u00e3o R\u00e1dio Planeta Saudade","datePublished":"2023-11-09T22:48:40+00:00","mainEntityOfPage":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2023\/11\/09\/confira-as-dez-ultimas-tocadas-na-programacao-radio-planeta-saudade\/"},"wordCount":107,"commentCount":0,"publisher":{"@id":"https:\/\/radioplanetasaudade.com.br\/#organization"},"image":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2023\/11\/09\/confira-as-dez-ultimas-tocadas-na-programacao-radio-planeta-saudade\/#primaryimage"},"thumbnailUrl":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2023\/11\/400111931_122155204652002213_932932828564752266_n.jpg","keywords":["Anos 70","Anos 80","Anos 90","As 10 Mais tocadas","Flashaback","R\u00e1dio","R\u00e1dio Planeta Saudade"],"articleSection":["BAIXE NOSSO APLICATIVO"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/radioplanetasaudade.com.br\/index.php\/2023\/11\/09\/confira-as-dez-ultimas-tocadas-na-programacao-radio-planeta-saudade\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2023\/11\/09\/confira-as-dez-ultimas-tocadas-na-programacao-radio-planeta-saudade\/","url":"https:\/\/radioplanetasaudade.com.br\/index.php\/2023\/11\/09\/confira-as-dez-ultimas-tocadas-na-programacao-radio-planeta-saudade\/","name":"Confira as dez \u00faltimas tocadas na programa\u00e7\u00e3o R\u00e1dio Planeta Saudade - R\u00c1DIO PLANETA SAUDADE","isPartOf":{"@id":"https:\/\/radioplanetasaudade.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2023\/11\/09\/confira-as-dez-ultimas-tocadas-na-programacao-radio-planeta-saudade\/#primaryimage"},"image":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2023\/11\/09\/confira-as-dez-ultimas-tocadas-na-programacao-radio-planeta-saudade\/#primaryimage"},"thumbnailUrl":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2023\/11\/400111931_122155204652002213_932932828564752266_n.jpg","datePublished":"2023-11-09T22:48:40+00:00","breadcrumb":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2023\/11\/09\/confira-as-dez-ultimas-tocadas-na-programacao-radio-planeta-saudade\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radioplanetasaudade.com.br\/index.php\/2023\/11\/09\/confira-as-dez-ultimas-tocadas-na-programacao-radio-planeta-saudade\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2023\/11\/09\/confira-as-dez-ultimas-tocadas-na-programacao-radio-planeta-saudade\/#primaryimage","url":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2023\/11\/400111931_122155204652002213_932932828564752266_n.jpg","contentUrl":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2023\/11\/400111931_122155204652002213_932932828564752266_n.jpg","width":596,"height":593},{"@type":"BreadcrumbList","@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2023\/11\/09\/confira-as-dez-ultimas-tocadas-na-programacao-radio-planeta-saudade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/radioplanetasaudade.com.br\/"},{"@type":"ListItem","position":2,"name":"Confira as dez \u00faltimas tocadas na programa\u00e7\u00e3o R\u00e1dio Planeta Saudade"}]},{"@type":"WebSite","@id":"https:\/\/radioplanetasaudade.com.br\/#website","url":"https:\/\/radioplanetasaudade.com.br\/","name":"R\u00e1dio Planeta Saudade","description":"Relembrando grandes sucessos musicais e informando sobre os maiores artistas do mundo ou\u00e7a no seu celular.","publisher":{"@id":"https:\/\/radioplanetasaudade.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radioplanetasaudade.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/radioplanetasaudade.com.br\/#organization","name":"R\u00e1dio Planeta Saudade","url":"https:\/\/radioplanetasaudade.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radioplanetasaudade.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2023\/10\/capture-20230607-202153.png","contentUrl":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2023\/10\/capture-20230607-202153.png","width":1350,"height":358,"caption":"R\u00e1dio Planeta Saudade"},"image":{"@id":"https:\/\/radioplanetasaudade.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/radioplanetasaudade.com.br\/#\/schema\/person\/1a6f6fc0d987819324e7ed417a1a6581","name":"Planeta Saudade","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g","caption":"Planeta Saudade"},"sameAs":["https:\/\/radioplanetasaudade.com.br"],"url":"https:\/\/radioplanetasaudade.com.br\/index.php\/author\/wendelsantos4567\/"}]}},"_links":{"self":[{"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/posts\/440","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=440"}],"version-history":[{"count":1,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/posts\/440\/revisions"}],"predecessor-version":[{"id":442,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/posts\/440\/revisions\/442"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/media\/441"}],"wp:attachment":[{"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=440"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=440"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=440"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}