{"id":498,"date":"2023-11-18T12:23:25","date_gmt":"2023-11-18T15:23:25","guid":{"rendered":"https:\/\/radioplanetasaudade.com.br\/?p=498"},"modified":"2023-11-18T12:23:27","modified_gmt":"2023-11-18T15:23:27","slug":"rock-nacional-pop-e-new-wave","status":"publish","type":"post","link":"https:\/\/radioplanetasaudade.com.br\/index.php\/2023\/11\/18\/rock-nacional-pop-e-new-wave\/","title":{"rendered":"ROCK NACIONAL, POP E NEW WAVE"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Est\u00e3o sempre presentes no AMN\u00c9SIA venha conferir:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>O Melhor da m\u00fasica nacional e mundial voc\u00ea ouve na R\u00e1dio Planeta Saudade<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t1\/1\/16\/1f3a7.png\" alt=\"\ud83c\udfa7\"> <strong>PLANETA SAUDADE <\/strong><img decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t1\/1\/16\/1f3a7.png\" alt=\"\ud83c\udfa7\"> <strong>SUA MELHOR OP\u00c7\u00c3O<\/strong> <img decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/tcc\/1\/16\/1f3bc.png\" alt=\"\ud83c\udfbc\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Baixe nosso APP pela Google Play<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Dispon\u00edvel tamb\u00e9m pelos portais:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t9e\/1\/16\/27a1.png\" alt=\"\u27a1\ufe0f\"> <strong>R\u00c1DIOS.COM.BR<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t9e\/1\/16\/27a1.png\" alt=\"\u27a1\ufe0f\"> <strong>CX R\u00c1DIO<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t9e\/1\/16\/27a1.png\" alt=\"\u27a1\ufe0f\"> <strong>ONLINE R\u00c1DIO BOX<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t9e\/1\/16\/27a1.png\" alt=\"\u27a1\ufe0f\"> <strong>R\u00c1DIOS. NET<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t9e\/1\/16\/27a1.png\" alt=\"\u27a1\ufe0f\"> <strong>+ R\u00c1DIO<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Est\u00e3o sempre presentes no AMN\u00c9SIA venha conferir: O Melhor da m\u00fasica nacional e mundial voc\u00ea&#8230;<\/p>\n","protected":false},"author":1,"featured_media":499,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[92],"tags":[134,119,118,120,121,117,116,99],"class_list":["post-498","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-baixe-nosso-aplicativo","tag-amnesia","tag-anos-70","tag-anos-80","tag-anos-90","tag-baixe-nosso-app","tag-flashaback","tag-radio","tag-radio-planeta-saudade"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ROCK NACIONAL, POP E NEW WAVE - R\u00c1DIO PLANETA SAUDADE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radioplanetasaudade.com.br\/index.php\/2023\/11\/18\/rock-nacional-pop-e-new-wave\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ROCK NACIONAL, POP E NEW WAVE - R\u00c1DIO PLANETA SAUDADE\" \/>\n<meta property=\"og:description\" content=\"Est\u00e3o sempre presentes no AMN\u00c9SIA venha conferir: O Melhor da m\u00fasica nacional e mundial voc\u00ea...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radioplanetasaudade.com.br\/index.php\/2023\/11\/18\/rock-nacional-pop-e-new-wave\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00c1DIO PLANETA SAUDADE\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-18T15:23:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-18T15:23:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2023\/11\/POST-2024-Copia-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"650\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Planeta Saudade\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Planeta Saudade\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2023\\\/11\\\/18\\\/rock-nacional-pop-e-new-wave\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2023\\\/11\\\/18\\\/rock-nacional-pop-e-new-wave\\\/\"},\"author\":{\"name\":\"Planeta Saudade\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#\\\/schema\\\/person\\\/1a6f6fc0d987819324e7ed417a1a6581\"},\"headline\":\"ROCK NACIONAL, POP E NEW WAVE\",\"datePublished\":\"2023-11-18T15:23:25+00:00\",\"dateModified\":\"2023-11-18T15:23:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2023\\\/11\\\/18\\\/rock-nacional-pop-e-new-wave\\\/\"},\"wordCount\":64,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2023\\\/11\\\/18\\\/rock-nacional-pop-e-new-wave\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/POST-2024-Copia-2.jpg\",\"keywords\":[\"Amn\u00e9sia\",\"Anos 70\",\"Anos 80\",\"Anos 90\",\"Baixe nosso App\",\"Flashaback\",\"R\u00e1dio\",\"R\u00e1dio Planeta Saudade\"],\"articleSection\":[\"BAIXE NOSSO APLICATIVO\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2023\\\/11\\\/18\\\/rock-nacional-pop-e-new-wave\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2023\\\/11\\\/18\\\/rock-nacional-pop-e-new-wave\\\/\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2023\\\/11\\\/18\\\/rock-nacional-pop-e-new-wave\\\/\",\"name\":\"ROCK NACIONAL, POP E NEW WAVE - R\u00c1DIO PLANETA SAUDADE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2023\\\/11\\\/18\\\/rock-nacional-pop-e-new-wave\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2023\\\/11\\\/18\\\/rock-nacional-pop-e-new-wave\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/POST-2024-Copia-2.jpg\",\"datePublished\":\"2023-11-18T15:23:25+00:00\",\"dateModified\":\"2023-11-18T15:23:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2023\\\/11\\\/18\\\/rock-nacional-pop-e-new-wave\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2023\\\/11\\\/18\\\/rock-nacional-pop-e-new-wave\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2023\\\/11\\\/18\\\/rock-nacional-pop-e-new-wave\\\/#primaryimage\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/POST-2024-Copia-2.jpg\",\"contentUrl\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/POST-2024-Copia-2.jpg\",\"width\":650,\"height\":650},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2023\\\/11\\\/18\\\/rock-nacional-pop-e-new-wave\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ROCK NACIONAL, POP E NEW WAVE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#website\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/\",\"name\":\"R\u00e1dio Planeta Saudade\",\"description\":\"Relembrando grandes sucessos musicais e informando sobre os maiores artistas do mundo ou\u00e7a no seu celular.\",\"publisher\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#organization\",\"name\":\"R\u00e1dio Planeta Saudade\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/capture-20230607-202153.png\",\"contentUrl\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/capture-20230607-202153.png\",\"width\":1350,\"height\":358,\"caption\":\"R\u00e1dio Planeta Saudade\"},\"image\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#\\\/schema\\\/person\\\/1a6f6fc0d987819324e7ed417a1a6581\",\"name\":\"Planeta Saudade\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g\",\"caption\":\"Planeta Saudade\"},\"sameAs\":[\"https:\\\/\\\/radioplanetasaudade.com.br\"],\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/author\\\/wendelsantos4567\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ROCK NACIONAL, POP E NEW WAVE - R\u00c1DIO PLANETA SAUDADE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radioplanetasaudade.com.br\/index.php\/2023\/11\/18\/rock-nacional-pop-e-new-wave\/","og_locale":"pt_BR","og_type":"article","og_title":"ROCK NACIONAL, POP E NEW WAVE - R\u00c1DIO PLANETA SAUDADE","og_description":"Est\u00e3o sempre presentes no AMN\u00c9SIA venha conferir: O Melhor da m\u00fasica nacional e mundial voc\u00ea...","og_url":"https:\/\/radioplanetasaudade.com.br\/index.php\/2023\/11\/18\/rock-nacional-pop-e-new-wave\/","og_site_name":"R\u00c1DIO PLANETA SAUDADE","article_published_time":"2023-11-18T15:23:25+00:00","article_modified_time":"2023-11-18T15:23:27+00:00","og_image":[{"width":650,"height":650,"url":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2023\/11\/POST-2024-Copia-2.jpg","type":"image\/jpeg"}],"author":"Planeta Saudade","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Planeta Saudade","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2023\/11\/18\/rock-nacional-pop-e-new-wave\/#article","isPartOf":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2023\/11\/18\/rock-nacional-pop-e-new-wave\/"},"author":{"name":"Planeta Saudade","@id":"https:\/\/radioplanetasaudade.com.br\/#\/schema\/person\/1a6f6fc0d987819324e7ed417a1a6581"},"headline":"ROCK NACIONAL, POP E NEW WAVE","datePublished":"2023-11-18T15:23:25+00:00","dateModified":"2023-11-18T15:23:27+00:00","mainEntityOfPage":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2023\/11\/18\/rock-nacional-pop-e-new-wave\/"},"wordCount":64,"commentCount":0,"publisher":{"@id":"https:\/\/radioplanetasaudade.com.br\/#organization"},"image":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2023\/11\/18\/rock-nacional-pop-e-new-wave\/#primaryimage"},"thumbnailUrl":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2023\/11\/POST-2024-Copia-2.jpg","keywords":["Amn\u00e9sia","Anos 70","Anos 80","Anos 90","Baixe nosso App","Flashaback","R\u00e1dio","R\u00e1dio Planeta Saudade"],"articleSection":["BAIXE NOSSO APLICATIVO"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/radioplanetasaudade.com.br\/index.php\/2023\/11\/18\/rock-nacional-pop-e-new-wave\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2023\/11\/18\/rock-nacional-pop-e-new-wave\/","url":"https:\/\/radioplanetasaudade.com.br\/index.php\/2023\/11\/18\/rock-nacional-pop-e-new-wave\/","name":"ROCK NACIONAL, POP E NEW WAVE - R\u00c1DIO PLANETA SAUDADE","isPartOf":{"@id":"https:\/\/radioplanetasaudade.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2023\/11\/18\/rock-nacional-pop-e-new-wave\/#primaryimage"},"image":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2023\/11\/18\/rock-nacional-pop-e-new-wave\/#primaryimage"},"thumbnailUrl":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2023\/11\/POST-2024-Copia-2.jpg","datePublished":"2023-11-18T15:23:25+00:00","dateModified":"2023-11-18T15:23:27+00:00","breadcrumb":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2023\/11\/18\/rock-nacional-pop-e-new-wave\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radioplanetasaudade.com.br\/index.php\/2023\/11\/18\/rock-nacional-pop-e-new-wave\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2023\/11\/18\/rock-nacional-pop-e-new-wave\/#primaryimage","url":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2023\/11\/POST-2024-Copia-2.jpg","contentUrl":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2023\/11\/POST-2024-Copia-2.jpg","width":650,"height":650},{"@type":"BreadcrumbList","@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2023\/11\/18\/rock-nacional-pop-e-new-wave\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/radioplanetasaudade.com.br\/"},{"@type":"ListItem","position":2,"name":"ROCK NACIONAL, POP E NEW WAVE"}]},{"@type":"WebSite","@id":"https:\/\/radioplanetasaudade.com.br\/#website","url":"https:\/\/radioplanetasaudade.com.br\/","name":"R\u00e1dio Planeta Saudade","description":"Relembrando grandes sucessos musicais e informando sobre os maiores artistas do mundo ou\u00e7a no seu celular.","publisher":{"@id":"https:\/\/radioplanetasaudade.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radioplanetasaudade.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/radioplanetasaudade.com.br\/#organization","name":"R\u00e1dio Planeta Saudade","url":"https:\/\/radioplanetasaudade.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radioplanetasaudade.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2023\/10\/capture-20230607-202153.png","contentUrl":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2023\/10\/capture-20230607-202153.png","width":1350,"height":358,"caption":"R\u00e1dio Planeta Saudade"},"image":{"@id":"https:\/\/radioplanetasaudade.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/radioplanetasaudade.com.br\/#\/schema\/person\/1a6f6fc0d987819324e7ed417a1a6581","name":"Planeta Saudade","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g","caption":"Planeta Saudade"},"sameAs":["https:\/\/radioplanetasaudade.com.br"],"url":"https:\/\/radioplanetasaudade.com.br\/index.php\/author\/wendelsantos4567\/"}]}},"_links":{"self":[{"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/posts\/498","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=498"}],"version-history":[{"count":1,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/posts\/498\/revisions"}],"predecessor-version":[{"id":500,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/posts\/498\/revisions\/500"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/media\/499"}],"wp:attachment":[{"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=498"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=498"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}