{"id":5670,"date":"2026-03-21T10:39:33","date_gmt":"2026-03-21T13:39:33","guid":{"rendered":"https:\/\/radioplanetasaudade.com.br\/?p=5670"},"modified":"2026-03-21T10:39:34","modified_gmt":"2026-03-21T13:39:34","slug":"natalie-cole-saudade-que-ecoa-com-um-classico-inesquecivel","status":"publish","type":"post","link":"https:\/\/radioplanetasaudade.com.br\/index.php\/2026\/03\/21\/natalie-cole-saudade-que-ecoa-com-um-classico-inesquecivel\/","title":{"rendered":"Natalie Cole, saudade que Ecoa: com um cl\u00e1ssico inesquec\u00edvel."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><em>Hoje em destaque, Miss You Like Crazy Lan\u00e7ada em 1989 \u00e9 um dos maiores \u00eaxitos da talentosa cantora Natalie Cole e marcou profundamente o cen\u00e1rio da m\u00fasica rom\u00e2ntica internacional. Presente no \u00e1lbum Good to Be Back, a can\u00e7\u00e3o conquistou o p\u00fablico com sua melodia envolvente e uma interpreta\u00e7\u00e3o carregada de emo\u00e7\u00e3o, tornando-se rapidamente um cl\u00e1ssico do pop\/R&amp;B.<\/em><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"745\" src=\"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2026\/03\/ColeBlackShirtcolor_20OCT_orig_1401x1019-1024x745.jpg\" alt=\"\" class=\"wp-image-5671\" srcset=\"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2026\/03\/ColeBlackShirtcolor_20OCT_orig_1401x1019-1024x745.jpg 1024w, https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2026\/03\/ColeBlackShirtcolor_20OCT_orig_1401x1019-300x218.jpg 300w, https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2026\/03\/ColeBlackShirtcolor_20OCT_orig_1401x1019-768x559.jpg 768w, https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2026\/03\/ColeBlackShirtcolor_20OCT_orig_1401x1019.jpg 1401w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>A m\u00fasica retrata com sensibilidade a dor da saudade e o sentimento persistente de amor ap\u00f3s o fim de um relacionamento. Sua letra mergulha em lembran\u00e7as marcantes e na esperan\u00e7a de um reencontro, algo com que muitos ouvintes se identificam at\u00e9 hoje. Esse apelo emocional ajudou a can\u00e7\u00e3o a alcan\u00e7ar grande sucesso nas paradas, consolidando ainda mais o nome de Natalie Cole no final dos anos 80.<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Antes do ic\u00f4nico \u00e1lbum Unforgettable&#8230; with Love (1991), esse sucesso j\u00e1 mostrava a for\u00e7a e o alcance da cantora, que soube como poucos traduzir sentimentos em forma de m\u00fasica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Acesse agora a R\u00e1dio Planeta Saudade e reviva momentos inesquec\u00edveis como esse!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\udcf1\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t57\/1\/16\/1f4f1.png\"> Baixe nosso APP \u2013 dispon\u00edvel para Android e iOS<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83c\udf10\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/taa\/1\/16\/1f310.png\"> Ou\u00e7a tamb\u00e9m em: <a href=\"http:\/\/radioplanetasaudade.com.br\/?fbclid=IwZXh0bgNhZW0CMTAAYnJpZBExZHRWWkpLcnB4UVE2VGJLb3NydGMGYXBwX2lkEDIyMjAzOTE3ODgyMDA4OTIAAR56LOjXNSyWAphnT79_ylgEgKVl2FNN_ePsTehRokuhwu7SDROBEoPfyDf37g_aem_zLJCpv628I3xxUVnuzKKpw\" rel=\"noreferrer noopener\" target=\"_blank\">radioplanetasaudade.com.br<\/a> e pela R\u00e1dios Net<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.facebook.com\/hashtag\/radioplanetasaudade?__eep__=6&amp;__cft__[0]=AZZdpDYUSjvFkR7EkUBiAUlCc0NJJEXCv_1idKiumZZy-sVQPZ9trKx8AWtIyDZhVfMJjPSaGCpRAQmtuRxNPW92UtjlSUq_SxCVDir3uhXxLOue2Pv3E8qZKR5d-HdcAZ-SquwqUrTbSF0fjnTnYs_DCifi2gbY9geZLV7A6AHpMQx8Pp88jl-LGSinKGWhn9I&amp;__tn__=*NK-R\">#RadioPlanetaSaudade<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.facebook.com\/hashtag\/nataliecole?__eep__=6&amp;__cft__[0]=AZZdpDYUSjvFkR7EkUBiAUlCc0NJJEXCv_1idKiumZZy-sVQPZ9trKx8AWtIyDZhVfMJjPSaGCpRAQmtuRxNPW92UtjlSUq_SxCVDir3uhXxLOue2Pv3E8qZKR5d-HdcAZ-SquwqUrTbSF0fjnTnYs_DCifi2gbY9geZLV7A6AHpMQx8Pp88jl-LGSinKGWhn9I&amp;__tn__=*NK-R\">#NatalieCole<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.facebook.com\/hashtag\/missyoulikecrazy?__eep__=6&amp;__cft__[0]=AZZdpDYUSjvFkR7EkUBiAUlCc0NJJEXCv_1idKiumZZy-sVQPZ9trKx8AWtIyDZhVfMJjPSaGCpRAQmtuRxNPW92UtjlSUq_SxCVDir3uhXxLOue2Pv3E8qZKR5d-HdcAZ-SquwqUrTbSF0fjnTnYs_DCifi2gbY9geZLV7A6AHpMQx8Pp88jl-LGSinKGWhn9I&amp;__tn__=*NK-R\">#MissYouLikeCrazy<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.facebook.com\/hashtag\/romanticasinternacionais?__eep__=6&amp;__cft__[0]=AZZdpDYUSjvFkR7EkUBiAUlCc0NJJEXCv_1idKiumZZy-sVQPZ9trKx8AWtIyDZhVfMJjPSaGCpRAQmtuRxNPW92UtjlSUq_SxCVDir3uhXxLOue2Pv3E8qZKR5d-HdcAZ-SquwqUrTbSF0fjnTnYs_DCifi2gbY9geZLV7A6AHpMQx8Pp88jl-LGSinKGWhn9I&amp;__tn__=*NK-R\">#RomanticasInternacionais<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.facebook.com\/hashtag\/anos80?__eep__=6&amp;__cft__[0]=AZZdpDYUSjvFkR7EkUBiAUlCc0NJJEXCv_1idKiumZZy-sVQPZ9trKx8AWtIyDZhVfMJjPSaGCpRAQmtuRxNPW92UtjlSUq_SxCVDir3uhXxLOue2Pv3E8qZKR5d-HdcAZ-SquwqUrTbSF0fjnTnYs_DCifi2gbY9geZLV7A6AHpMQx8Pp88jl-LGSinKGWhn9I&amp;__tn__=*NK-R\">#Anos80<\/a><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83c\udfa7\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t1\/1\/16\/1f3a7.png\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoje em destaque, Miss You Like Crazy Lan\u00e7ada em 1989 \u00e9 um dos maiores \u00eaxitos&#8230;<\/p>\n","protected":false},"author":1,"featured_media":5671,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[92],"tags":[119,118,120,121,117,411,410,561,562,116,99],"class_list":["post-5670","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-baixe-nosso-aplicativo","tag-anos-70","tag-anos-80","tag-anos-90","tag-baixe-nosso-app","tag-flashaback","tag-miss-you-like-crazy","tag-natalie-cole","tag-ouvir","tag-ouvir-radio","tag-radio","tag-radio-planeta-saudade"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Natalie Cole, saudade que Ecoa: com um cl\u00e1ssico inesquec\u00edvel. - R\u00c1DIO PLANETA SAUDADE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radioplanetasaudade.com.br\/index.php\/2026\/03\/21\/natalie-cole-saudade-que-ecoa-com-um-classico-inesquecivel\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Natalie Cole, saudade que Ecoa: com um cl\u00e1ssico inesquec\u00edvel. - R\u00c1DIO PLANETA SAUDADE\" \/>\n<meta property=\"og:description\" content=\"Hoje em destaque, Miss You Like Crazy Lan\u00e7ada em 1989 \u00e9 um dos maiores \u00eaxitos...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radioplanetasaudade.com.br\/index.php\/2026\/03\/21\/natalie-cole-saudade-que-ecoa-com-um-classico-inesquecivel\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00c1DIO PLANETA SAUDADE\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-21T13:39:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-21T13:39:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2026\/03\/ColeBlackShirtcolor_20OCT_orig_1401x1019.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1401\" \/>\n\t<meta property=\"og:image:height\" content=\"1019\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Planeta Saudade\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Planeta Saudade\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2026\\\/03\\\/21\\\/natalie-cole-saudade-que-ecoa-com-um-classico-inesquecivel\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2026\\\/03\\\/21\\\/natalie-cole-saudade-que-ecoa-com-um-classico-inesquecivel\\\/\"},\"author\":{\"name\":\"Planeta Saudade\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#\\\/schema\\\/person\\\/1a6f6fc0d987819324e7ed417a1a6581\"},\"headline\":\"Natalie Cole, saudade que Ecoa: com um cl\u00e1ssico inesquec\u00edvel.\",\"datePublished\":\"2026-03-21T13:39:33+00:00\",\"dateModified\":\"2026-03-21T13:39:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2026\\\/03\\\/21\\\/natalie-cole-saudade-que-ecoa-com-um-classico-inesquecivel\\\/\"},\"wordCount\":222,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2026\\\/03\\\/21\\\/natalie-cole-saudade-que-ecoa-com-um-classico-inesquecivel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/ColeBlackShirtcolor_20OCT_orig_1401x1019.jpg\",\"keywords\":[\"Anos 70\",\"Anos 80\",\"Anos 90\",\"Baixe nosso App\",\"Flashaback\",\"Miss You Like Crazy\",\"Natalie Cole\",\"Ouvir\",\"Ouvir r\u00e1dio\",\"R\u00e1dio\",\"R\u00e1dio Planeta Saudade\"],\"articleSection\":[\"BAIXE NOSSO APLICATIVO\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2026\\\/03\\\/21\\\/natalie-cole-saudade-que-ecoa-com-um-classico-inesquecivel\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2026\\\/03\\\/21\\\/natalie-cole-saudade-que-ecoa-com-um-classico-inesquecivel\\\/\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2026\\\/03\\\/21\\\/natalie-cole-saudade-que-ecoa-com-um-classico-inesquecivel\\\/\",\"name\":\"Natalie Cole, saudade que Ecoa: com um cl\u00e1ssico inesquec\u00edvel. - R\u00c1DIO PLANETA SAUDADE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2026\\\/03\\\/21\\\/natalie-cole-saudade-que-ecoa-com-um-classico-inesquecivel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2026\\\/03\\\/21\\\/natalie-cole-saudade-que-ecoa-com-um-classico-inesquecivel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/ColeBlackShirtcolor_20OCT_orig_1401x1019.jpg\",\"datePublished\":\"2026-03-21T13:39:33+00:00\",\"dateModified\":\"2026-03-21T13:39:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2026\\\/03\\\/21\\\/natalie-cole-saudade-que-ecoa-com-um-classico-inesquecivel\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2026\\\/03\\\/21\\\/natalie-cole-saudade-que-ecoa-com-um-classico-inesquecivel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2026\\\/03\\\/21\\\/natalie-cole-saudade-que-ecoa-com-um-classico-inesquecivel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/ColeBlackShirtcolor_20OCT_orig_1401x1019.jpg\",\"contentUrl\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/ColeBlackShirtcolor_20OCT_orig_1401x1019.jpg\",\"width\":1401,\"height\":1019},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2026\\\/03\\\/21\\\/natalie-cole-saudade-que-ecoa-com-um-classico-inesquecivel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Natalie Cole, saudade que Ecoa: com um cl\u00e1ssico inesquec\u00edvel.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#website\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/\",\"name\":\"R\u00e1dio Planeta Saudade\",\"description\":\"Relembrando grandes sucessos musicais e informando sobre os maiores artistas do mundo ou\u00e7a no seu celular.\",\"publisher\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#organization\",\"name\":\"R\u00e1dio Planeta Saudade\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/capture-20230607-202153.png\",\"contentUrl\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/capture-20230607-202153.png\",\"width\":1350,\"height\":358,\"caption\":\"R\u00e1dio Planeta Saudade\"},\"image\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#\\\/schema\\\/person\\\/1a6f6fc0d987819324e7ed417a1a6581\",\"name\":\"Planeta Saudade\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g\",\"caption\":\"Planeta Saudade\"},\"sameAs\":[\"https:\\\/\\\/radioplanetasaudade.com.br\"],\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/author\\\/wendelsantos4567\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Natalie Cole, saudade que Ecoa: com um cl\u00e1ssico inesquec\u00edvel. - R\u00c1DIO PLANETA SAUDADE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radioplanetasaudade.com.br\/index.php\/2026\/03\/21\/natalie-cole-saudade-que-ecoa-com-um-classico-inesquecivel\/","og_locale":"pt_BR","og_type":"article","og_title":"Natalie Cole, saudade que Ecoa: com um cl\u00e1ssico inesquec\u00edvel. - R\u00c1DIO PLANETA SAUDADE","og_description":"Hoje em destaque, Miss You Like Crazy Lan\u00e7ada em 1989 \u00e9 um dos maiores \u00eaxitos...","og_url":"https:\/\/radioplanetasaudade.com.br\/index.php\/2026\/03\/21\/natalie-cole-saudade-que-ecoa-com-um-classico-inesquecivel\/","og_site_name":"R\u00c1DIO PLANETA SAUDADE","article_published_time":"2026-03-21T13:39:33+00:00","article_modified_time":"2026-03-21T13:39:34+00:00","og_image":[{"width":1401,"height":1019,"url":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2026\/03\/ColeBlackShirtcolor_20OCT_orig_1401x1019.jpg","type":"image\/jpeg"}],"author":"Planeta Saudade","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Planeta Saudade","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2026\/03\/21\/natalie-cole-saudade-que-ecoa-com-um-classico-inesquecivel\/#article","isPartOf":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2026\/03\/21\/natalie-cole-saudade-que-ecoa-com-um-classico-inesquecivel\/"},"author":{"name":"Planeta Saudade","@id":"https:\/\/radioplanetasaudade.com.br\/#\/schema\/person\/1a6f6fc0d987819324e7ed417a1a6581"},"headline":"Natalie Cole, saudade que Ecoa: com um cl\u00e1ssico inesquec\u00edvel.","datePublished":"2026-03-21T13:39:33+00:00","dateModified":"2026-03-21T13:39:34+00:00","mainEntityOfPage":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2026\/03\/21\/natalie-cole-saudade-que-ecoa-com-um-classico-inesquecivel\/"},"wordCount":222,"commentCount":0,"publisher":{"@id":"https:\/\/radioplanetasaudade.com.br\/#organization"},"image":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2026\/03\/21\/natalie-cole-saudade-que-ecoa-com-um-classico-inesquecivel\/#primaryimage"},"thumbnailUrl":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2026\/03\/ColeBlackShirtcolor_20OCT_orig_1401x1019.jpg","keywords":["Anos 70","Anos 80","Anos 90","Baixe nosso App","Flashaback","Miss You Like Crazy","Natalie Cole","Ouvir","Ouvir r\u00e1dio","R\u00e1dio","R\u00e1dio Planeta Saudade"],"articleSection":["BAIXE NOSSO APLICATIVO"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/radioplanetasaudade.com.br\/index.php\/2026\/03\/21\/natalie-cole-saudade-que-ecoa-com-um-classico-inesquecivel\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2026\/03\/21\/natalie-cole-saudade-que-ecoa-com-um-classico-inesquecivel\/","url":"https:\/\/radioplanetasaudade.com.br\/index.php\/2026\/03\/21\/natalie-cole-saudade-que-ecoa-com-um-classico-inesquecivel\/","name":"Natalie Cole, saudade que Ecoa: com um cl\u00e1ssico inesquec\u00edvel. - R\u00c1DIO PLANETA SAUDADE","isPartOf":{"@id":"https:\/\/radioplanetasaudade.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2026\/03\/21\/natalie-cole-saudade-que-ecoa-com-um-classico-inesquecivel\/#primaryimage"},"image":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2026\/03\/21\/natalie-cole-saudade-que-ecoa-com-um-classico-inesquecivel\/#primaryimage"},"thumbnailUrl":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2026\/03\/ColeBlackShirtcolor_20OCT_orig_1401x1019.jpg","datePublished":"2026-03-21T13:39:33+00:00","dateModified":"2026-03-21T13:39:34+00:00","breadcrumb":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2026\/03\/21\/natalie-cole-saudade-que-ecoa-com-um-classico-inesquecivel\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radioplanetasaudade.com.br\/index.php\/2026\/03\/21\/natalie-cole-saudade-que-ecoa-com-um-classico-inesquecivel\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2026\/03\/21\/natalie-cole-saudade-que-ecoa-com-um-classico-inesquecivel\/#primaryimage","url":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2026\/03\/ColeBlackShirtcolor_20OCT_orig_1401x1019.jpg","contentUrl":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2026\/03\/ColeBlackShirtcolor_20OCT_orig_1401x1019.jpg","width":1401,"height":1019},{"@type":"BreadcrumbList","@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2026\/03\/21\/natalie-cole-saudade-que-ecoa-com-um-classico-inesquecivel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/radioplanetasaudade.com.br\/"},{"@type":"ListItem","position":2,"name":"Natalie Cole, saudade que Ecoa: com um cl\u00e1ssico inesquec\u00edvel."}]},{"@type":"WebSite","@id":"https:\/\/radioplanetasaudade.com.br\/#website","url":"https:\/\/radioplanetasaudade.com.br\/","name":"R\u00e1dio Planeta Saudade","description":"Relembrando grandes sucessos musicais e informando sobre os maiores artistas do mundo ou\u00e7a no seu celular.","publisher":{"@id":"https:\/\/radioplanetasaudade.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radioplanetasaudade.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/radioplanetasaudade.com.br\/#organization","name":"R\u00e1dio Planeta Saudade","url":"https:\/\/radioplanetasaudade.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radioplanetasaudade.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2023\/10\/capture-20230607-202153.png","contentUrl":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2023\/10\/capture-20230607-202153.png","width":1350,"height":358,"caption":"R\u00e1dio Planeta Saudade"},"image":{"@id":"https:\/\/radioplanetasaudade.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/radioplanetasaudade.com.br\/#\/schema\/person\/1a6f6fc0d987819324e7ed417a1a6581","name":"Planeta Saudade","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g","caption":"Planeta Saudade"},"sameAs":["https:\/\/radioplanetasaudade.com.br"],"url":"https:\/\/radioplanetasaudade.com.br\/index.php\/author\/wendelsantos4567\/"}]}},"_links":{"self":[{"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5670","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=5670"}],"version-history":[{"count":1,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5670\/revisions"}],"predecessor-version":[{"id":5672,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5670\/revisions\/5672"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/media\/5671"}],"wp:attachment":[{"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=5670"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=5670"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=5670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}