{"id":92,"date":"2023-10-23T10:35:47","date_gmt":"2023-10-23T13:35:47","guid":{"rendered":"https:\/\/radioplanetasaudade.com.br\/?p=92"},"modified":"2023-10-24T19:41:36","modified_gmt":"2023-10-24T22:41:36","slug":"shania-twain-teme-o-retorno-da-doenca-de-lyme","status":"publish","type":"post","link":"https:\/\/radioplanetasaudade.com.br\/index.php\/2023\/10\/23\/shania-twain-teme-o-retorno-da-doenca-de-lyme\/","title":{"rendered":"Shania Twain teme o retorno da\u00a0doen\u00e7a de Lyme\u00a0"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Ap\u00f3s sofrer uma queda durante um show em Chicago, a cantora&nbsp;de 57 anos, teme que os efeitos da&nbsp;doen\u00e7a de Lyme&nbsp;retornem, revela o Radar Online. Uma fonte pr\u00f3xima \u00e0 Shania, cujo nome n\u00e3o foi revelado, definiu o poss\u00edvel retorno dos sintomas como \u201cassustador\u201d.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>A interprete de&nbsp;<em>Man! I Feel Like a Woman<\/em>&nbsp;vem tra\u00e7ando uma batalha com a doen\u00e7a transmitida por carrapatos por quase duas d\u00e9cadas. Em seu document\u00e1rio da&nbsp;Netflix,&nbsp;<em>Not Just a Girl<\/em>, Shania conta que foi picada durante um passeio a cavalo, em 2003.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Al\u00e9m dos impactos no equil\u00edbrio e desmaios, a cantora sentiu os sintomas principalmente em suas cordas vocais. Durante o per\u00edodo de tratamento, precisou passar por uma cirurgia na garganta e teve que reaprender a cantar, o que a&nbsp;deixou afastada dos palcos e sem um novo \u00e1lbum por mais de 10 anos.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u201c\u00c9 assustador para ela pensar que esses sintomas horr\u00edveis que ela sofreu est\u00e3o voltando agora\u201d, compartilhou o amigo.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ap\u00f3s sofrer uma queda durante um show em Chicago, a cantora&nbsp;de 57 anos, teme que&#8230;<\/p>\n","protected":false},"author":1,"featured_media":93,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[25,24],"class_list":["post-92","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cantoras","tag-doenca-de-lyme","tag-shania-twain"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Shania Twain teme o retorno da\u00a0doen\u00e7a de Lyme\u00a0 - R\u00c1DIO PLANETA SAUDADE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radioplanetasaudade.com.br\/index.php\/2023\/10\/23\/shania-twain-teme-o-retorno-da-doenca-de-lyme\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Shania Twain teme o retorno da\u00a0doen\u00e7a de Lyme\u00a0 - R\u00c1DIO PLANETA SAUDADE\" \/>\n<meta property=\"og:description\" content=\"Ap\u00f3s sofrer uma queda durante um show em Chicago, a cantora&nbsp;de 57 anos, teme que...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radioplanetasaudade.com.br\/index.php\/2023\/10\/23\/shania-twain-teme-o-retorno-da-doenca-de-lyme\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00c1DIO PLANETA SAUDADE\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-23T13:35:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-24T22:41:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2023\/10\/shania-twain-cantora-foto-nicholas-hunt-getty-images.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Planeta Saudade\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Planeta Saudade\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2023\\\/10\\\/23\\\/shania-twain-teme-o-retorno-da-doenca-de-lyme\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2023\\\/10\\\/23\\\/shania-twain-teme-o-retorno-da-doenca-de-lyme\\\/\"},\"author\":{\"name\":\"Planeta Saudade\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#\\\/schema\\\/person\\\/1a6f6fc0d987819324e7ed417a1a6581\"},\"headline\":\"Shania Twain teme o retorno da\u00a0doen\u00e7a de Lyme\u00a0\",\"datePublished\":\"2023-10-23T13:35:47+00:00\",\"dateModified\":\"2023-10-24T22:41:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2023\\\/10\\\/23\\\/shania-twain-teme-o-retorno-da-doenca-de-lyme\\\/\"},\"wordCount\":186,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2023\\\/10\\\/23\\\/shania-twain-teme-o-retorno-da-doenca-de-lyme\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/shania-twain-cantora-foto-nicholas-hunt-getty-images.jpg\",\"keywords\":[\"Doen\u00e7a de Lyme\",\"Shania Twain\"],\"articleSection\":[\"CANTORAS\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2023\\\/10\\\/23\\\/shania-twain-teme-o-retorno-da-doenca-de-lyme\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2023\\\/10\\\/23\\\/shania-twain-teme-o-retorno-da-doenca-de-lyme\\\/\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2023\\\/10\\\/23\\\/shania-twain-teme-o-retorno-da-doenca-de-lyme\\\/\",\"name\":\"Shania Twain teme o retorno da\u00a0doen\u00e7a de Lyme\u00a0 - R\u00c1DIO PLANETA SAUDADE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2023\\\/10\\\/23\\\/shania-twain-teme-o-retorno-da-doenca-de-lyme\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2023\\\/10\\\/23\\\/shania-twain-teme-o-retorno-da-doenca-de-lyme\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/shania-twain-cantora-foto-nicholas-hunt-getty-images.jpg\",\"datePublished\":\"2023-10-23T13:35:47+00:00\",\"dateModified\":\"2023-10-24T22:41:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2023\\\/10\\\/23\\\/shania-twain-teme-o-retorno-da-doenca-de-lyme\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2023\\\/10\\\/23\\\/shania-twain-teme-o-retorno-da-doenca-de-lyme\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2023\\\/10\\\/23\\\/shania-twain-teme-o-retorno-da-doenca-de-lyme\\\/#primaryimage\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/shania-twain-cantora-foto-nicholas-hunt-getty-images.jpg\",\"contentUrl\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/shania-twain-cantora-foto-nicholas-hunt-getty-images.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2023\\\/10\\\/23\\\/shania-twain-teme-o-retorno-da-doenca-de-lyme\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shania Twain teme o retorno da\u00a0doen\u00e7a de Lyme\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#website\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/\",\"name\":\"R\u00e1dio Planeta Saudade\",\"description\":\"Relembrando grandes sucessos musicais e informando sobre os maiores artistas do mundo ou\u00e7a no seu celular.\",\"publisher\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#organization\",\"name\":\"R\u00e1dio Planeta Saudade\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/capture-20230607-202153.png\",\"contentUrl\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/capture-20230607-202153.png\",\"width\":1350,\"height\":358,\"caption\":\"R\u00e1dio Planeta Saudade\"},\"image\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#\\\/schema\\\/person\\\/1a6f6fc0d987819324e7ed417a1a6581\",\"name\":\"Planeta Saudade\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g\",\"caption\":\"Planeta Saudade\"},\"sameAs\":[\"https:\\\/\\\/radioplanetasaudade.com.br\"],\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/author\\\/wendelsantos4567\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Shania Twain teme o retorno da\u00a0doen\u00e7a de Lyme\u00a0 - R\u00c1DIO PLANETA SAUDADE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radioplanetasaudade.com.br\/index.php\/2023\/10\/23\/shania-twain-teme-o-retorno-da-doenca-de-lyme\/","og_locale":"pt_BR","og_type":"article","og_title":"Shania Twain teme o retorno da\u00a0doen\u00e7a de Lyme\u00a0 - R\u00c1DIO PLANETA SAUDADE","og_description":"Ap\u00f3s sofrer uma queda durante um show em Chicago, a cantora&nbsp;de 57 anos, teme que...","og_url":"https:\/\/radioplanetasaudade.com.br\/index.php\/2023\/10\/23\/shania-twain-teme-o-retorno-da-doenca-de-lyme\/","og_site_name":"R\u00c1DIO PLANETA SAUDADE","article_published_time":"2023-10-23T13:35:47+00:00","article_modified_time":"2023-10-24T22:41:36+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2023\/10\/shania-twain-cantora-foto-nicholas-hunt-getty-images.jpg","type":"image\/jpeg"}],"author":"Planeta Saudade","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Planeta Saudade","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2023\/10\/23\/shania-twain-teme-o-retorno-da-doenca-de-lyme\/#article","isPartOf":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2023\/10\/23\/shania-twain-teme-o-retorno-da-doenca-de-lyme\/"},"author":{"name":"Planeta Saudade","@id":"https:\/\/radioplanetasaudade.com.br\/#\/schema\/person\/1a6f6fc0d987819324e7ed417a1a6581"},"headline":"Shania Twain teme o retorno da\u00a0doen\u00e7a de Lyme\u00a0","datePublished":"2023-10-23T13:35:47+00:00","dateModified":"2023-10-24T22:41:36+00:00","mainEntityOfPage":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2023\/10\/23\/shania-twain-teme-o-retorno-da-doenca-de-lyme\/"},"wordCount":186,"commentCount":0,"publisher":{"@id":"https:\/\/radioplanetasaudade.com.br\/#organization"},"image":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2023\/10\/23\/shania-twain-teme-o-retorno-da-doenca-de-lyme\/#primaryimage"},"thumbnailUrl":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2023\/10\/shania-twain-cantora-foto-nicholas-hunt-getty-images.jpg","keywords":["Doen\u00e7a de Lyme","Shania Twain"],"articleSection":["CANTORAS"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/radioplanetasaudade.com.br\/index.php\/2023\/10\/23\/shania-twain-teme-o-retorno-da-doenca-de-lyme\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2023\/10\/23\/shania-twain-teme-o-retorno-da-doenca-de-lyme\/","url":"https:\/\/radioplanetasaudade.com.br\/index.php\/2023\/10\/23\/shania-twain-teme-o-retorno-da-doenca-de-lyme\/","name":"Shania Twain teme o retorno da\u00a0doen\u00e7a de Lyme\u00a0 - R\u00c1DIO PLANETA SAUDADE","isPartOf":{"@id":"https:\/\/radioplanetasaudade.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2023\/10\/23\/shania-twain-teme-o-retorno-da-doenca-de-lyme\/#primaryimage"},"image":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2023\/10\/23\/shania-twain-teme-o-retorno-da-doenca-de-lyme\/#primaryimage"},"thumbnailUrl":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2023\/10\/shania-twain-cantora-foto-nicholas-hunt-getty-images.jpg","datePublished":"2023-10-23T13:35:47+00:00","dateModified":"2023-10-24T22:41:36+00:00","breadcrumb":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2023\/10\/23\/shania-twain-teme-o-retorno-da-doenca-de-lyme\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radioplanetasaudade.com.br\/index.php\/2023\/10\/23\/shania-twain-teme-o-retorno-da-doenca-de-lyme\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2023\/10\/23\/shania-twain-teme-o-retorno-da-doenca-de-lyme\/#primaryimage","url":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2023\/10\/shania-twain-cantora-foto-nicholas-hunt-getty-images.jpg","contentUrl":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2023\/10\/shania-twain-cantora-foto-nicholas-hunt-getty-images.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2023\/10\/23\/shania-twain-teme-o-retorno-da-doenca-de-lyme\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/radioplanetasaudade.com.br\/"},{"@type":"ListItem","position":2,"name":"Shania Twain teme o retorno da\u00a0doen\u00e7a de Lyme\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/radioplanetasaudade.com.br\/#website","url":"https:\/\/radioplanetasaudade.com.br\/","name":"R\u00e1dio Planeta Saudade","description":"Relembrando grandes sucessos musicais e informando sobre os maiores artistas do mundo ou\u00e7a no seu celular.","publisher":{"@id":"https:\/\/radioplanetasaudade.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radioplanetasaudade.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/radioplanetasaudade.com.br\/#organization","name":"R\u00e1dio Planeta Saudade","url":"https:\/\/radioplanetasaudade.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radioplanetasaudade.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2023\/10\/capture-20230607-202153.png","contentUrl":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2023\/10\/capture-20230607-202153.png","width":1350,"height":358,"caption":"R\u00e1dio Planeta Saudade"},"image":{"@id":"https:\/\/radioplanetasaudade.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/radioplanetasaudade.com.br\/#\/schema\/person\/1a6f6fc0d987819324e7ed417a1a6581","name":"Planeta Saudade","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g","caption":"Planeta Saudade"},"sameAs":["https:\/\/radioplanetasaudade.com.br"],"url":"https:\/\/radioplanetasaudade.com.br\/index.php\/author\/wendelsantos4567\/"}]}},"_links":{"self":[{"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/posts\/92","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=92"}],"version-history":[{"count":3,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/posts\/92\/revisions"}],"predecessor-version":[{"id":170,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/posts\/92\/revisions\/170"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/media\/93"}],"wp:attachment":[{"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=92"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=92"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=92"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}