{"id":965,"date":"2024-03-18T12:00:42","date_gmt":"2024-03-18T15:00:42","guid":{"rendered":"https:\/\/radioplanetasaudade.com.br\/?p=965"},"modified":"2024-03-18T12:00:53","modified_gmt":"2024-03-18T15:00:53","slug":"965","status":"publish","type":"post","link":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/03\/18\/965\/","title":{"rendered":""},"content":{"rendered":"\n<figure class=\"wp-block-image aligncenter size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"588\" height=\"577\" src=\"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2024\/03\/QUAL-SUA-SAUDADE.jpg\" alt=\"\" class=\"wp-image-966\" srcset=\"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2024\/03\/QUAL-SUA-SAUDADE.jpg 588w, https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2024\/03\/QUAL-SUA-SAUDADE-300x294.jpg 300w\" sizes=\"(max-width: 588px) 100vw, 588px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[213],"tags":[119,118,120,121,117,116,99],"class_list":["post-965","post","type-post","status-publish","format-standard","hentry","category-qual-e-a-sua-saudade","tag-anos-70","tag-anos-80","tag-anos-90","tag-baixe-nosso-app","tag-flashaback","tag-radio","tag-radio-planeta-saudade"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>- R\u00c1DIO PLANETA SAUDADE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/03\/18\/965\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"- R\u00c1DIO PLANETA SAUDADE\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/03\/18\/965\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00c1DIO PLANETA SAUDADE\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-18T15:00:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-18T15:00:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2024\/03\/QUAL-SUA-SAUDADE.jpg\" \/>\n<meta name=\"author\" content=\"Planeta Saudade\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Planeta Saudade\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2024\\\/03\\\/18\\\/965\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2024\\\/03\\\/18\\\/965\\\/\"},\"author\":{\"name\":\"Planeta Saudade\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#\\\/schema\\\/person\\\/1a6f6fc0d987819324e7ed417a1a6581\"},\"headline\":\"Sem t\u00edtulo\",\"datePublished\":\"2024-03-18T15:00:42+00:00\",\"dateModified\":\"2024-03-18T15:00:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2024\\\/03\\\/18\\\/965\\\/\"},\"wordCount\":0,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2024\\\/03\\\/18\\\/965\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/QUAL-SUA-SAUDADE.jpg\",\"keywords\":[\"Anos 70\",\"Anos 80\",\"Anos 90\",\"Baixe nosso App\",\"Flashaback\",\"R\u00e1dio\",\"R\u00e1dio Planeta Saudade\"],\"articleSection\":[\"QUAL \u00c9 A SUA SAUDADE?\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2024\\\/03\\\/18\\\/965\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2024\\\/03\\\/18\\\/965\\\/\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2024\\\/03\\\/18\\\/965\\\/\",\"name\":\"- R\u00c1DIO PLANETA SAUDADE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2024\\\/03\\\/18\\\/965\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2024\\\/03\\\/18\\\/965\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/QUAL-SUA-SAUDADE.jpg\",\"datePublished\":\"2024-03-18T15:00:42+00:00\",\"dateModified\":\"2024-03-18T15:00:53+00:00\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2024\\\/03\\\/18\\\/965\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/2024\\\/03\\\/18\\\/965\\\/#primaryimage\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/QUAL-SUA-SAUDADE.jpg\",\"contentUrl\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/QUAL-SUA-SAUDADE.jpg\",\"width\":588,\"height\":577},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#website\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/\",\"name\":\"R\u00e1dio Planeta Saudade\",\"description\":\"Relembrando grandes sucessos musicais e informando sobre os maiores artistas do mundo ou\u00e7a no seu celular.\",\"publisher\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#organization\",\"name\":\"R\u00e1dio Planeta Saudade\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/capture-20230607-202153.png\",\"contentUrl\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/capture-20230607-202153.png\",\"width\":1350,\"height\":358,\"caption\":\"R\u00e1dio Planeta Saudade\"},\"image\":{\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/#\\\/schema\\\/person\\\/1a6f6fc0d987819324e7ed417a1a6581\",\"name\":\"Planeta Saudade\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g\",\"caption\":\"Planeta Saudade\"},\"sameAs\":[\"https:\\\/\\\/radioplanetasaudade.com.br\"],\"url\":\"https:\\\/\\\/radioplanetasaudade.com.br\\\/index.php\\\/author\\\/wendelsantos4567\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"- R\u00c1DIO PLANETA SAUDADE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/03\/18\/965\/","og_locale":"pt_BR","og_type":"article","og_title":"- R\u00c1DIO PLANETA SAUDADE","og_url":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/03\/18\/965\/","og_site_name":"R\u00c1DIO PLANETA SAUDADE","article_published_time":"2024-03-18T15:00:42+00:00","article_modified_time":"2024-03-18T15:00:53+00:00","og_image":[{"url":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2024\/03\/QUAL-SUA-SAUDADE.jpg","type":"","width":"","height":""}],"author":"Planeta Saudade","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Planeta Saudade","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/03\/18\/965\/#article","isPartOf":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/03\/18\/965\/"},"author":{"name":"Planeta Saudade","@id":"https:\/\/radioplanetasaudade.com.br\/#\/schema\/person\/1a6f6fc0d987819324e7ed417a1a6581"},"headline":"Sem t\u00edtulo","datePublished":"2024-03-18T15:00:42+00:00","dateModified":"2024-03-18T15:00:53+00:00","mainEntityOfPage":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/03\/18\/965\/"},"wordCount":0,"commentCount":0,"publisher":{"@id":"https:\/\/radioplanetasaudade.com.br\/#organization"},"image":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/03\/18\/965\/#primaryimage"},"thumbnailUrl":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2024\/03\/QUAL-SUA-SAUDADE.jpg","keywords":["Anos 70","Anos 80","Anos 90","Baixe nosso App","Flashaback","R\u00e1dio","R\u00e1dio Planeta Saudade"],"articleSection":["QUAL \u00c9 A SUA SAUDADE?"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/03\/18\/965\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/03\/18\/965\/","url":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/03\/18\/965\/","name":"- R\u00c1DIO PLANETA SAUDADE","isPartOf":{"@id":"https:\/\/radioplanetasaudade.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/03\/18\/965\/#primaryimage"},"image":{"@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/03\/18\/965\/#primaryimage"},"thumbnailUrl":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2024\/03\/QUAL-SUA-SAUDADE.jpg","datePublished":"2024-03-18T15:00:42+00:00","dateModified":"2024-03-18T15:00:53+00:00","inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/03\/18\/965\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radioplanetasaudade.com.br\/index.php\/2024\/03\/18\/965\/#primaryimage","url":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2024\/03\/QUAL-SUA-SAUDADE.jpg","contentUrl":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2024\/03\/QUAL-SUA-SAUDADE.jpg","width":588,"height":577},{"@type":"WebSite","@id":"https:\/\/radioplanetasaudade.com.br\/#website","url":"https:\/\/radioplanetasaudade.com.br\/","name":"R\u00e1dio Planeta Saudade","description":"Relembrando grandes sucessos musicais e informando sobre os maiores artistas do mundo ou\u00e7a no seu celular.","publisher":{"@id":"https:\/\/radioplanetasaudade.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radioplanetasaudade.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/radioplanetasaudade.com.br\/#organization","name":"R\u00e1dio Planeta Saudade","url":"https:\/\/radioplanetasaudade.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radioplanetasaudade.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2023\/10\/capture-20230607-202153.png","contentUrl":"https:\/\/radioplanetasaudade.com.br\/wp-content\/uploads\/2023\/10\/capture-20230607-202153.png","width":1350,"height":358,"caption":"R\u00e1dio Planeta Saudade"},"image":{"@id":"https:\/\/radioplanetasaudade.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/radioplanetasaudade.com.br\/#\/schema\/person\/1a6f6fc0d987819324e7ed417a1a6581","name":"Planeta Saudade","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f81afe153fb6e9e1d38e83d127599e125ba7a0bd5cdb1f795af3d9b0af8ddeb0?s=96&d=mm&r=g","caption":"Planeta Saudade"},"sameAs":["https:\/\/radioplanetasaudade.com.br"],"url":"https:\/\/radioplanetasaudade.com.br\/index.php\/author\/wendelsantos4567\/"}]}},"_links":{"self":[{"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/posts\/965","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=965"}],"version-history":[{"count":1,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/posts\/965\/revisions"}],"predecessor-version":[{"id":967,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/posts\/965\/revisions\/967"}],"wp:attachment":[{"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=965"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=965"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radioplanetasaudade.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=965"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}